{"id":131127,"date":"2016-06-21T19:49:24","date_gmt":"2016-06-21T16:49:24","guid":{"rendered":"http:\/\/ets2.lt\/?p=131127"},"modified":"2016-06-21T19:49:24","modified_gmt":"2016-06-21T16:49:24","slug":"yellow-road-lines-2","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/","title":{"rendered":"Yellow Road Lines"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"http:\/\/ets2.lt\/wp-content\/uploads\/2016\/06\/Yellow-Road-Lines.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-131128\" src=\"http:\/\/ets2.lt\/wp-content\/uploads\/2016\/06\/Yellow-Road-Lines-470x490.jpg\" alt=\"Yellow-Road-Lines\" width=\"470\" height=\"490\"><\/a><\/p><p>This mod change original colour lines to yellow colour lines.<br>\n&ndash; Compatible with 1.24x Version Game<\/p><p>Tested: 1.24x, 1.23x<\/p><p>Author: Samo<\/p><p><strong><a href=\"http:\/\/sharemods.com\/gws9qr917fdz\/Yellow_Road_Lines.scs.html\" target=\"_blank\" rel=\"ugc nofollow noopener\">DOWNLOAD<\/a> 2 MB<\/strong><br>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>This mod change original colour lines to yellow colour lines. &ndash; Compatible with 1.24x Version GameTested: 1.24x, 1.23xAuthor: SamoDOWNLOAD 2 MB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-131127","post","type-post","status-publish","format-standard","hentry","category-other-mods"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"This mod change original colour lines to yellow colour lines. - Compatible with 1.24x Version Game Tested: 1.24x, 1.23x Author: Samo DOWNLOAD 2 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/yellow-road-lines-2\\\/#article\",\"name\":\"Yellow Road Lines | ETS 2 mods\",\"headline\":\"Yellow Road Lines\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/Yellow-Road-Lines-470x490.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/yellow-road-lines-2\\\/#articleImage\"},\"datePublished\":\"2016-06-21T19:49:24+02:00\",\"dateModified\":\"2016-06-21T19:49:24+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/yellow-road-lines-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/yellow-road-lines-2\\\/#webpage\"},\"articleSection\":\"Others\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/yellow-road-lines-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"position\":2,\"name\":\"Others\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/yellow-road-lines-2\\\/#listItem\",\"name\":\"Yellow Road Lines\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/yellow-road-lines-2\\\/#listItem\",\"position\":3,\"name\":\"Yellow Road Lines\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/yellow-road-lines-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/yellow-road-lines-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/yellow-road-lines-2\\\/\",\"name\":\"Yellow Road Lines | ETS 2 mods\",\"description\":\"This mod change original colour lines to yellow colour lines. - Compatible with 1.24x Version Game Tested: 1.24x, 1.23x Author: Samo DOWNLOAD 2 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/yellow-road-lines-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2016-06-21T19:49:24+02:00\",\"dateModified\":\"2016-06-21T19:49:24+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Yellow Road Lines | ETS 2 mods","description":"This mod change original colour lines to yellow colour lines. - Compatible with 1.24x Version Game Tested: 1.24x, 1.23x Author: Samo DOWNLOAD 2 MB","canonical_url":"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/#article","name":"Yellow Road Lines | ETS 2 mods","headline":"Yellow Road Lines","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/ets2.lt\/wp-content\/uploads\/2016\/06\/Yellow-Road-Lines-470x490.jpg","@id":"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/#articleImage"},"datePublished":"2016-06-21T19:49:24+02:00","dateModified":"2016-06-21T19:49:24+02:00","inLanguage":"en-US","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/#webpage"},"articleSection":"Others"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","position":2,"name":"Others","item":"https:\/\/ets2.lt\/en\/category\/other-mods\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/#listItem","name":"Yellow Road Lines"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/#listItem","position":3,"name":"Yellow Road Lines","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/#webpage","url":"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/","name":"Yellow Road Lines | ETS 2 mods","description":"This mod change original colour lines to yellow colour lines. - Compatible with 1.24x Version Game Tested: 1.24x, 1.23x Author: Samo DOWNLOAD 2 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2016-06-21T19:49:24+02:00","dateModified":"2016-06-21T19:49:24+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"131127","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-23 12:23:08","updated":"2022-09-24 05:25:33","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/other-mods\/\" title=\"Others\">Others<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tYellow Road Lines\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Others","link":"https:\/\/ets2.lt\/en\/category\/other-mods\/"},{"label":"Yellow Road Lines","link":"https:\/\/ets2.lt\/en\/yellow-road-lines-2\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/131127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=131127"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/131127\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=131127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=131127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=131127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}