{"id":141440,"date":"2016-10-02T09:44:48","date_gmt":"2016-10-02T06:44:48","guid":{"rendered":"http:\/\/ets2.lt\/?p=141440"},"modified":"2016-10-02T16:13:47","modified_gmt":"2016-10-02T13:13:47","slug":"volvo-fh13-v-2-0","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/","title":{"rendered":"Volvo FH13 v 2.0"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"http:\/\/ets2.lt\/wp-content\/uploads\/2016\/10\/Volvo-FH13-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-141443\" src=\"http:\/\/ets2.lt\/wp-content\/uploads\/2016\/10\/Volvo-FH13-1-470x294.jpg\" alt=\"volvo-fh13-1\" width=\"470\" height=\"294\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2016\/10\/Volvo-FH13-1-470x294.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2016\/10\/Volvo-FH13-1.jpg 1000w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\"><\/a> <a href=\"http:\/\/ets2.lt\/wp-content\/uploads\/2016\/10\/Volvo-FH13-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-141442\" src=\"http:\/\/ets2.lt\/wp-content\/uploads\/2016\/10\/Volvo-FH13-2-470x294.jpg\" alt=\"volvo-fh13-2\" width=\"470\" height=\"294\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2016\/10\/Volvo-FH13-2-470x294.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2016\/10\/Volvo-FH13-2.jpg 1000w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\"><\/a> <a href=\"http:\/\/ets2.lt\/wp-content\/uploads\/2016\/10\/Volvo-FH13-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-141441\" src=\"http:\/\/ets2.lt\/wp-content\/uploads\/2016\/10\/Volvo-FH13-3-470x294.jpg\" alt=\"volvo-fh13-3\" width=\"470\" height=\"294\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2016\/10\/Volvo-FH13-3-470x294.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2016\/10\/Volvo-FH13-3.jpg 1000w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\"><\/a><\/p><p><a href=\"http:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/#more-141440\"><img decoding=\"async\" src=\"http:\/\/ets2.lt\/youtube.jpg\" alt=\"YouTube preview\"><\/a><\/p><p>&ndash; Available in Volvo dealership<br>\n&ndash; 2 types of cabins<br>\n&ndash; 10 kinds of frame<br>\n&ndash; 12 types of engines<br>\n&ndash; 2 types of transmissions<br>\n&ndash; 2 types of inner<br>\n&ndash; Clock Functional analog<br>\n&ndash; 13 skins of Brazilian companies<br>\n&ndash; More than 50 accessories<\/p><p>Tested in version 1.24.x and 1.25.x<\/p><p>Author: Possato<\/p><p><strong><a href=\"http:\/\/sharemods.com\/ps4k2x5mg59k\/FH_top.rar.html\" target=\"_blank\" rel=\"ugc nofollow noopener\">DOWNLOAD<\/a> 36 MB [Sharemods]<\/strong><br>\n<strong><a href=\"http:\/\/uploadfiles.eu\/uunnqmdblcu6\/FH_top.rar.html\" target=\"_blank\" rel=\"ugc nofollow noopener\">DOWNLOAD<\/a> 36 MB [Uploadfiles]<\/strong> <\/p><p><!--more--><\/p><p>https:\/\/www.youtube.com\/watch?v=fqPY2J9NgSw&amp;feature=youtu.be<\/p>","protected":false},"excerpt":{"rendered":"<p>&ndash; Available in Volvo dealership &ndash; 2 types of cabins &ndash; 10 kinds of frame &ndash; 12 types of engines &ndash; 2 types of transmissions &ndash; 2 types of inner &ndash; Clock Functional analog &ndash; 13 skins of Brazilian companies &ndash; More than 50 accessoriesTested in version 1.24.x and 1.25.xAuthor: PossatoDOWNLOAD 36 MB [Sharemods] DOWNLOAD [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-141440","post","type-post","status-publish","format-standard","hentry","category-trucks"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u2013 Available in Volvo dealership \u2013 2 types of cabins \u2013 10 kinds of frame \u2013 12 types of engines \u2013 2 types of transmissions \u2013 2 types of inner - Clock Functional analog \u2013 13 skins of Brazilian companies \u2013 More than 50 accessories Tested in version 1.24.x and 1.25.x Author: Possato DOWNLOAD 36\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh13-v-2-0\\\/#article\",\"name\":\"Volvo FH13 v 2.0 | ETS 2 mods\",\"headline\":\"Volvo FH13 v 2.0\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/Volvo-FH13-1-470x294.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh13-v-2-0\\\/#articleImage\"},\"datePublished\":\"2016-10-02T09:44:48+02:00\",\"dateModified\":\"2016-10-02T16:13:47+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh13-v-2-0\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh13-v-2-0\\\/#webpage\"},\"articleSection\":\"Trucks\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh13-v-2-0\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"name\":\"Trucks\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"position\":2,\"name\":\"Trucks\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh13-v-2-0\\\/#listItem\",\"name\":\"Volvo FH13 v 2.0\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh13-v-2-0\\\/#listItem\",\"position\":3,\"name\":\"Volvo FH13 v 2.0\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"name\":\"Trucks\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh13-v-2-0\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh13-v-2-0\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh13-v-2-0\\\/\",\"name\":\"Volvo FH13 v 2.0 | ETS 2 mods\",\"description\":\"\\u2013 Available in Volvo dealership \\u2013 2 types of cabins \\u2013 10 kinds of frame \\u2013 12 types of engines \\u2013 2 types of transmissions \\u2013 2 types of inner - Clock Functional analog \\u2013 13 skins of Brazilian companies \\u2013 More than 50 accessories Tested in version 1.24.x and 1.25.x Author: Possato DOWNLOAD 36\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh13-v-2-0\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2016-10-02T09:44:48+02:00\",\"dateModified\":\"2016-10-02T16:13:47+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Volvo FH13 v 2.0 | ETS 2 mods","description":"\u2013 Available in Volvo dealership \u2013 2 types of cabins \u2013 10 kinds of frame \u2013 12 types of engines \u2013 2 types of transmissions \u2013 2 types of inner - Clock Functional analog \u2013 13 skins of Brazilian companies \u2013 More than 50 accessories Tested in version 1.24.x and 1.25.x Author: Possato DOWNLOAD 36","canonical_url":"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/#article","name":"Volvo FH13 v 2.0 | ETS 2 mods","headline":"Volvo FH13 v 2.0","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/ets2.lt\/wp-content\/uploads\/2016\/10\/Volvo-FH13-1-470x294.jpg","@id":"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/#articleImage"},"datePublished":"2016-10-02T09:44:48+02:00","dateModified":"2016-10-02T16:13:47+02:00","inLanguage":"en-US","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/#webpage"},"articleSection":"Trucks"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","name":"Trucks"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","position":2,"name":"Trucks","item":"https:\/\/ets2.lt\/en\/category\/trucks\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/#listItem","name":"Volvo FH13 v 2.0"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/#listItem","position":3,"name":"Volvo FH13 v 2.0","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","name":"Trucks"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/#webpage","url":"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/","name":"Volvo FH13 v 2.0 | ETS 2 mods","description":"\u2013 Available in Volvo dealership \u2013 2 types of cabins \u2013 10 kinds of frame \u2013 12 types of engines \u2013 2 types of transmissions \u2013 2 types of inner - Clock Functional analog \u2013 13 skins of Brazilian companies \u2013 More than 50 accessories Tested in version 1.24.x and 1.25.x Author: Possato DOWNLOAD 36","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2016-10-02T09:44:48+02:00","dateModified":"2016-10-02T16:13:47+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"141440","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-23 12:27:07","updated":"2022-09-15 07:29:42","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/trucks\/\" title=\"Trucks\">Trucks<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVolvo FH13 v 2.0\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Trucks","link":"https:\/\/ets2.lt\/en\/category\/trucks\/"},{"label":"Volvo FH13 v 2.0","link":"https:\/\/ets2.lt\/en\/volvo-fh13-v-2-0\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/141440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=141440"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/141440\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=141440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=141440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=141440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}