{"id":149095,"date":"2017-01-09T15:54:43","date_gmt":"2017-01-09T13:54:43","guid":{"rendered":"http:\/\/ets2.lt\/?p=149095"},"modified":"2017-01-10T10:04:02","modified_gmt":"2017-01-10T08:04:02","slug":"krone-mega-liner","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/krone-mega-liner\/","title":{"rendered":"Krone Mega Liner"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"http:\/\/ets2.lt\/wp-content\/uploads\/2017\/01\/Krone-Mega-Liner-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-149097\" src=\"http:\/\/ets2.lt\/wp-content\/uploads\/2017\/01\/Krone-Mega-Liner-1-470x265.jpg\" alt=\"krone-mega-liner-1\" width=\"470\" height=\"265\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2017\/01\/Krone-Mega-Liner-1-470x265.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2017\/01\/Krone-Mega-Liner-1.jpg 1000w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\"><\/a> <a href=\"http:\/\/ets2.lt\/wp-content\/uploads\/2017\/01\/Krone-Mega-Liner-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-149096\" src=\"http:\/\/ets2.lt\/wp-content\/uploads\/2017\/01\/Krone-Mega-Liner-2-470x265.jpg\" alt=\"krone-mega-liner-2\" width=\"470\" height=\"265\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2017\/01\/Krone-Mega-Liner-2-470x265.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2017\/01\/Krone-Mega-Liner-2.jpg 1000w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\"><\/a><\/p><p><a href=\"http:\/\/ets2.lt\/en\/krone-mega-liner\/#more-149095\"><img decoding=\"async\" src=\"http:\/\/ets2.lt\/youtube.jpg\" alt=\"YouTube preview\"><\/a><\/p><p>Krone Mega Liner Trailer.<br>\nMod tested on 1.26<\/p><p>Credits:<br>\nEdekLs, Borsuk<\/p><p><strong><a href=\"http:\/\/sharemods.com\/3kh7xqze2363\/Krone_firanka_mega.scs.html\" target=\"_blank\" rel=\"ugc nofollow noopener\">DOWNLOAD<\/a> 34 MB<\/strong><\/p><p><!--more--><\/p><p>https:\/\/www.youtube.com\/watch?v=_RHWX8e3EGU&amp;feature=youtu.be<br>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>Krone Mega Liner Trailer. Mod tested on 1.26Credits: EdekLs, BorsukDOWNLOAD 34 MB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-149095","post","type-post","status-publish","format-standard","hentry","category-trailers"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Krone Mega Liner Trailer. Mod tested on 1.26 Credits: EdekLs, Borsuk DOWNLOAD 34 MB https:\/\/www.youtube.com\/watch?v=_RHWX8e3EGU&amp;feature=youtu.be\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/krone-mega-liner\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/krone-mega-liner\\\/#article\",\"name\":\"Krone Mega Liner | ETS 2 mods\",\"headline\":\"Krone Mega Liner\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Krone-Mega-Liner-1-470x265.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/krone-mega-liner\\\/#articleImage\"},\"datePublished\":\"2017-01-09T15:54:43+02:00\",\"dateModified\":\"2017-01-10T10:04:02+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":19,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/krone-mega-liner\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/krone-mega-liner\\\/#webpage\"},\"articleSection\":\"Trailers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/krone-mega-liner\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trailers\\\/#listItem\",\"name\":\"Trailers\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trailers\\\/#listItem\",\"position\":2,\"name\":\"Trailers\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trailers\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/krone-mega-liner\\\/#listItem\",\"name\":\"Krone Mega Liner\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/krone-mega-liner\\\/#listItem\",\"position\":3,\"name\":\"Krone Mega Liner\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trailers\\\/#listItem\",\"name\":\"Trailers\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/krone-mega-liner\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/krone-mega-liner\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/krone-mega-liner\\\/\",\"name\":\"Krone Mega Liner | ETS 2 mods\",\"description\":\"Krone Mega Liner Trailer. Mod tested on 1.26 Credits: EdekLs, Borsuk DOWNLOAD 34 MB https:\\\/\\\/www.youtube.com\\\/watch?v=_RHWX8e3EGU&feature=youtu.be\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/krone-mega-liner\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2017-01-09T15:54:43+02:00\",\"dateModified\":\"2017-01-10T10:04:02+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Krone Mega Liner | ETS 2 mods","description":"Krone Mega Liner Trailer. Mod tested on 1.26 Credits: EdekLs, Borsuk DOWNLOAD 34 MB https:\/\/www.youtube.com\/watch?v=_RHWX8e3EGU&feature=youtu.be","canonical_url":"https:\/\/ets2.lt\/en\/krone-mega-liner\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/krone-mega-liner\/#article","name":"Krone Mega Liner | ETS 2 mods","headline":"Krone Mega Liner","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/ets2.lt\/wp-content\/uploads\/2017\/01\/Krone-Mega-Liner-1-470x265.jpg","@id":"https:\/\/ets2.lt\/en\/krone-mega-liner\/#articleImage"},"datePublished":"2017-01-09T15:54:43+02:00","dateModified":"2017-01-10T10:04:02+02:00","inLanguage":"en-US","commentCount":19,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/krone-mega-liner\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/krone-mega-liner\/#webpage"},"articleSection":"Trailers"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/krone-mega-liner\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trailers\/#listItem","name":"Trailers"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trailers\/#listItem","position":2,"name":"Trailers","item":"https:\/\/ets2.lt\/en\/category\/trailers\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/krone-mega-liner\/#listItem","name":"Krone Mega Liner"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/krone-mega-liner\/#listItem","position":3,"name":"Krone Mega Liner","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trailers\/#listItem","name":"Trailers"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/krone-mega-liner\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/krone-mega-liner\/#webpage","url":"https:\/\/ets2.lt\/en\/krone-mega-liner\/","name":"Krone Mega Liner | ETS 2 mods","description":"Krone Mega Liner Trailer. Mod tested on 1.26 Credits: EdekLs, Borsuk DOWNLOAD 34 MB https:\/\/www.youtube.com\/watch?v=_RHWX8e3EGU&feature=youtu.be","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/krone-mega-liner\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2017-01-09T15:54:43+02:00","dateModified":"2017-01-10T10:04:02+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"149095","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-23 11:36:45","updated":"2022-09-15 19:52:02","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/trailers\/\" title=\"Trailers\">Trailers<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tKrone Mega Liner\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Trailers","link":"https:\/\/ets2.lt\/en\/category\/trailers\/"},{"label":"Krone Mega Liner","link":"https:\/\/ets2.lt\/en\/krone-mega-liner\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/149095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=149095"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/149095\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=149095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=149095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=149095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}