{"id":178069,"date":"2017-12-18T15:49:36","date_gmt":"2017-12-18T13:49:36","guid":{"rendered":"https:\/\/ets2.lt\/?p=178069"},"modified":"2017-12-18T15:49:36","modified_gmt":"2017-12-18T13:49:36","slug":"new-beacons-v-1-0","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/","title":{"rendered":"New Beacons v 1.0"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2017\/12\/Beacons-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-178070\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2017\/12\/Beacons-3-470x401.jpg\" alt=\"\" width=\"470\" height=\"401\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2017\/12\/Beacons-3-470x401.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2017\/12\/Beacons-3.jpg 1000w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2017\/12\/Beacons-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-178071\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2017\/12\/Beacons-2-470x264.jpg\" alt=\"\" width=\"470\" height=\"264\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2017\/12\/Beacons-2-470x264.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2017\/12\/Beacons-2.jpg 1000w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2017\/12\/Beacons-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-178072\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2017\/12\/Beacons-1-470x264.jpg\" alt=\"\" width=\"470\" height=\"264\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2017\/12\/Beacons-1-470x264.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2017\/12\/Beacons-1.jpg 1000w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\"><\/a><\/p><p>New beacons<br>\nFor all Trucks from SCS + Scania rs from RJL<\/p><p>Credits:<br>\nHonza_CZ, SCS<\/p><p><strong><a href=\"http:\/\/sharemods.com\/1b282lyartgh\/beacon.scs.html\" target=\"_blank\" rel=\"ugc nofollow noopener\">DOWNLOAD<\/a> 366 KB<\/strong><br>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>New beacons For all Trucks from SCS + Scania rs from RJLCredits: Honza_CZ, SCSDOWNLOAD 366 KB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-178069","post","type-post","status-publish","format-standard","hentry","category-detalestiuningas"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"New beacons For all Trucks from SCS + Scania rs from RJL Credits: Honza_CZ, SCS DOWNLOAD 366 KB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/new-beacons-v-1-0\\\/#article\",\"name\":\"New Beacons v 1.0 | ETS 2 mods\",\"headline\":\"New Beacons v 1.0\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Beacons-3.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/new-beacons-v-1-0\\\/#articleImage\",\"width\":1000,\"height\":853},\"datePublished\":\"2017-12-18T15:49:36+02:00\",\"dateModified\":\"2017-12-18T15:49:36+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":7,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/new-beacons-v-1-0\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/new-beacons-v-1-0\\\/#webpage\"},\"articleSection\":\"Parts\\\/Tuning\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/new-beacons-v-1-0\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"name\":\"Parts\\\/Tuning\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"position\":2,\"name\":\"Parts\\\/Tuning\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/new-beacons-v-1-0\\\/#listItem\",\"name\":\"New Beacons v 1.0\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/new-beacons-v-1-0\\\/#listItem\",\"position\":3,\"name\":\"New Beacons v 1.0\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"name\":\"Parts\\\/Tuning\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/new-beacons-v-1-0\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/new-beacons-v-1-0\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/new-beacons-v-1-0\\\/\",\"name\":\"New Beacons v 1.0 | ETS 2 mods\",\"description\":\"New beacons For all Trucks from SCS + Scania rs from RJL Credits: Honza_CZ, SCS DOWNLOAD 366 KB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/new-beacons-v-1-0\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2017-12-18T15:49:36+02:00\",\"dateModified\":\"2017-12-18T15:49:36+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"New Beacons v 1.0 | ETS 2 mods","description":"New beacons For all Trucks from SCS + Scania rs from RJL Credits: Honza_CZ, SCS DOWNLOAD 366 KB","canonical_url":"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/#article","name":"New Beacons v 1.0 | ETS 2 mods","headline":"New Beacons v 1.0","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2017\/12\/Beacons-3.jpg","@id":"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/#articleImage","width":1000,"height":853},"datePublished":"2017-12-18T15:49:36+02:00","dateModified":"2017-12-18T15:49:36+02:00","inLanguage":"en-US","commentCount":7,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/#webpage"},"articleSection":"Parts\/Tuning"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","name":"Parts\/Tuning"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","position":2,"name":"Parts\/Tuning","item":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/#listItem","name":"New Beacons v 1.0"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/#listItem","position":3,"name":"New Beacons v 1.0","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","name":"Parts\/Tuning"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/#webpage","url":"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/","name":"New Beacons v 1.0 | ETS 2 mods","description":"New beacons For all Trucks from SCS + Scania rs from RJL Credits: Honza_CZ, SCS DOWNLOAD 366 KB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2017-12-18T15:49:36+02:00","dateModified":"2017-12-18T15:49:36+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"178069","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-23 12:40:13","updated":"2022-09-17 08:07:14","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/\" title=\"Parts\/Tuning\">Parts\/Tuning<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNew Beacons v 1.0\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Parts\/Tuning","link":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/"},{"label":"New Beacons v 1.0","link":"https:\/\/ets2.lt\/en\/new-beacons-v-1-0\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/178069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=178069"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/178069\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=178069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=178069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=178069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}