{"id":191476,"date":"2018-05-22T08:08:46","date_gmt":"2018-05-22T06:08:46","guid":{"rendered":"https:\/\/ets2.lt\/?p=191476"},"modified":"2018-05-22T08:08:46","modified_gmt":"2018-05-22T06:08:46","slug":"horn-blaster-for-p8-horn","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/","title":{"rendered":"Horn Blaster For P8 Horn"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2018\/05\/Horn-Blaster.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-191477\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2018\/05\/Horn-Blaster-470x264.jpg\" alt=\"\" width=\"470\" height=\"264\"><\/a><\/p><p>Horn Blaster For P8 Horn<br>\nThat&rsquo;s a mods By Mael , the mod add a new sound a the P8 Horn<\/p><p>Credits:<br>\nMael , Powerkasi<\/p><p><strong><a href=\"http:\/\/sharemods.com\/vxzovrogvq72\/HornBlasterFoRP8hornByMael.scs.html\" target=\"_blank\" rel=\"ugc nofollow noopener\">DOWNLOAD<\/a> 726 KB<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Horn Blaster For P8 Horn That&rsquo;s a mods By Mael , the mod add a new sound a the P8 HornCredits: Mael , PowerkasiDOWNLOAD 726 KB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-191476","post","type-post","status-publish","format-standard","hentry","category-detalestiuningas"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Horn Blaster For P8 Horn That&#039;s a mods By Mael , the mod add a new sound a the P8 Horn Credits: Mael , Powerkasi DOWNLOAD 726 KB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horn-blaster-for-p8-horn\\\/#article\",\"name\":\"Horn Blaster For P8 Horn | ETS 2 mods\",\"headline\":\"Horn Blaster For P8 Horn\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Horn-Blaster.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horn-blaster-for-p8-horn\\\/#articleImage\",\"width\":470,\"height\":264},\"datePublished\":\"2018-05-22T08:08:46+02:00\",\"dateModified\":\"2018-05-22T08:08:46+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horn-blaster-for-p8-horn\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horn-blaster-for-p8-horn\\\/#webpage\"},\"articleSection\":\"Parts\\\/Tuning\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horn-blaster-for-p8-horn\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"name\":\"Parts\\\/Tuning\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"position\":2,\"name\":\"Parts\\\/Tuning\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horn-blaster-for-p8-horn\\\/#listItem\",\"name\":\"Horn Blaster For P8 Horn\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horn-blaster-for-p8-horn\\\/#listItem\",\"position\":3,\"name\":\"Horn Blaster For P8 Horn\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"name\":\"Parts\\\/Tuning\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horn-blaster-for-p8-horn\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horn-blaster-for-p8-horn\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horn-blaster-for-p8-horn\\\/\",\"name\":\"Horn Blaster For P8 Horn | ETS 2 mods\",\"description\":\"Horn Blaster For P8 Horn That's a mods By Mael , the mod add a new sound a the P8 Horn Credits: Mael , Powerkasi DOWNLOAD 726 KB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horn-blaster-for-p8-horn\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2018-05-22T08:08:46+02:00\",\"dateModified\":\"2018-05-22T08:08:46+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Horn Blaster For P8 Horn | ETS 2 mods","description":"Horn Blaster For P8 Horn That's a mods By Mael , the mod add a new sound a the P8 Horn Credits: Mael , Powerkasi DOWNLOAD 726 KB","canonical_url":"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/#article","name":"Horn Blaster For P8 Horn | ETS 2 mods","headline":"Horn Blaster For P8 Horn","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2018\/05\/Horn-Blaster.jpg","@id":"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/#articleImage","width":470,"height":264},"datePublished":"2018-05-22T08:08:46+02:00","dateModified":"2018-05-22T08:08:46+02:00","inLanguage":"en-US","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/#webpage"},"articleSection":"Parts\/Tuning"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","name":"Parts\/Tuning"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","position":2,"name":"Parts\/Tuning","item":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/#listItem","name":"Horn Blaster For P8 Horn"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/#listItem","position":3,"name":"Horn Blaster For P8 Horn","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","name":"Parts\/Tuning"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/#webpage","url":"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/","name":"Horn Blaster For P8 Horn | ETS 2 mods","description":"Horn Blaster For P8 Horn That's a mods By Mael , the mod add a new sound a the P8 Horn Credits: Mael , Powerkasi DOWNLOAD 726 KB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2018-05-22T08:08:46+02:00","dateModified":"2018-05-22T08:08:46+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"191476","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-23 12:47:11","updated":"2022-09-20 14:01:54","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/\" title=\"Parts\/Tuning\">Parts\/Tuning<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHorn Blaster For P8 Horn\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Parts\/Tuning","link":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/"},{"label":"Horn Blaster For P8 Horn","link":"https:\/\/ets2.lt\/en\/horn-blaster-for-p8-horn\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/191476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=191476"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/191476\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=191476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=191476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=191476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}