{"id":245827,"date":"2019-04-28T14:41:18","date_gmt":"2019-04-28T12:41:18","guid":{"rendered":"https:\/\/ets2.lt\/?p=245827"},"modified":"2019-04-28T14:41:18","modified_gmt":"2019-04-28T12:41:18","slug":"intercooler-sunvisors","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/","title":{"rendered":"Intercooler Sunvisors"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2019\/04\/Intercooler-Sunvisors.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-245828\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2019\/04\/Intercooler-Sunvisors-470x257.jpg\" alt=\"\" width=\"470\" height=\"257\"><\/a><\/p><p>Tested: 1.30x-1.34x<br>\nIntercooler sun visors<br>\nPlease don&rsquo;t upload!<\/p><p>Credits:<br>\nBeni<\/p><p><strong><a href=\"https:\/\/sharemods.com\/1chzd0wr7mvz\/Intercooler.zip.html\" target=\"_blank\" rel=\"noopener noreferrer ugc nofollow\">DOWNLOAD<\/a> 731 KB<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Tested: 1.30x-1.34x Intercooler sun visors Please don&rsquo;t upload!Credits: BeniDOWNLOAD 731 KB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-245827","post","type-post","status-publish","format-standard","hentry","category-detalestiuningas"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Tested: 1.30x-1.34x Intercooler sun visors Please don\u2019t upload! Credits: Beni DOWNLOAD 731 KB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/intercooler-sunvisors\\\/#article\",\"name\":\"Intercooler Sunvisors | ETS 2 mods\",\"headline\":\"Intercooler Sunvisors\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Intercooler-Sunvisors.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/intercooler-sunvisors\\\/#articleImage\",\"width\":470,\"height\":257},\"datePublished\":\"2019-04-28T14:41:18+02:00\",\"dateModified\":\"2019-04-28T14:41:18+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/intercooler-sunvisors\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/intercooler-sunvisors\\\/#webpage\"},\"articleSection\":\"Parts\\\/Tuning\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/intercooler-sunvisors\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"name\":\"Parts\\\/Tuning\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"position\":2,\"name\":\"Parts\\\/Tuning\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/intercooler-sunvisors\\\/#listItem\",\"name\":\"Intercooler Sunvisors\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/intercooler-sunvisors\\\/#listItem\",\"position\":3,\"name\":\"Intercooler Sunvisors\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"name\":\"Parts\\\/Tuning\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/intercooler-sunvisors\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/intercooler-sunvisors\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/intercooler-sunvisors\\\/\",\"name\":\"Intercooler Sunvisors | ETS 2 mods\",\"description\":\"Tested: 1.30x-1.34x Intercooler sun visors Please don\\u2019t upload! Credits: Beni DOWNLOAD 731 KB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/intercooler-sunvisors\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2019-04-28T14:41:18+02:00\",\"dateModified\":\"2019-04-28T14:41:18+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Intercooler Sunvisors | ETS 2 mods","description":"Tested: 1.30x-1.34x Intercooler sun visors Please don\u2019t upload! Credits: Beni DOWNLOAD 731 KB","canonical_url":"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/#article","name":"Intercooler Sunvisors | ETS 2 mods","headline":"Intercooler Sunvisors","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2019\/04\/Intercooler-Sunvisors.jpg","@id":"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/#articleImage","width":470,"height":257},"datePublished":"2019-04-28T14:41:18+02:00","dateModified":"2019-04-28T14:41:18+02:00","inLanguage":"en-US","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/#webpage"},"articleSection":"Parts\/Tuning"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","name":"Parts\/Tuning"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","position":2,"name":"Parts\/Tuning","item":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/#listItem","name":"Intercooler Sunvisors"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/#listItem","position":3,"name":"Intercooler Sunvisors","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","name":"Parts\/Tuning"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/#webpage","url":"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/","name":"Intercooler Sunvisors | ETS 2 mods","description":"Tested: 1.30x-1.34x Intercooler sun visors Please don\u2019t upload! Credits: Beni DOWNLOAD 731 KB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2019-04-28T14:41:18+02:00","dateModified":"2019-04-28T14:41:18+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"245827","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-23 12:49:21","updated":"2022-09-16 17:47:56","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/\" title=\"Parts\/Tuning\">Parts\/Tuning<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tIntercooler Sunvisors\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Parts\/Tuning","link":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/"},{"label":"Intercooler Sunvisors","link":"https:\/\/ets2.lt\/en\/intercooler-sunvisors\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/245827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=245827"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/245827\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=245827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=245827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=245827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}