{"id":250799,"date":"2019-07-21T18:27:50","date_gmt":"2019-07-21T16:27:50","guid":{"rendered":"https:\/\/ets2.lt\/?p=250799"},"modified":"2019-07-22T07:52:39","modified_gmt":"2019-07-22T05:52:39","slug":"volvo-f-series-pack-of-stripes-paintjobs","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/","title":{"rendered":"Volvo F-Series Pack of Stripes Paintjobs"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2019\/07\/Stripes-Paintjobs.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-250800\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2019\/07\/Stripes-Paintjobs-470x338.jpg\" alt=\"\" width=\"470\" height=\"338\"><\/a><\/p><p><a href=\"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/#more-250799\"><img decoding=\"async\" src=\"http:\/\/ets2.lt\/youtube.png\" alt=\"YouTube preview\"><\/a><\/p><p>Four Paintjobs with Stripes for the Volvo F-Series.<br>\nAll colours are changeable.<\/p><p>Credits:<br>\nSCS Software, doexpectnothing<\/p><p><strong><a href=\"https:\/\/sharemods.com\/qthepd7raf3x\/Pack_of_Stripes.zip.html\" target=\"_blank\" rel=\"noopener noreferrer ugc nofollow\">DOWNLOAD<\/a>  278 KB<\/strong><\/p><p><!--more--><\/p><p>https:\/\/youtu.be\/kW6xKPGqzpI<br>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>Four Paintjobs with Stripes for the Volvo F-Series. All colours are changeable.Credits: SCS Software, doexpectnothingDOWNLOAD 278 KB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-250799","post","type-post","status-publish","format-standard","hentry","category-detalestiuningas"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Four Paintjobs with Stripes for the Volvo F-Series. All colours are changeable. Credits: SCS Software, doexpectnothing DOWNLOAD 278 KB https:\/\/youtu.be\/kW6xKPGqzpI\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-f-series-pack-of-stripes-paintjobs\\\/#article\",\"name\":\"Volvo F-Series Pack of Stripes Paintjobs | ETS 2 mods\",\"headline\":\"Volvo F-Series Pack of Stripes Paintjobs\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Stripes-Paintjobs.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-f-series-pack-of-stripes-paintjobs\\\/#articleImage\",\"width\":470,\"height\":338},\"datePublished\":\"2019-07-21T18:27:50+02:00\",\"dateModified\":\"2019-07-22T07:52:39+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-f-series-pack-of-stripes-paintjobs\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-f-series-pack-of-stripes-paintjobs\\\/#webpage\"},\"articleSection\":\"Parts\\\/Tuning\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-f-series-pack-of-stripes-paintjobs\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"name\":\"Parts\\\/Tuning\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"position\":2,\"name\":\"Parts\\\/Tuning\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-f-series-pack-of-stripes-paintjobs\\\/#listItem\",\"name\":\"Volvo F-Series Pack of Stripes Paintjobs\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-f-series-pack-of-stripes-paintjobs\\\/#listItem\",\"position\":3,\"name\":\"Volvo F-Series Pack of Stripes Paintjobs\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"name\":\"Parts\\\/Tuning\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-f-series-pack-of-stripes-paintjobs\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-f-series-pack-of-stripes-paintjobs\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-f-series-pack-of-stripes-paintjobs\\\/\",\"name\":\"Volvo F-Series Pack of Stripes Paintjobs | ETS 2 mods\",\"description\":\"Four Paintjobs with Stripes for the Volvo F-Series. All colours are changeable. Credits: SCS Software, doexpectnothing DOWNLOAD 278 KB https:\\\/\\\/youtu.be\\\/kW6xKPGqzpI\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-f-series-pack-of-stripes-paintjobs\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2019-07-21T18:27:50+02:00\",\"dateModified\":\"2019-07-22T07:52:39+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Volvo F-Series Pack of Stripes Paintjobs | ETS 2 mods","description":"Four Paintjobs with Stripes for the Volvo F-Series. All colours are changeable. Credits: SCS Software, doexpectnothing DOWNLOAD 278 KB https:\/\/youtu.be\/kW6xKPGqzpI","canonical_url":"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/#article","name":"Volvo F-Series Pack of Stripes Paintjobs | ETS 2 mods","headline":"Volvo F-Series Pack of Stripes Paintjobs","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2019\/07\/Stripes-Paintjobs.jpg","@id":"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/#articleImage","width":470,"height":338},"datePublished":"2019-07-21T18:27:50+02:00","dateModified":"2019-07-22T07:52:39+02:00","inLanguage":"en-US","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/#webpage"},"articleSection":"Parts\/Tuning"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","name":"Parts\/Tuning"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","position":2,"name":"Parts\/Tuning","item":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/#listItem","name":"Volvo F-Series Pack of Stripes Paintjobs"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/#listItem","position":3,"name":"Volvo F-Series Pack of Stripes Paintjobs","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","name":"Parts\/Tuning"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/#webpage","url":"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/","name":"Volvo F-Series Pack of Stripes Paintjobs | ETS 2 mods","description":"Four Paintjobs with Stripes for the Volvo F-Series. All colours are changeable. Credits: SCS Software, doexpectnothing DOWNLOAD 278 KB https:\/\/youtu.be\/kW6xKPGqzpI","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2019-07-21T18:27:50+02:00","dateModified":"2019-07-22T07:52:39+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"250799","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-23 12:49:31","updated":"2022-09-15 04:27:25","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/\" title=\"Parts\/Tuning\">Parts\/Tuning<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVolvo F-Series Pack of Stripes Paintjobs\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Parts\/Tuning","link":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/"},{"label":"Volvo F-Series Pack of Stripes Paintjobs","link":"https:\/\/ets2.lt\/en\/volvo-f-series-pack-of-stripes-paintjobs\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/250799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=250799"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/250799\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=250799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=250799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=250799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}