{"id":261680,"date":"2020-02-03T09:10:01","date_gmt":"2020-02-03T07:10:01","guid":{"rendered":"https:\/\/ets2.lt\/?p=261680"},"modified":"2020-02-03T09:10:01","modified_gmt":"2020-02-03T07:10:01","slug":"mercedes-actros-2014-blue-white-interior","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/","title":{"rendered":"Mercedes Actros 2014 Blue White Interior"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Blue-White-Interior-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-261683\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Blue-White-Interior-1-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Blue-White-Interior-1-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Blue-White-Interior-1.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Blue-White-Interior-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-261682\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Blue-White-Interior-2-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Blue-White-Interior-2-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Blue-White-Interior-2.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Blue-White-Interior-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-261681\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Blue-White-Interior-3-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Blue-White-Interior-3-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Blue-White-Interior-3.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><\/p><p>Mercedes Actros 2014 Blue White Interior<\/p><p>Tested on last version<br>\nWork super<\/p><p>ENJOY<\/p><p>Credits:<br>\nPile4<\/p><p><strong><a href=\"https:\/\/modsbase.com\/f0ykye9jgkov\/Mercedes_Actros_2014_Blue_White_Interior.scs.html\" target=\"_blank\" rel=\"noopener noreferrer ugc nofollow\">DOWNLOAD<\/a> 3 MB<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Mercedes Actros 2014 Blue White InteriorTested on last version Work superENJOYCredits: Pile4DOWNLOAD 3 MB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[13],"tags":[22],"class_list":["post-261680","post","type-post","status-publish","format-standard","hentry","category-interiors","tag-mercedes-benz"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Mercedes Actros 2014 Blue White Interior Tested on last version Work super ENJOY Credits: Pile4 DOWNLOAD 3 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-actros-2014-blue-white-interior\\\/#article\",\"name\":\"Mercedes Actros 2014 Blue White Interior | ETS 2 mods\",\"headline\":\"Mercedes Actros 2014 Blue White Interior\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Blue-White-Interior-1.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-actros-2014-blue-white-interior\\\/#articleImage\",\"width\":1000,\"height\":563},\"datePublished\":\"2020-02-03T09:10:01+02:00\",\"dateModified\":\"2020-02-03T09:10:01+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-actros-2014-blue-white-interior\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-actros-2014-blue-white-interior\\\/#webpage\"},\"articleSection\":\"Interiors, Mercedes-Benz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-actros-2014-blue-white-interior\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/interiors\\\/#listItem\",\"name\":\"Interiors\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/interiors\\\/#listItem\",\"position\":2,\"name\":\"Interiors\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/interiors\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-actros-2014-blue-white-interior\\\/#listItem\",\"name\":\"Mercedes Actros 2014 Blue White Interior\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-actros-2014-blue-white-interior\\\/#listItem\",\"position\":3,\"name\":\"Mercedes Actros 2014 Blue White Interior\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/interiors\\\/#listItem\",\"name\":\"Interiors\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-actros-2014-blue-white-interior\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-actros-2014-blue-white-interior\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-actros-2014-blue-white-interior\\\/\",\"name\":\"Mercedes Actros 2014 Blue White Interior | ETS 2 mods\",\"description\":\"Mercedes Actros 2014 Blue White Interior Tested on last version Work super ENJOY Credits: Pile4 DOWNLOAD 3 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-actros-2014-blue-white-interior\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2020-02-03T09:10:01+02:00\",\"dateModified\":\"2020-02-03T09:10:01+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mercedes Actros 2014 Blue White Interior | ETS 2 mods","description":"Mercedes Actros 2014 Blue White Interior Tested on last version Work super ENJOY Credits: Pile4 DOWNLOAD 3 MB","canonical_url":"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/#article","name":"Mercedes Actros 2014 Blue White Interior | ETS 2 mods","headline":"Mercedes Actros 2014 Blue White Interior","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Blue-White-Interior-1.jpg","@id":"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/#articleImage","width":1000,"height":563},"datePublished":"2020-02-03T09:10:01+02:00","dateModified":"2020-02-03T09:10:01+02:00","inLanguage":"en-US","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/#webpage"},"articleSection":"Interiors, Mercedes-Benz"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/interiors\/#listItem","name":"Interiors"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/interiors\/#listItem","position":2,"name":"Interiors","item":"https:\/\/ets2.lt\/en\/category\/interiors\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/#listItem","name":"Mercedes Actros 2014 Blue White Interior"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/#listItem","position":3,"name":"Mercedes Actros 2014 Blue White Interior","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/interiors\/#listItem","name":"Interiors"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/#webpage","url":"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/","name":"Mercedes Actros 2014 Blue White Interior | ETS 2 mods","description":"Mercedes Actros 2014 Blue White Interior Tested on last version Work super ENJOY Credits: Pile4 DOWNLOAD 3 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2020-02-03T09:10:01+02:00","dateModified":"2020-02-03T09:10:01+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"261680","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-23 12:51:17","updated":"2022-09-15 12:02:53","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/interiors\/\" title=\"Interiors\">Interiors<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMercedes Actros 2014 Blue White Interior\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Interiors","link":"https:\/\/ets2.lt\/en\/category\/interiors\/"},{"label":"Mercedes Actros 2014 Blue White Interior","link":"https:\/\/ets2.lt\/en\/mercedes-actros-2014-blue-white-interior\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/261680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=261680"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/261680\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=261680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=261680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=261680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}