{"id":263041,"date":"2020-02-26T16:02:47","date_gmt":"2020-02-26T14:02:47","guid":{"rendered":"https:\/\/ets2.lt\/?p=263041"},"modified":"2020-02-26T16:03:04","modified_gmt":"2020-02-26T14:03:04","slug":"horizon-map-save-game-profile","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/","title":{"rendered":"Horizon Map Save Game Profile"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Horizon-Map-Save-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-263044\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Horizon-Map-Save-1-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Horizon-Map-Save-1-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Horizon-Map-Save-1.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Horizon-Map-Save-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-263042\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Horizon-Map-Save-3-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Horizon-Map-Save-3-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Horizon-Map-Save-3.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Horizon-Map-Save-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-263043\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Horizon-Map-Save-2-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Horizon-Map-Save-2-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Horizon-Map-Save-2.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><\/p><p><a href=\"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/#more-263041\"><img decoding=\"async\" src=\"http:\/\/ets2.lt\/youtube.png\" alt=\"YouTube preview\"><\/a><\/p><p>Here you have a Save Profile for Horizon Map Mod ETS2 1.36<br>\n&ndash; Money<br>\n&ndash; skills<br>\n&ndash; Garages<br>\n&ndash; Truck dealers<br>\n&ndash; Level 44<br>\n&ndash; cities discovered<\/p><p>Credits:<br>\nPixell<\/p><p><strong><a href=\"https:\/\/sharemods.com\/jyhhautgnjn6\/Horizon_Map_Save_Game_Profile_1.36.zip.html\" target=\"_blank\" rel=\"noopener noreferrer ugc nofollow\">DOWNLOAD<\/a> 597 KB<\/strong><\/p><p><!--more--><\/p><p>https:\/\/youtu.be\/xWr4snMEhZ0<br>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>Here you have a Save Profile for Horizon Map Mod ETS2 1.36 &ndash; Money &ndash; skills &ndash; Garages &ndash; Truck dealers &ndash; Level 44 &ndash; cities discoveredCredits: PixellDOWNLOAD 597 KB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-263041","post","type-post","status-publish","format-standard","hentry","category-other-mods"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Here you have a Save Profile for Horizon Map Mod ETS2 1.36 \u2013 Money \u2013 skills \u2013 Garages \u2013 Truck dealers \u2013 Level 44 \u2013 cities discovered Credits: Pixell DOWNLOAD 597 KB https:\/\/youtu.be\/xWr4snMEhZ0\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horizon-map-save-game-profile\\\/#article\",\"name\":\"Horizon Map Save Game Profile | ETS 2 mods\",\"headline\":\"Horizon Map Save Game Profile\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Horizon-Map-Save-1.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horizon-map-save-game-profile\\\/#articleImage\",\"width\":1000,\"height\":563},\"datePublished\":\"2020-02-26T16:02:47+02:00\",\"dateModified\":\"2020-02-26T16:03:04+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horizon-map-save-game-profile\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horizon-map-save-game-profile\\\/#webpage\"},\"articleSection\":\"Others\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horizon-map-save-game-profile\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"position\":2,\"name\":\"Others\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horizon-map-save-game-profile\\\/#listItem\",\"name\":\"Horizon Map Save Game Profile\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horizon-map-save-game-profile\\\/#listItem\",\"position\":3,\"name\":\"Horizon Map Save Game Profile\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horizon-map-save-game-profile\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horizon-map-save-game-profile\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horizon-map-save-game-profile\\\/\",\"name\":\"Horizon Map Save Game Profile | ETS 2 mods\",\"description\":\"Here you have a Save Profile for Horizon Map Mod ETS2 1.36 \\u2013 Money \\u2013 skills \\u2013 Garages \\u2013 Truck dealers \\u2013 Level 44 \\u2013 cities discovered Credits: Pixell DOWNLOAD 597 KB https:\\\/\\\/youtu.be\\\/xWr4snMEhZ0\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/horizon-map-save-game-profile\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2020-02-26T16:02:47+02:00\",\"dateModified\":\"2020-02-26T16:03:04+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Horizon Map Save Game Profile | ETS 2 mods","description":"Here you have a Save Profile for Horizon Map Mod ETS2 1.36 \u2013 Money \u2013 skills \u2013 Garages \u2013 Truck dealers \u2013 Level 44 \u2013 cities discovered Credits: Pixell DOWNLOAD 597 KB https:\/\/youtu.be\/xWr4snMEhZ0","canonical_url":"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/#article","name":"Horizon Map Save Game Profile | ETS 2 mods","headline":"Horizon Map Save Game Profile","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/02\/Horizon-Map-Save-1.jpg","@id":"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/#articleImage","width":1000,"height":563},"datePublished":"2020-02-26T16:02:47+02:00","dateModified":"2020-02-26T16:03:04+02:00","inLanguage":"en-US","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/#webpage"},"articleSection":"Others"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","position":2,"name":"Others","item":"https:\/\/ets2.lt\/en\/category\/other-mods\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/#listItem","name":"Horizon Map Save Game Profile"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/#listItem","position":3,"name":"Horizon Map Save Game Profile","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/#webpage","url":"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/","name":"Horizon Map Save Game Profile | ETS 2 mods","description":"Here you have a Save Profile for Horizon Map Mod ETS2 1.36 \u2013 Money \u2013 skills \u2013 Garages \u2013 Truck dealers \u2013 Level 44 \u2013 cities discovered Credits: Pixell DOWNLOAD 597 KB https:\/\/youtu.be\/xWr4snMEhZ0","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2020-02-26T16:02:47+02:00","dateModified":"2020-02-26T16:03:04+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"263041","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-23 12:51:19","updated":"2022-09-15 02:55:32","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/other-mods\/\" title=\"Others\">Others<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHorizon Map Save Game Profile\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Others","link":"https:\/\/ets2.lt\/en\/category\/other-mods\/"},{"label":"Horizon Map Save Game Profile","link":"https:\/\/ets2.lt\/en\/horizon-map-save-game-profile\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/263041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=263041"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/263041\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=263041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=263041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=263041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}