{"id":267277,"date":"2020-05-07T07:45:08","date_gmt":"2020-05-07T05:45:08","guid":{"rendered":"https:\/\/ets2.lt\/?p=267277"},"modified":"2020-05-08T07:26:16","modified_gmt":"2020-05-08T05:26:16","slug":"renault-t-addons-v2-1-37","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/","title":{"rendered":"Renault T Addons v2 1.37"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/05\/Renault-T-Addons-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-267280\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/05\/Renault-T-Addons-1-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/05\/Renault-T-Addons-1-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2020\/05\/Renault-T-Addons-1.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/05\/Renault-T-Addons-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-267279\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/05\/Renault-T-Addons-2-555x739.jpg\" alt=\"\" width=\"555\" height=\"739\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/05\/Renault-T-Addons-2-555x739.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2020\/05\/Renault-T-Addons-2.jpg 877w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/05\/Renault-T-Addons-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-267278\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/05\/Renault-T-Addons-3-555x739.jpg\" alt=\"\" width=\"555\" height=\"739\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/05\/Renault-T-Addons-3-555x739.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2020\/05\/Renault-T-Addons-3.jpg 877w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><\/p><p><a href=\"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/#more-267277\"><img decoding=\"async\" src=\"http:\/\/ets2.lt\/youtube.png\" alt=\"YouTube preview\"><\/a><\/p><p>Changelog: v2<\/p><p>&#9745;Added Low Chasis 4&times;2<br>\n&#9745;Added Low Chasis 6&times;2<br>\n&#9745;Added New &#304;nterior Beige<br>\n&#9745;Added Front Glass sticker<br>\n&#9745;Added Front Logo 6 color option<br>\n&#9745;Added Front Botomgrill<br>\n&#9745;Added Front Bumper paint<br>\n&#9745;Added Front Mudflap<br>\n&#9745;Added Frontgrill lowcab<br>\n&#9745;Added Rear bumper 3 variant<br>\n&#9745;Added Rear Exhaust<br>\n&#9745;Added Rear Chs Cover<br>\n&#9745;Added Rear Mudflap<br>\n&#9745;Added R Deflector 3 variant+slot<br>\n&#9745;Added Rear Backlight<br>\n&#9745;Adapted 2 skin (thanks Kriistof General Lee)<br>\n&#9745;Adapted Route 66 skin Blade1974<br>\n&#9745;Added Front Bumper paint<br>\n&#9745;Added Front bumber light<br>\n&#9745;Added Front botomgrill<br>\n&#9745;Added Frontgrill<br>\n&#9745;Added Front fender paint<br>\n&#9745;Added Rear fender paint<br>\n&#9745;Added Miror paint<br>\n&#9745;Added Roofgrill<br>\n&#9745;Added New Rearmudflaps<br>\n&#9745;Added new Sunvisor<br>\n&#9745;Added new Stoneguard<br>\n&#9745;Added new Sunshield<br>\n&#9745;Added Windowtrim<br>\n&#9745;Added Doorstep light<br>\n&#9745;Added Stickers<br>\n&#9745;Added Rear bumper<br>\n&#9745;Added intbacklight<br>\n&#9745;Added Filter Paint<br>\n&#9745;Adapted Tuning pack 1.37<\/p><p>Tested 1.37x<\/p><p>Enjoy the mod!<br>\nPlease don&rsquo;t reupload, keep the original link. Thank you.<\/p><p>Credits:<br>\nScs,Blade1974<\/p><p><strong><a href=\"https:\/\/sharemods.com\/44a337r9g4eh\/Renault_T_Adons_v2.0.rar.html\" target=\"_blank\" rel=\"noopener noreferrer ugc nofollow\">DOWNLOAD<\/a> 66 MB<\/strong><\/p><p><!--more--><\/p><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"Renault T Addons v2.1   1.37\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/a2-UW4QpFzY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"Renault Range T Mega Tuning  Addons v2| Euro Truck Simulator 2 Mod [1.37]\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/XboNABZdQDM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><p>https:\/\/youtu.be\/vv8j9rTNR8Q<\/p><p>https:\/\/youtu.be\/Xt5y-kL8X0w<\/p>","protected":false},"excerpt":{"rendered":"<p>Changelog: v2&#9745;Added Low Chasis 4&times;2 &#9745;Added Low Chasis 6&times;2 &#9745;Added New &#304;nterior Beige &#9745;Added Front Glass sticker &#9745;Added Front Logo 6 color option &#9745;Added Front Botomgrill &#9745;Added Front Bumper paint &#9745;Added Front Mudflap &#9745;Added Frontgrill lowcab &#9745;Added Rear bumper 3 variant &#9745;Added Rear Exhaust &#9745;Added Rear Chs Cover &#9745;Added Rear Mudflap &#9745;Added R Deflector 3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-267277","post","type-post","status-publish","format-standard","hentry","category-detalestiuningas"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Changelog: v2 \u2611Added Low Chasis 4x2 \u2611Added Low Chasis 6x2 \u2611Added New \u0130nterior Beige \u2611Added Front Glass sticker \u2611Added Front Logo 6 color option \u2611Added Front Botomgrill \u2611Added Front Bumper paint \u2611Added Front Mudflap \u2611Added Frontgrill lowcab \u2611Added Rear bumper 3 variant \u2611Added Rear Exhaust \u2611Added Rear Chs Cover \u2611Added Rear Mudflap \u2611Added R Deflector\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-t-addons-v2-1-37\\\/#article\",\"name\":\"Renault T Addons v2 1.37 | ETS 2 mods\",\"headline\":\"Renault T Addons v2 1.37\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Renault-T-Addons-1.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-t-addons-v2-1-37\\\/#articleImage\",\"width\":1000,\"height\":563},\"datePublished\":\"2020-05-07T07:45:08+02:00\",\"dateModified\":\"2020-05-08T07:26:16+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":20,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-t-addons-v2-1-37\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-t-addons-v2-1-37\\\/#webpage\"},\"articleSection\":\"Parts\\\/Tuning\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-t-addons-v2-1-37\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"name\":\"Parts\\\/Tuning\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"position\":2,\"name\":\"Parts\\\/Tuning\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-t-addons-v2-1-37\\\/#listItem\",\"name\":\"Renault T Addons v2 1.37\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-t-addons-v2-1-37\\\/#listItem\",\"position\":3,\"name\":\"Renault T Addons v2 1.37\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"name\":\"Parts\\\/Tuning\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-t-addons-v2-1-37\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-t-addons-v2-1-37\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-t-addons-v2-1-37\\\/\",\"name\":\"Renault T Addons v2 1.37 | ETS 2 mods\",\"description\":\"Changelog: v2 \\u2611Added Low Chasis 4x2 \\u2611Added Low Chasis 6x2 \\u2611Added New \\u0130nterior Beige \\u2611Added Front Glass sticker \\u2611Added Front Logo 6 color option \\u2611Added Front Botomgrill \\u2611Added Front Bumper paint \\u2611Added Front Mudflap \\u2611Added Frontgrill lowcab \\u2611Added Rear bumper 3 variant \\u2611Added Rear Exhaust \\u2611Added Rear Chs Cover \\u2611Added Rear Mudflap \\u2611Added R Deflector\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-t-addons-v2-1-37\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2020-05-07T07:45:08+02:00\",\"dateModified\":\"2020-05-08T07:26:16+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Renault T Addons v2 1.37 | ETS 2 mods","description":"Changelog: v2 \u2611Added Low Chasis 4x2 \u2611Added Low Chasis 6x2 \u2611Added New \u0130nterior Beige \u2611Added Front Glass sticker \u2611Added Front Logo 6 color option \u2611Added Front Botomgrill \u2611Added Front Bumper paint \u2611Added Front Mudflap \u2611Added Frontgrill lowcab \u2611Added Rear bumper 3 variant \u2611Added Rear Exhaust \u2611Added Rear Chs Cover \u2611Added Rear Mudflap \u2611Added R Deflector","canonical_url":"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/#article","name":"Renault T Addons v2 1.37 | ETS 2 mods","headline":"Renault T Addons v2 1.37","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2020\/05\/Renault-T-Addons-1.jpg","@id":"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/#articleImage","width":1000,"height":563},"datePublished":"2020-05-07T07:45:08+02:00","dateModified":"2020-05-08T07:26:16+02:00","inLanguage":"en-US","commentCount":20,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/#webpage"},"articleSection":"Parts\/Tuning"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","name":"Parts\/Tuning"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","position":2,"name":"Parts\/Tuning","item":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/#listItem","name":"Renault T Addons v2 1.37"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/#listItem","position":3,"name":"Renault T Addons v2 1.37","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","name":"Parts\/Tuning"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/#webpage","url":"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/","name":"Renault T Addons v2 1.37 | ETS 2 mods","description":"Changelog: v2 \u2611Added Low Chasis 4x2 \u2611Added Low Chasis 6x2 \u2611Added New \u0130nterior Beige \u2611Added Front Glass sticker \u2611Added Front Logo 6 color option \u2611Added Front Botomgrill \u2611Added Front Bumper paint \u2611Added Front Mudflap \u2611Added Frontgrill lowcab \u2611Added Rear bumper 3 variant \u2611Added Rear Exhaust \u2611Added Rear Chs Cover \u2611Added Rear Mudflap \u2611Added R Deflector","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2020-05-07T07:45:08+02:00","dateModified":"2020-05-08T07:26:16+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"267277","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-23 12:53:13","updated":"2022-09-14 19:13:43","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/\" title=\"Parts\/Tuning\">Parts\/Tuning<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRenault T Addons v2 1.37\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Parts\/Tuning","link":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/"},{"label":"Renault T Addons v2 1.37","link":"https:\/\/ets2.lt\/en\/renault-t-addons-v2-1-37\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/267277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=267277"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/267277\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=267277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=267277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=267277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}