{"id":293865,"date":"2021-07-13T18:09:08","date_gmt":"2021-07-13T16:09:08","guid":{"rendered":"https:\/\/ets2.lt\/?p=293865"},"modified":"2021-07-16T08:51:18","modified_gmt":"2021-07-16T06:51:18","slug":"moffett-forklifts-for-scs-trailers","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/","title":{"rendered":"Moffett Forklifts for SCS-Trailers"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2021\/07\/Moffett-Forklifts-for-SCS-Trailers.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293866\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2021\/07\/Moffett-Forklifts-for-SCS-Trailers-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2021\/07\/Moffett-Forklifts-for-SCS-Trailers-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2021\/07\/Moffett-Forklifts-for-SCS-Trailers.jpg 800w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><\/p><p>Moffett Forklifts for SCS-Trailers<\/p><p>Available through the Mudflaps of the Trailers.<\/p><p>Tested on:<br>\nETS 2 Ver.: 1.41.x<br>\n&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;<br>\nSupported Trailers:<\/p><p>SCS;<br>\nCurtainsider, Dryvan, Dryvan S, Flatbed, Insulated, Reefer, Walkingfloor.<\/p><p>Krone;<br>\nProfiliner, Dryliner, Coolliner, Profiliner HD.<\/p><p>Schwarzm&uuml;ller;<br>\nCurtainsider, Reefer.<br>\n&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;<br>\nMod by Scotty68<\/p><p>Credits:<br>\nScotty68<\/p><p><strong><a href=\"https:\/\/sharemods.com\/22bkn8wn4kx9\/Moffett_Forklifts_for_SCS-Trailers.scs.html\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 16 MB<\/strong><\/p><p><!--more--><\/p><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"ETS2 1.41 Moffett Forklifts for SCS Trailers | Euro Truck Simulator 2 Mod\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/tS5sZTUjjJE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><p><\/p>","protected":false},"excerpt":{"rendered":"<p>Moffett Forklifts for SCS-TrailersAvailable through the Mudflaps of the Trailers.Tested on: ETS 2 Ver.: 1.41.x &mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash; Supported Trailers:SCS; Curtainsider, Dryvan, Dryvan S, Flatbed, Insulated, Reefer, Walkingfloor.Krone; Profiliner, Dryliner, Coolliner, Profiliner HD.Schwarzm&uuml;ller; Curtainsider, Reefer. &mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash;&mdash; Mod by Scotty68Credits: Scotty68DOWNLOAD 16 MB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[6],"tags":[8873],"class_list":["post-293865","post","type-post","status-publish","format-standard","hentry","category-other-mods","tag-1-41"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Moffett Forklifts for SCS-Trailers Available through the Mudflaps of the Trailers. Tested on: ETS 2 Ver.: 1.41.x ------------------------------ Supported Trailers: SCS; Curtainsider, Dryvan, Dryvan S, Flatbed, Insulated, Reefer, Walkingfloor. Krone; Profiliner, Dryliner, Coolliner, Profiliner HD. Schwarzm\u00fcller; Curtainsider, Reefer. ------------------------------ Mod by Scotty68 Credits: Scotty68 DOWNLOAD 16 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/moffett-forklifts-for-scs-trailers\\\/#article\",\"name\":\"Moffett Forklifts for SCS-Trailers | ETS 2 mods\",\"headline\":\"Moffett Forklifts for SCS-Trailers\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Moffett-Forklifts-for-SCS-Trailers.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/moffett-forklifts-for-scs-trailers\\\/#articleImage\",\"width\":800,\"height\":450},\"datePublished\":\"2021-07-13T18:09:08+02:00\",\"dateModified\":\"2021-07-16T08:51:18+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":9,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/moffett-forklifts-for-scs-trailers\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/moffett-forklifts-for-scs-trailers\\\/#webpage\"},\"articleSection\":\"Others, 1.41\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/moffett-forklifts-for-scs-trailers\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"position\":2,\"name\":\"Others\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/moffett-forklifts-for-scs-trailers\\\/#listItem\",\"name\":\"Moffett Forklifts for SCS-Trailers\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/moffett-forklifts-for-scs-trailers\\\/#listItem\",\"position\":3,\"name\":\"Moffett Forklifts for SCS-Trailers\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/moffett-forklifts-for-scs-trailers\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/moffett-forklifts-for-scs-trailers\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/moffett-forklifts-for-scs-trailers\\\/\",\"name\":\"Moffett Forklifts for SCS-Trailers | ETS 2 mods\",\"description\":\"Moffett Forklifts for SCS-Trailers Available through the Mudflaps of the Trailers. Tested on: ETS 2 Ver.: 1.41.x ------------------------------ Supported Trailers: SCS; Curtainsider, Dryvan, Dryvan S, Flatbed, Insulated, Reefer, Walkingfloor. Krone; Profiliner, Dryliner, Coolliner, Profiliner HD. Schwarzm\\u00fcller; Curtainsider, Reefer. ------------------------------ Mod by Scotty68 Credits: Scotty68 DOWNLOAD 16 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/moffett-forklifts-for-scs-trailers\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2021-07-13T18:09:08+02:00\",\"dateModified\":\"2021-07-16T08:51:18+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Moffett Forklifts for SCS-Trailers | ETS 2 mods","description":"Moffett Forklifts for SCS-Trailers Available through the Mudflaps of the Trailers. Tested on: ETS 2 Ver.: 1.41.x ------------------------------ Supported Trailers: SCS; Curtainsider, Dryvan, Dryvan S, Flatbed, Insulated, Reefer, Walkingfloor. Krone; Profiliner, Dryliner, Coolliner, Profiliner HD. Schwarzm\u00fcller; Curtainsider, Reefer. ------------------------------ Mod by Scotty68 Credits: Scotty68 DOWNLOAD 16 MB","canonical_url":"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/#article","name":"Moffett Forklifts for SCS-Trailers | ETS 2 mods","headline":"Moffett Forklifts for SCS-Trailers","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2021\/07\/Moffett-Forklifts-for-SCS-Trailers.jpg","@id":"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/#articleImage","width":800,"height":450},"datePublished":"2021-07-13T18:09:08+02:00","dateModified":"2021-07-16T08:51:18+02:00","inLanguage":"en-US","commentCount":9,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/#webpage"},"articleSection":"Others, 1.41"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","position":2,"name":"Others","item":"https:\/\/ets2.lt\/en\/category\/other-mods\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/#listItem","name":"Moffett Forklifts for SCS-Trailers"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/#listItem","position":3,"name":"Moffett Forklifts for SCS-Trailers","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/#webpage","url":"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/","name":"Moffett Forklifts for SCS-Trailers | ETS 2 mods","description":"Moffett Forklifts for SCS-Trailers Available through the Mudflaps of the Trailers. Tested on: ETS 2 Ver.: 1.41.x ------------------------------ Supported Trailers: SCS; Curtainsider, Dryvan, Dryvan S, Flatbed, Insulated, Reefer, Walkingfloor. Krone; Profiliner, Dryliner, Coolliner, Profiliner HD. Schwarzm\u00fcller; Curtainsider, Reefer. ------------------------------ Mod by Scotty68 Credits: Scotty68 DOWNLOAD 16 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2021-07-13T18:09:08+02:00","dateModified":"2021-07-16T08:51:18+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"293865","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-07-13 16:08:33","updated":"2022-09-14 17:24:35","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/other-mods\/\" title=\"Others\">Others<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMoffett Forklifts for SCS-Trailers\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Others","link":"https:\/\/ets2.lt\/en\/category\/other-mods\/"},{"label":"Moffett Forklifts for SCS-Trailers","link":"https:\/\/ets2.lt\/en\/moffett-forklifts-for-scs-trailers\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/293865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=293865"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/293865\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=293865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=293865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=293865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}