{"id":296168,"date":"2021-09-07T07:39:51","date_gmt":"2021-09-07T05:39:51","guid":{"rendered":"https:\/\/ets2.lt\/?p=296168"},"modified":"2021-09-08T18:06:35","modified_gmt":"2021-09-08T16:06:35","slug":"imperamods-todos-buses-v1-41","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/","title":{"rendered":"IMPERAMODS TODOS BUSES v1.41"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2021\/09\/IMPERAMODS-TODOS-BUSES-v1.41-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-296169\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2021\/09\/IMPERAMODS-TODOS-BUSES-v1.41-3-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2021\/09\/IMPERAMODS-TODOS-BUSES-v1.41-3-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2021\/09\/IMPERAMODS-TODOS-BUSES-v1.41-3.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2021\/09\/IMPERAMODS-TODOS-BUSES-v1.41-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-296170\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2021\/09\/IMPERAMODS-TODOS-BUSES-v1.41-2-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2021\/09\/IMPERAMODS-TODOS-BUSES-v1.41-2-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2021\/09\/IMPERAMODS-TODOS-BUSES-v1.41-2.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2021\/09\/IMPERAMODS-TODOS-BUSES-v1.41-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-296171\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2021\/09\/IMPERAMODS-TODOS-BUSES-v1.41-1-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2021\/09\/IMPERAMODS-TODOS-BUSES-v1.41-1-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2021\/09\/IMPERAMODS-TODOS-BUSES-v1.41-1.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><\/p><p>Busscar Vissta Buss &ndash; Mercedes Benz O400RSD<br>\nMarcopolo Paradiso GV 1150 &ndash; Volvo B10M<br>\nMarcopolo Viaggio GV 1150 &ndash; Mercedes-Benz O-371<\/p><p>Credits:<br>\nImperaMods<\/p><p><strong><a href=\"https:\/\/www.mediafire.com\/file\/47ykmlvcp5vwxbl\/IMPERAMODS_1.41_TODOS.rar\/file\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 204 MB<\/strong><\/p><p><!--more--><\/p><p><a href=\"https:\/\/youtu.be\/gpi7zakp9GI\" rel=\"ugc nofollow noopener\" target=\"_blank\">https:\/\/youtu.be\/gpi7zakp9GI<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Busscar Vissta Buss &ndash; Mercedes Benz O400RSD Marcopolo Paradiso GV 1150 &ndash; Volvo B10M Marcopolo Viaggio GV 1150 &ndash; Mercedes-Benz O-371Credits: ImperaModsDOWNLOAD 204 MB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1211],"tags":[],"class_list":["post-296168","post","type-post","status-publish","format-standard","hentry","category-bus-mods"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Busscar Vissta Buss - Mercedes Benz O400RSD Marcopolo Paradiso GV 1150 - Volvo B10M Marcopolo Viaggio GV 1150 - Mercedes-Benz O-371 Credits: ImperaMods DOWNLOAD 204 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/imperamods-todos-buses-v1-41\\\/#article\",\"name\":\"IMPERAMODS TODOS BUSES v1.41 | ETS 2 mods\",\"headline\":\"IMPERAMODS TODOS BUSES v1.41\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/IMPERAMODS-TODOS-BUSES-v1.41-3.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/imperamods-todos-buses-v1-41\\\/#articleImage\",\"width\":1000,\"height\":562},\"datePublished\":\"2021-09-07T07:39:51+02:00\",\"dateModified\":\"2021-09-08T18:06:35+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/imperamods-todos-buses-v1-41\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/imperamods-todos-buses-v1-41\\\/#webpage\"},\"articleSection\":\"Bus mods\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/imperamods-todos-buses-v1-41\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/bus-mods\\\/#listItem\",\"name\":\"Bus mods\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/bus-mods\\\/#listItem\",\"position\":2,\"name\":\"Bus mods\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/bus-mods\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/imperamods-todos-buses-v1-41\\\/#listItem\",\"name\":\"IMPERAMODS TODOS BUSES v1.41\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/imperamods-todos-buses-v1-41\\\/#listItem\",\"position\":3,\"name\":\"IMPERAMODS TODOS BUSES v1.41\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/bus-mods\\\/#listItem\",\"name\":\"Bus mods\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/imperamods-todos-buses-v1-41\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/imperamods-todos-buses-v1-41\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/imperamods-todos-buses-v1-41\\\/\",\"name\":\"IMPERAMODS TODOS BUSES v1.41 | ETS 2 mods\",\"description\":\"Busscar Vissta Buss - Mercedes Benz O400RSD Marcopolo Paradiso GV 1150 - Volvo B10M Marcopolo Viaggio GV 1150 - Mercedes-Benz O-371 Credits: ImperaMods DOWNLOAD 204 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/imperamods-todos-buses-v1-41\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2021-09-07T07:39:51+02:00\",\"dateModified\":\"2021-09-08T18:06:35+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"IMPERAMODS TODOS BUSES v1.41 | ETS 2 mods","description":"Busscar Vissta Buss - Mercedes Benz O400RSD Marcopolo Paradiso GV 1150 - Volvo B10M Marcopolo Viaggio GV 1150 - Mercedes-Benz O-371 Credits: ImperaMods DOWNLOAD 204 MB","canonical_url":"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/#article","name":"IMPERAMODS TODOS BUSES v1.41 | ETS 2 mods","headline":"IMPERAMODS TODOS BUSES v1.41","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2021\/09\/IMPERAMODS-TODOS-BUSES-v1.41-3.jpg","@id":"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/#articleImage","width":1000,"height":562},"datePublished":"2021-09-07T07:39:51+02:00","dateModified":"2021-09-08T18:06:35+02:00","inLanguage":"en-US","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/#webpage"},"articleSection":"Bus mods"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/bus-mods\/#listItem","name":"Bus mods"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/bus-mods\/#listItem","position":2,"name":"Bus mods","item":"https:\/\/ets2.lt\/en\/category\/bus-mods\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/#listItem","name":"IMPERAMODS TODOS BUSES v1.41"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/#listItem","position":3,"name":"IMPERAMODS TODOS BUSES v1.41","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/bus-mods\/#listItem","name":"Bus mods"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/#webpage","url":"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/","name":"IMPERAMODS TODOS BUSES v1.41 | ETS 2 mods","description":"Busscar Vissta Buss - Mercedes Benz O400RSD Marcopolo Paradiso GV 1150 - Volvo B10M Marcopolo Viaggio GV 1150 - Mercedes-Benz O-371 Credits: ImperaMods DOWNLOAD 204 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2021-09-07T07:39:51+02:00","dateModified":"2021-09-08T18:06:35+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"296168","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-09-07 05:38:49","updated":"2022-09-16 05:57:47","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/bus-mods\/\" title=\"Bus mods\">Bus mods<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tIMPERAMODS TODOS BUSES v1.41\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Bus mods","link":"https:\/\/ets2.lt\/en\/category\/bus-mods\/"},{"label":"IMPERAMODS TODOS BUSES v1.41","link":"https:\/\/ets2.lt\/en\/imperamods-todos-buses-v1-41\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/296168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=296168"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/296168\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=296168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=296168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=296168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}