{"id":305149,"date":"2022-03-06T19:03:03","date_gmt":"2022-03-06T17:03:03","guid":{"rendered":"https:\/\/ets2.lt\/?p=305149"},"modified":"2022-03-06T19:03:03","modified_gmt":"2022-03-06T17:03:03","slug":"jurassic-roads-map-save-game-profile-ets2-1-43","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/","title":{"rendered":"Jurassic Roads Map Save Game Profile ETS2 1.43"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/03\/Jurassic-Roads-Map-Save-Game-Profile-ETS2-1.43-1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/03\/Jurassic-Roads-Map-Save-Game-Profile-ETS2-1.43-1-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" class=\"alignnone size-medium wp-image-305152\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/03\/Jurassic-Roads-Map-Save-Game-Profile-ETS2-1.43-1-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/03\/Jurassic-Roads-Map-Save-Game-Profile-ETS2-1.43-1.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><br>\n<a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/03\/Jurassic-Roads-Map-Save-Game-Profile-ETS2-1.43-3.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/03\/Jurassic-Roads-Map-Save-Game-Profile-ETS2-1.43-3-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" class=\"alignnone size-medium wp-image-305150\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/03\/Jurassic-Roads-Map-Save-Game-Profile-ETS2-1.43-3-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/03\/Jurassic-Roads-Map-Save-Game-Profile-ETS2-1.43-3.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><br>\n<a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/03\/Jurassic-Roads-Map-Save-Game-Profile-ETS2-1.43-2.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/03\/Jurassic-Roads-Map-Save-Game-Profile-ETS2-1.43-2-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" class=\"alignnone size-medium wp-image-305151\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/03\/Jurassic-Roads-Map-Save-Game-Profile-ETS2-1.43-2-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/03\/Jurassic-Roads-Map-Save-Game-Profile-ETS2-1.43-2.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><\/p><p>Here you have a Save Profile for Jurassic Roads Map for ets2 1.43<\/p><p>&ndash; Money<br>\n&ndash; All skills<br>\n&ndash; Garages<br>\n&ndash; All Truck dealers<br>\n&ndash; Level 75<br>\n&ndash; All cities discovered<\/p><p>Credits:<br>\npixell<\/p><p><strong><a href=\"https:\/\/sharemods.com\/ebn1yz8qrpa3\/Jurassic_Roads_Map_Save_Profile_Download_ETS2_1.43.rar.html\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 2 MB<\/strong><\/p><p><!--more--><\/p><p>https:\/\/youtu.be\/8e2PrxVKpAI<\/p>","protected":false},"excerpt":{"rendered":"<p>Here you have a Save Profile for Jurassic Roads Map for ets2 1.43&ndash; Money &ndash; All skills &ndash; Garages &ndash; All Truck dealers &ndash; Level 75 &ndash; All cities discoveredCredits: pixellDOWNLOAD 2 MB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[6],"tags":[8868],"class_list":["post-305149","post","type-post","status-publish","format-standard","hentry","category-other-mods","tag-1-43"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Here you have a Save Profile for Jurassic Roads Map for ets2 1.43 \u2013 Money \u2013 All skills \u2013 Garages \u2013 All Truck dealers \u2013 Level 75 \u2013 All cities discovered Credits: pixell DOWNLOAD 2 MB https:\/\/youtu.be\/8e2PrxVKpAI\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jurassic-roads-map-save-game-profile-ets2-1-43\\\/#article\",\"name\":\"Jurassic Roads Map Save Game Profile ETS2 1.43 | ETS 2 mods\",\"headline\":\"Jurassic Roads Map Save Game Profile ETS2 1.43\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Jurassic-Roads-Map-Save-Game-Profile-ETS2-1.43-1.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jurassic-roads-map-save-game-profile-ets2-1-43\\\/#articleImage\",\"width\":1000,\"height\":563},\"datePublished\":\"2022-03-06T19:03:03+02:00\",\"dateModified\":\"2022-03-06T19:03:03+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":9,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jurassic-roads-map-save-game-profile-ets2-1-43\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jurassic-roads-map-save-game-profile-ets2-1-43\\\/#webpage\"},\"articleSection\":\"Others, 1.43\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jurassic-roads-map-save-game-profile-ets2-1-43\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"position\":2,\"name\":\"Others\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jurassic-roads-map-save-game-profile-ets2-1-43\\\/#listItem\",\"name\":\"Jurassic Roads Map Save Game Profile ETS2 1.43\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jurassic-roads-map-save-game-profile-ets2-1-43\\\/#listItem\",\"position\":3,\"name\":\"Jurassic Roads Map Save Game Profile ETS2 1.43\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jurassic-roads-map-save-game-profile-ets2-1-43\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jurassic-roads-map-save-game-profile-ets2-1-43\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jurassic-roads-map-save-game-profile-ets2-1-43\\\/\",\"name\":\"Jurassic Roads Map Save Game Profile ETS2 1.43 | ETS 2 mods\",\"description\":\"Here you have a Save Profile for Jurassic Roads Map for ets2 1.43 \\u2013 Money \\u2013 All skills \\u2013 Garages \\u2013 All Truck dealers \\u2013 Level 75 \\u2013 All cities discovered Credits: pixell DOWNLOAD 2 MB https:\\\/\\\/youtu.be\\\/8e2PrxVKpAI\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jurassic-roads-map-save-game-profile-ets2-1-43\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2022-03-06T19:03:03+02:00\",\"dateModified\":\"2022-03-06T19:03:03+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Jurassic Roads Map Save Game Profile ETS2 1.43 | ETS 2 mods","description":"Here you have a Save Profile for Jurassic Roads Map for ets2 1.43 \u2013 Money \u2013 All skills \u2013 Garages \u2013 All Truck dealers \u2013 Level 75 \u2013 All cities discovered Credits: pixell DOWNLOAD 2 MB https:\/\/youtu.be\/8e2PrxVKpAI","canonical_url":"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/#article","name":"Jurassic Roads Map Save Game Profile ETS2 1.43 | ETS 2 mods","headline":"Jurassic Roads Map Save Game Profile ETS2 1.43","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/03\/Jurassic-Roads-Map-Save-Game-Profile-ETS2-1.43-1.jpg","@id":"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/#articleImage","width":1000,"height":563},"datePublished":"2022-03-06T19:03:03+02:00","dateModified":"2022-03-06T19:03:03+02:00","inLanguage":"en-US","commentCount":9,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/#webpage"},"articleSection":"Others, 1.43"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","position":2,"name":"Others","item":"https:\/\/ets2.lt\/en\/category\/other-mods\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/#listItem","name":"Jurassic Roads Map Save Game Profile ETS2 1.43"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/#listItem","position":3,"name":"Jurassic Roads Map Save Game Profile ETS2 1.43","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/#webpage","url":"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/","name":"Jurassic Roads Map Save Game Profile ETS2 1.43 | ETS 2 mods","description":"Here you have a Save Profile for Jurassic Roads Map for ets2 1.43 \u2013 Money \u2013 All skills \u2013 Garages \u2013 All Truck dealers \u2013 Level 75 \u2013 All cities discovered Credits: pixell DOWNLOAD 2 MB https:\/\/youtu.be\/8e2PrxVKpAI","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2022-03-06T19:03:03+02:00","dateModified":"2022-03-06T19:03:03+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"305149","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-03-06 17:02:09","updated":"2022-09-18 11:49:08","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/other-mods\/\" title=\"Others\">Others<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tJurassic Roads Map Save Game Profile ETS2 1.43\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Others","link":"https:\/\/ets2.lt\/en\/category\/other-mods\/"},{"label":"Jurassic Roads Map Save Game Profile ETS2 1.43","link":"https:\/\/ets2.lt\/en\/jurassic-roads-map-save-game-profile-ets2-1-43\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/305149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=305149"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/305149\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=305149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=305149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=305149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}