{"id":306486,"date":"2022-04-09T08:40:35","date_gmt":"2022-04-09T06:40:35","guid":{"rendered":"https:\/\/ets2.lt\/?p=306486"},"modified":"2022-04-09T08:40:35","modified_gmt":"2022-04-09T06:40:35","slug":"ts-saveeditor-tool-v0-3-2-0","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/","title":{"rendered":"TS SaveEditor Tool v0.3.2.0"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/04\/TS-SaveEditor-Tool-v0.3.2.0.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-306487\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/04\/TS-SaveEditor-Tool-v0.3.2.0-555x400.jpg\" alt=\"\" width=\"555\" height=\"400\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/04\/TS-SaveEditor-Tool-v0.3.2.0-555x400.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/04\/TS-SaveEditor-Tool-v0.3.2.0.jpg 800w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><\/p><p>Update | 0.3.2.0<br>\nAdded Restore save from backup button<br>\nAdded Unload save button<br>\nUpdated Switch Trucks function<br>\nUpdated DDS Image loader<br>\nUpdated Save file write procedure<br>\nFixed Save items Data format errors<\/p><p>This program created for editing game save files.<\/p><p>You can:<br>\nedit Local and Steam save files.<br>\nadd Custom paths for save files.<br>\nmanage profiles (Rename and Clone).<br>\nedit Player Level and Skill.<br>\nedit and share saved User colors for truck and trailer paint.<br>\nedit amount of Money on company account.<br>\nedit visited cities (to be able to grab cargo from discovered cities).<br>\nbuy and\\or upgrade Garages.<br>\nmanage trucks + repair and\\or refuel.<br>\nshare truck Paint job.<br>\nmanage trailers +repair.<br>\ncreate custom Jobs for Freight market.<br>\ngenerate new seeds for Cargo market.<br>\nshare Truck position.<br>\nshare GPS paths.<br>\nshare Multiple Truck positions as one Convoy &#1089;ontrol pack.<br>\nShort term goals:<br>\nfinish sharing functions for truck parts.<br>\nadd share functions for trailers.-Long term goals:<\/p><p>Long term goals:<br>\nadd the ability to creat jobs for Cargo market.<br>\nget map data from game\\game generated files.<br>\nscan mods for data (trucks, cargo&hellip;)<\/p><p>Credits:<br>\nLIPtoH<\/p><p><strong><a href=\"https:\/\/rebrand.ly\/TS-SET-Download\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 7 MB<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Update | 0.3.2.0 Added Restore save from backup button Added Unload save button Updated Switch Trucks function Updated DDS Image loader Updated Save file write procedure Fixed Save items Data format errorsThis program created for editing game save files.You can: edit Local and Steam save files. add Custom paths for save files. manage profiles (Rename [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-306486","post","type-post","status-publish","format-standard","hentry","category-other-mods"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Update | 0.3.2.0 Added Restore save from backup button Added Unload save button Updated Switch Trucks function Updated DDS Image loader Updated Save file write procedure Fixed Save items Data format errors This program created for editing game save files. You can: edit Local and Steam save files. add Custom paths for save files. manage\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/ts-saveeditor-tool-v0-3-2-0\\\/#article\",\"name\":\"TS SaveEditor Tool v0.3.2.0 | ETS 2 mods\",\"headline\":\"TS SaveEditor Tool v0.3.2.0\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/TS-SaveEditor-Tool-v0.3.2.0.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/ts-saveeditor-tool-v0-3-2-0\\\/#articleImage\",\"width\":800,\"height\":576},\"datePublished\":\"2022-04-09T08:40:35+02:00\",\"dateModified\":\"2022-04-09T08:40:35+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/ts-saveeditor-tool-v0-3-2-0\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/ts-saveeditor-tool-v0-3-2-0\\\/#webpage\"},\"articleSection\":\"Others\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/ts-saveeditor-tool-v0-3-2-0\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"position\":2,\"name\":\"Others\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/ts-saveeditor-tool-v0-3-2-0\\\/#listItem\",\"name\":\"TS SaveEditor Tool v0.3.2.0\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/ts-saveeditor-tool-v0-3-2-0\\\/#listItem\",\"position\":3,\"name\":\"TS SaveEditor Tool v0.3.2.0\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/ts-saveeditor-tool-v0-3-2-0\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/ts-saveeditor-tool-v0-3-2-0\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/ts-saveeditor-tool-v0-3-2-0\\\/\",\"name\":\"TS SaveEditor Tool v0.3.2.0 | ETS 2 mods\",\"description\":\"Update | 0.3.2.0 Added Restore save from backup button Added Unload save button Updated Switch Trucks function Updated DDS Image loader Updated Save file write procedure Fixed Save items Data format errors This program created for editing game save files. You can: edit Local and Steam save files. add Custom paths for save files. manage\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/ts-saveeditor-tool-v0-3-2-0\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2022-04-09T08:40:35+02:00\",\"dateModified\":\"2022-04-09T08:40:35+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"TS SaveEditor Tool v0.3.2.0 | ETS 2 mods","description":"Update | 0.3.2.0 Added Restore save from backup button Added Unload save button Updated Switch Trucks function Updated DDS Image loader Updated Save file write procedure Fixed Save items Data format errors This program created for editing game save files. You can: edit Local and Steam save files. add Custom paths for save files. manage","canonical_url":"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/#article","name":"TS SaveEditor Tool v0.3.2.0 | ETS 2 mods","headline":"TS SaveEditor Tool v0.3.2.0","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/04\/TS-SaveEditor-Tool-v0.3.2.0.jpg","@id":"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/#articleImage","width":800,"height":576},"datePublished":"2022-04-09T08:40:35+02:00","dateModified":"2022-04-09T08:40:35+02:00","inLanguage":"en-US","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/#webpage"},"articleSection":"Others"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","position":2,"name":"Others","item":"https:\/\/ets2.lt\/en\/category\/other-mods\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/#listItem","name":"TS SaveEditor Tool v0.3.2.0"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/#listItem","position":3,"name":"TS SaveEditor Tool v0.3.2.0","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/#webpage","url":"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/","name":"TS SaveEditor Tool v0.3.2.0 | ETS 2 mods","description":"Update | 0.3.2.0 Added Restore save from backup button Added Unload save button Updated Switch Trucks function Updated DDS Image loader Updated Save file write procedure Fixed Save items Data format errors This program created for editing game save files. You can: edit Local and Steam save files. add Custom paths for save files. manage","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2022-04-09T08:40:35+02:00","dateModified":"2022-04-09T08:40:35+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"306486","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-04-09 06:39:31","updated":"2022-09-14 15:55:45","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/other-mods\/\" title=\"Others\">Others<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTS SaveEditor Tool v0.3.2.0\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Others","link":"https:\/\/ets2.lt\/en\/category\/other-mods\/"},{"label":"TS SaveEditor Tool v0.3.2.0","link":"https:\/\/ets2.lt\/en\/ts-saveeditor-tool-v0-3-2-0\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/306486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=306486"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/306486\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=306486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=306486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=306486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}