{"id":308133,"date":"2022-05-15T17:53:24","date_gmt":"2022-05-15T15:53:24","guid":{"rendered":"https:\/\/ets2.lt\/?p=308133"},"modified":"2022-05-15T18:55:45","modified_gmt":"2022-05-15T16:55:45","slug":"real-graphic-texture-1-44","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/","title":{"rendered":"Real Graphic Texture 1.44"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Real-Graphic-Texture-1.44-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-308134\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Real-Graphic-Texture-1.44-3-555x286.jpg\" alt=\"\" width=\"555\" height=\"286\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Real-Graphic-Texture-1.44-3-555x286.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Real-Graphic-Texture-1.44-3.jpg 1024w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Real-Graphic-Texture-1.44-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-308135\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Real-Graphic-Texture-1.44-2-555x309.jpg\" alt=\"\" width=\"555\" height=\"309\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Real-Graphic-Texture-1.44-2-555x309.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Real-Graphic-Texture-1.44-2.jpg 1024w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Real-Graphic-Texture-1.44-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-308136\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Real-Graphic-Texture-1.44-1-555x264.jpg\" alt=\"\" width=\"555\" height=\"264\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Real-Graphic-Texture-1.44-1-555x264.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Real-Graphic-Texture-1.44-1.jpg 1024w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><\/p><p>Real texture of asphalt vegetation and more realistic weather.<\/p><p>Credits:<br>\nAdr mods<\/p><p><strong><a href=\"https:\/\/modsfire.com\/g3A1a1CqYaF7VJA\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 2.2 GB<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Real texture of asphalt vegetation and more realistic weather.Credits: Adr modsDOWNLOAD 2.2 GB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[6],"tags":[8875],"class_list":["post-308133","post","type-post","status-publish","format-standard","hentry","category-other-mods","tag-1-44"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Real texture of asphalt vegetation and more realistic weather. Credits: Adr mods DOWNLOAD 2.2 GB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-graphic-texture-1-44\\\/#article\",\"name\":\"Real Graphic Texture 1.44 | ETS 2 mods\",\"headline\":\"Real Graphic Texture 1.44\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Real-Graphic-Texture-1.44-3.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-graphic-texture-1-44\\\/#articleImage\",\"width\":1024,\"height\":527},\"datePublished\":\"2022-05-15T17:53:24+02:00\",\"dateModified\":\"2022-05-15T18:55:45+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-graphic-texture-1-44\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-graphic-texture-1-44\\\/#webpage\"},\"articleSection\":\"Others, 1.44\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-graphic-texture-1-44\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"position\":2,\"name\":\"Others\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-graphic-texture-1-44\\\/#listItem\",\"name\":\"Real Graphic Texture 1.44\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-graphic-texture-1-44\\\/#listItem\",\"position\":3,\"name\":\"Real Graphic Texture 1.44\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-graphic-texture-1-44\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-graphic-texture-1-44\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-graphic-texture-1-44\\\/\",\"name\":\"Real Graphic Texture 1.44 | ETS 2 mods\",\"description\":\"Real texture of asphalt vegetation and more realistic weather. Credits: Adr mods DOWNLOAD 2.2 GB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-graphic-texture-1-44\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2022-05-15T17:53:24+02:00\",\"dateModified\":\"2022-05-15T18:55:45+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Real Graphic Texture 1.44 | ETS 2 mods","description":"Real texture of asphalt vegetation and more realistic weather. Credits: Adr mods DOWNLOAD 2.2 GB","canonical_url":"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/#article","name":"Real Graphic Texture 1.44 | ETS 2 mods","headline":"Real Graphic Texture 1.44","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Real-Graphic-Texture-1.44-3.jpg","@id":"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/#articleImage","width":1024,"height":527},"datePublished":"2022-05-15T17:53:24+02:00","dateModified":"2022-05-15T18:55:45+02:00","inLanguage":"en-US","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/#webpage"},"articleSection":"Others, 1.44"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","position":2,"name":"Others","item":"https:\/\/ets2.lt\/en\/category\/other-mods\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/#listItem","name":"Real Graphic Texture 1.44"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/#listItem","position":3,"name":"Real Graphic Texture 1.44","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/#webpage","url":"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/","name":"Real Graphic Texture 1.44 | ETS 2 mods","description":"Real texture of asphalt vegetation and more realistic weather. Credits: Adr mods DOWNLOAD 2.2 GB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2022-05-15T17:53:24+02:00","dateModified":"2022-05-15T18:55:45+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"308133","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-05-15 16:53:25","updated":"2022-09-14 12:40:31","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/other-mods\/\" title=\"Others\">Others<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tReal Graphic Texture 1.44\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Others","link":"https:\/\/ets2.lt\/en\/category\/other-mods\/"},{"label":"Real Graphic Texture 1.44","link":"https:\/\/ets2.lt\/en\/real-graphic-texture-1-44\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/308133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=308133"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/308133\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=308133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=308133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=308133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}