{"id":308440,"date":"2022-05-21T18:31:37","date_gmt":"2022-05-21T16:31:37","guid":{"rendered":"https:\/\/ets2.lt\/?p=308440"},"modified":"2022-05-21T18:31:37","modified_gmt":"2022-05-21T16:31:37","slug":"bmw-m3-e30-2","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/","title":{"rendered":"Bmw M3 E30"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Bmw-M3-E30-2.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Bmw-M3-E30-2-555x624.jpg\" alt=\"\" width=\"555\" height=\"624\" class=\"alignnone size-medium wp-image-308442\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Bmw-M3-E30-2-555x624.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Bmw-M3-E30-2.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><br>\n<a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Bmw-M3-E30-1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Bmw-M3-E30-1-555x937.jpg\" alt=\"\" width=\"555\" height=\"937\" class=\"alignnone size-medium wp-image-308443\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Bmw-M3-E30-1-555x937.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Bmw-M3-E30-1-910x1536.jpg 910w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Bmw-M3-E30-1.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><br>\n<a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Bmw-M3-E30-3.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Bmw-M3-E30-3.jpg\" alt=\"\" width=\"555\" height=\"624\" class=\"alignnone size-full wp-image-308441\"><\/a><\/p><p>Changelog;<br>\n-Fixed the glass rain issue<br>\n-Fixed the glass reflection issue<br>\n-Fixed the mirror glare issue<br>\n-Fixes Wheel<br>\n-Fixed bugs<\/p><p>***********************************<br>\n&ndash;HQ Model<br>\n&ndash;Ao(Ambiyans Coating)<br>\n-Sound<br>\n-2 Different Wheel<\/p><p>Credits:<br>\nMert &#304;r&#351;i<br>\nSound:Nimit-Slav Jerry<\/p><p><strong><a href=\"https:\/\/modsfire.com\/qu66mTZJLnfxgzv\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 79 MB<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Changelog; -Fixed the glass rain issue -Fixed the glass reflection issue -Fixed the mirror glare issue -Fixes Wheel -Fixed bugs*********************************** &ndash;HQ Model &ndash;Ao(Ambiyans Coating) -Sound -2 Different WheelCredits: Mert &#304;r&#351;i Sound:Nimit-Slav JerryDOWNLOAD 79 MB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[172],"tags":[],"class_list":["post-308440","post","type-post","status-publish","format-standard","hentry","category-cars"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Changelog; -Fixed the glass rain issue -Fixed the glass reflection issue -Fixed the mirror glare issue -Fixes Wheel -Fixed bugs *********************************** \u2013HQ Model \u2013Ao(Ambiyans Coating) -Sound -2 Different Wheel Credits: Mert \u0130r\u015fi Sound:Nimit-Slav Jerry DOWNLOAD 79 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bmw-m3-e30-2\\\/#article\",\"name\":\"Bmw M3 E30 | ETS 2 mods\",\"headline\":\"Bmw M3 E30\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Bmw-M3-E30-2.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bmw-m3-e30-2\\\/#articleImage\",\"width\":1000,\"height\":1125},\"datePublished\":\"2022-05-21T18:31:37+02:00\",\"dateModified\":\"2022-05-21T18:31:37+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bmw-m3-e30-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bmw-m3-e30-2\\\/#webpage\"},\"articleSection\":\"Cars\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bmw-m3-e30-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"name\":\"Cars\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"position\":2,\"name\":\"Cars\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bmw-m3-e30-2\\\/#listItem\",\"name\":\"Bmw M3 E30\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bmw-m3-e30-2\\\/#listItem\",\"position\":3,\"name\":\"Bmw M3 E30\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"name\":\"Cars\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bmw-m3-e30-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bmw-m3-e30-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bmw-m3-e30-2\\\/\",\"name\":\"Bmw M3 E30 | ETS 2 mods\",\"description\":\"Changelog; -Fixed the glass rain issue -Fixed the glass reflection issue -Fixed the mirror glare issue -Fixes Wheel -Fixed bugs *********************************** \\u2013HQ Model \\u2013Ao(Ambiyans Coating) -Sound -2 Different Wheel Credits: Mert \\u0130r\\u015fi Sound:Nimit-Slav Jerry DOWNLOAD 79 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bmw-m3-e30-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2022-05-21T18:31:37+02:00\",\"dateModified\":\"2022-05-21T18:31:37+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Bmw M3 E30 | ETS 2 mods","description":"Changelog; -Fixed the glass rain issue -Fixed the glass reflection issue -Fixed the mirror glare issue -Fixes Wheel -Fixed bugs *********************************** \u2013HQ Model \u2013Ao(Ambiyans Coating) -Sound -2 Different Wheel Credits: Mert \u0130r\u015fi Sound:Nimit-Slav Jerry DOWNLOAD 79 MB","canonical_url":"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/#article","name":"Bmw M3 E30 | ETS 2 mods","headline":"Bmw M3 E30","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/05\/Bmw-M3-E30-2.jpg","@id":"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/#articleImage","width":1000,"height":1125},"datePublished":"2022-05-21T18:31:37+02:00","dateModified":"2022-05-21T18:31:37+02:00","inLanguage":"en-US","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/#webpage"},"articleSection":"Cars"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","name":"Cars"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","position":2,"name":"Cars","item":"https:\/\/ets2.lt\/en\/category\/cars\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/#listItem","name":"Bmw M3 E30"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/#listItem","position":3,"name":"Bmw M3 E30","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","name":"Cars"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/#webpage","url":"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/","name":"Bmw M3 E30 | ETS 2 mods","description":"Changelog; -Fixed the glass rain issue -Fixed the glass reflection issue -Fixed the mirror glare issue -Fixes Wheel -Fixed bugs *********************************** \u2013HQ Model \u2013Ao(Ambiyans Coating) -Sound -2 Different Wheel Credits: Mert \u0130r\u015fi Sound:Nimit-Slav Jerry DOWNLOAD 79 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2022-05-21T18:31:37+02:00","dateModified":"2022-05-21T18:31:37+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"308440","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-05-21 16:30:49","updated":"2022-09-14 17:52:14","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/cars\/\" title=\"Cars\">Cars<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBmw M3 E30\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Cars","link":"https:\/\/ets2.lt\/en\/category\/cars\/"},{"label":"Bmw M3 E30","link":"https:\/\/ets2.lt\/en\/bmw-m3-e30-2\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/308440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=308440"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/308440\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=308440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=308440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=308440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}