{"id":311284,"date":"2022-07-14T18:12:32","date_gmt":"2022-07-14T16:12:32","guid":{"rendered":"https:\/\/ets2.lt\/?p=311284"},"modified":"2022-07-27T08:25:23","modified_gmt":"2022-07-27T06:25:23","slug":"mercedes-benz-gt63s-amg-couple","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/","title":{"rendered":"Mercedes Benz Gt63s AMG Couple"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/07\/Mercedes-Benz-Gt63s-AMG-Couple-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-311287\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/07\/Mercedes-Benz-Gt63s-AMG-Couple-1-555x937.jpg\" alt=\"\" width=\"555\" height=\"937\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/07\/Mercedes-Benz-Gt63s-AMG-Couple-1-555x937.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/07\/Mercedes-Benz-Gt63s-AMG-Couple-1-910x1536.jpg 910w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/07\/Mercedes-Benz-Gt63s-AMG-Couple-1.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><br>\n<a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/07\/Mercedes-Benz-Gt63s-AMG-Couple-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-311286\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/07\/Mercedes-Benz-Gt63s-AMG-Couple-2-555x624.jpg\" alt=\"\" width=\"555\" height=\"624\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/07\/Mercedes-Benz-Gt63s-AMG-Couple-2-555x624.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/07\/Mercedes-Benz-Gt63s-AMG-Couple-2.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><br>\n<a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/07\/Mercedes-Benz-Gt63s-AMG-Couple-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-311285\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/07\/Mercedes-Benz-Gt63s-AMG-Couple-3-555x624.jpg\" alt=\"\" width=\"555\" height=\"624\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/07\/Mercedes-Benz-Gt63s-AMG-Couple-3-555x624.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/07\/Mercedes-Benz-Gt63s-AMG-Couple-3.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><\/p><p>Features;<br>\n&ndash; HQ Model<br>\n&ndash; HQ Salon<br>\n&ndash;Ao(Ambiyans Coating)<br>\n&ndash;Different 3 Neon<\/p><p>Credits:<br>\n&#304;smail Kaan Sar&#305;b&#305;y&#305;k-Mert &#304;r&#351;i<br>\nSound;Nimit<\/p><p><strong><a href=\"https:\/\/modsfire.com\/IcgOBI5rqoJ3w36\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 79 MB<\/strong><\/p><p><!--more--><\/p><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"Mercedes-Benz GT63S AMG 4-Door Coup&eacute; - ETS2[1.44][Euro Truck Simulator 2]\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/RntavETkewI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"Mercedes-Benz GT63S AMG 4-Door Coup&eacute; |  ETS 2 1.44 | CAR Mods |Euro Truck Simulator 2|\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/4DitsPqNYk8?start=424&amp;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"[ETS2 1.44] Mercedes Benz GT63s AMG Coupe | Euro Truck Simulator 2 Mods\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/7KOzfdOQ-18?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"Mercedes Benz GT63S Amg 4-Door Couple ETS2 Car Mod #ets2 #ets2mods #newmods\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/MZxiyHn-ooY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"[ETS2 v1.44] Mercedes Benz GT63S AMG Couple\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/SGN431K8Lj8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><p><\/p>","protected":false},"excerpt":{"rendered":"<p>Features; &ndash; HQ Model &ndash; HQ Salon &ndash;Ao(Ambiyans Coating) &ndash;Different 3 NeonCredits: &#304;smail Kaan Sar&#305;b&#305;y&#305;k-Mert &#304;r&#351;i Sound;NimitDOWNLOAD 79 MB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[172],"tags":[],"class_list":["post-311284","post","type-post","status-publish","format-standard","hentry","category-cars"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Features; \u2013 HQ Model \u2013 HQ Salon \u2013Ao(Ambiyans Coating) \u2013Different 3 Neon Credits: \u0130smail Kaan Sar\u0131b\u0131y\u0131k-Mert \u0130r\u015fi Sound;Nimit DOWNLOAD 79 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-gt63s-amg-couple\\\/#article\",\"name\":\"Mercedes Benz Gt63s AMG Couple | ETS 2 mods\",\"headline\":\"Mercedes Benz Gt63s AMG Couple\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Mercedes-Benz-Gt63s-AMG-Couple-1.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-gt63s-amg-couple\\\/#articleImage\",\"width\":1000,\"height\":1688},\"datePublished\":\"2022-07-14T18:12:32+02:00\",\"dateModified\":\"2022-07-27T08:25:23+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":13,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-gt63s-amg-couple\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-gt63s-amg-couple\\\/#webpage\"},\"articleSection\":\"Cars\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-gt63s-amg-couple\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"name\":\"Cars\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"position\":2,\"name\":\"Cars\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-gt63s-amg-couple\\\/#listItem\",\"name\":\"Mercedes Benz Gt63s AMG Couple\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-gt63s-amg-couple\\\/#listItem\",\"position\":3,\"name\":\"Mercedes Benz Gt63s AMG Couple\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"name\":\"Cars\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-gt63s-amg-couple\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-gt63s-amg-couple\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-gt63s-amg-couple\\\/\",\"name\":\"Mercedes Benz Gt63s AMG Couple | ETS 2 mods\",\"description\":\"Features; \\u2013 HQ Model \\u2013 HQ Salon \\u2013Ao(Ambiyans Coating) \\u2013Different 3 Neon Credits: \\u0130smail Kaan Sar\\u0131b\\u0131y\\u0131k-Mert \\u0130r\\u015fi Sound;Nimit DOWNLOAD 79 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-gt63s-amg-couple\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2022-07-14T18:12:32+02:00\",\"dateModified\":\"2022-07-27T08:25:23+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mercedes Benz Gt63s AMG Couple | ETS 2 mods","description":"Features; \u2013 HQ Model \u2013 HQ Salon \u2013Ao(Ambiyans Coating) \u2013Different 3 Neon Credits: \u0130smail Kaan Sar\u0131b\u0131y\u0131k-Mert \u0130r\u015fi Sound;Nimit DOWNLOAD 79 MB","canonical_url":"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/#article","name":"Mercedes Benz Gt63s AMG Couple | ETS 2 mods","headline":"Mercedes Benz Gt63s AMG Couple","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/07\/Mercedes-Benz-Gt63s-AMG-Couple-1.jpg","@id":"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/#articleImage","width":1000,"height":1688},"datePublished":"2022-07-14T18:12:32+02:00","dateModified":"2022-07-27T08:25:23+02:00","inLanguage":"en-US","commentCount":13,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/#webpage"},"articleSection":"Cars"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","name":"Cars"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","position":2,"name":"Cars","item":"https:\/\/ets2.lt\/en\/category\/cars\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/#listItem","name":"Mercedes Benz Gt63s AMG Couple"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/#listItem","position":3,"name":"Mercedes Benz Gt63s AMG Couple","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","name":"Cars"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/#webpage","url":"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/","name":"Mercedes Benz Gt63s AMG Couple | ETS 2 mods","description":"Features; \u2013 HQ Model \u2013 HQ Salon \u2013Ao(Ambiyans Coating) \u2013Different 3 Neon Credits: \u0130smail Kaan Sar\u0131b\u0131y\u0131k-Mert \u0130r\u015fi Sound;Nimit DOWNLOAD 79 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2022-07-14T18:12:32+02:00","dateModified":"2022-07-27T08:25:23+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"311284","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-07-14 16:11:39","updated":"2022-09-14 11:54:29","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/cars\/\" title=\"Cars\">Cars<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMercedes Benz Gt63s AMG Couple\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Cars","link":"https:\/\/ets2.lt\/en\/category\/cars\/"},{"label":"Mercedes Benz Gt63s AMG Couple","link":"https:\/\/ets2.lt\/en\/mercedes-benz-gt63s-amg-couple\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/311284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=311284"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/311284\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=311284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=311284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=311284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}