{"id":312142,"date":"2022-08-02T18:39:30","date_gmt":"2022-08-02T16:39:30","guid":{"rendered":"https:\/\/ets2.lt\/?p=312142"},"modified":"2022-08-30T19:47:10","modified_gmt":"2022-08-30T17:47:10","slug":"mercedes-s-class-w221-1-45x","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/","title":{"rendered":"MERCEDES S-CLASS W221 1.45X"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/08\/MERCEDES-S-CLASS-W221-1.45X-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-312145\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/08\/MERCEDES-S-CLASS-W221-1.45X-1.jpg\" alt=\"\" width=\"555\" height=\"937\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/08\/MERCEDES-S-CLASS-W221-1.45X-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-312144\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/08\/MERCEDES-S-CLASS-W221-1.45X-2.jpg\" alt=\"\" width=\"555\" height=\"624\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/08\/MERCEDES-S-CLASS-W221-1.45X-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-312143\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/08\/MERCEDES-S-CLASS-W221-1.45X-3.jpg\" alt=\"\" width=\"555\" height=\"624\"><\/a><\/p><p>Changes;<br>\nBugs fixed<br>\nSkins have been improved<br>\nFeatures;<br>\n&ndash;HQ Model<br>\n&ndash;HQ Salon<br>\n&ndash;Ao(Ambiyans Coating)<br>\nLever Gear Animation<br>\nGlass Animations<br>\nWiper Animations<br>\nFlashing Option<br>\n3 Types of Wheel Options<br>\nHQ Interior<br>\nHQ EXterior<br>\nThere are 2 Different Engines (Low Hp High Hp)<br>\nSiren horn<\/p><p>Credits:<br>\n&#304;smail Kaan Sar&#305;b&#305;y&#305;k-Mert &#304;r&#351;i-Nimit<\/p><p><strong><a href=\"https:\/\/ets2gm.com\/mercedes-s-class-w221-1-45x\/\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a>&nbsp;<\/strong><\/p><p><!--more--><\/p><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"[ETS2 v1.44] Mercedes S-Class W221 | ETS2 Mod\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/xyrldLqpjso?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"&#9989;&#9654;MERCEDES S65 AMG W221&#9664; | ETS 2 1.45 |&#128678;CAR MOD | 2K\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/wrNULfOPyDE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><p><\/p>","protected":false},"excerpt":{"rendered":"<p>Changes; Bugs fixed Skins have been improved Features; &ndash;HQ Model &ndash;HQ Salon &ndash;Ao(Ambiyans Coating) Lever Gear Animation Glass Animations Wiper Animations Flashing Option 3 Types of Wheel Options HQ Interior HQ EXterior There are 2 Different Engines (Low Hp High Hp) Siren hornCredits: &#304;smail Kaan Sar&#305;b&#305;y&#305;k-Mert &#304;r&#351;i-NimitDOWNLOAD&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[172],"tags":[],"class_list":["post-312142","post","type-post","status-publish","format-standard","hentry","category-cars"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Changes; Bugs fixed Skins have been improved Features; \u2013HQ Model \u2013HQ Salon \u2013Ao(Ambiyans Coating) Lever Gear Animation Glass Animations Wiper Animations Flashing Option 3 Types of Wheel Options HQ Interior HQ EXterior There are 2 Different Engines (Low Hp High Hp) Siren horn Credits: \u0130smail Kaan Sar\u0131b\u0131y\u0131k-Mert \u0130r\u015fi-Nimit DOWNLOAD\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-s-class-w221-1-45x\\\/#article\",\"name\":\"MERCEDES S-CLASS W221 1.45X | ETS 2 mods\",\"headline\":\"MERCEDES S-CLASS W221 1.45X\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/MERCEDES-S-CLASS-W221-1.45X-1.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-s-class-w221-1-45x\\\/#articleImage\",\"width\":555,\"height\":937},\"datePublished\":\"2022-08-02T18:39:30+02:00\",\"dateModified\":\"2022-08-30T19:47:10+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":7,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-s-class-w221-1-45x\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-s-class-w221-1-45x\\\/#webpage\"},\"articleSection\":\"Cars\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-s-class-w221-1-45x\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"name\":\"Cars\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"position\":2,\"name\":\"Cars\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-s-class-w221-1-45x\\\/#listItem\",\"name\":\"MERCEDES S-CLASS W221 1.45X\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-s-class-w221-1-45x\\\/#listItem\",\"position\":3,\"name\":\"MERCEDES S-CLASS W221 1.45X\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"name\":\"Cars\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-s-class-w221-1-45x\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-s-class-w221-1-45x\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-s-class-w221-1-45x\\\/\",\"name\":\"MERCEDES S-CLASS W221 1.45X | ETS 2 mods\",\"description\":\"Changes; Bugs fixed Skins have been improved Features; \\u2013HQ Model \\u2013HQ Salon \\u2013Ao(Ambiyans Coating) Lever Gear Animation Glass Animations Wiper Animations Flashing Option 3 Types of Wheel Options HQ Interior HQ EXterior There are 2 Different Engines (Low Hp High Hp) Siren horn Credits: \\u0130smail Kaan Sar\\u0131b\\u0131y\\u0131k-Mert \\u0130r\\u015fi-Nimit DOWNLOAD\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-s-class-w221-1-45x\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2022-08-02T18:39:30+02:00\",\"dateModified\":\"2022-08-30T19:47:10+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"MERCEDES S-CLASS W221 1.45X | ETS 2 mods","description":"Changes; Bugs fixed Skins have been improved Features; \u2013HQ Model \u2013HQ Salon \u2013Ao(Ambiyans Coating) Lever Gear Animation Glass Animations Wiper Animations Flashing Option 3 Types of Wheel Options HQ Interior HQ EXterior There are 2 Different Engines (Low Hp High Hp) Siren horn Credits: \u0130smail Kaan Sar\u0131b\u0131y\u0131k-Mert \u0130r\u015fi-Nimit DOWNLOAD","canonical_url":"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/#article","name":"MERCEDES S-CLASS W221 1.45X | ETS 2 mods","headline":"MERCEDES S-CLASS W221 1.45X","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/08\/MERCEDES-S-CLASS-W221-1.45X-1.jpg","@id":"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/#articleImage","width":555,"height":937},"datePublished":"2022-08-02T18:39:30+02:00","dateModified":"2022-08-30T19:47:10+02:00","inLanguage":"en-US","commentCount":7,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/#webpage"},"articleSection":"Cars"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","name":"Cars"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","position":2,"name":"Cars","item":"https:\/\/ets2.lt\/en\/category\/cars\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/#listItem","name":"MERCEDES S-CLASS W221 1.45X"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/#listItem","position":3,"name":"MERCEDES S-CLASS W221 1.45X","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","name":"Cars"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/#webpage","url":"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/","name":"MERCEDES S-CLASS W221 1.45X | ETS 2 mods","description":"Changes; Bugs fixed Skins have been improved Features; \u2013HQ Model \u2013HQ Salon \u2013Ao(Ambiyans Coating) Lever Gear Animation Glass Animations Wiper Animations Flashing Option 3 Types of Wheel Options HQ Interior HQ EXterior There are 2 Different Engines (Low Hp High Hp) Siren horn Credits: \u0130smail Kaan Sar\u0131b\u0131y\u0131k-Mert \u0130r\u015fi-Nimit DOWNLOAD","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2022-08-02T18:39:30+02:00","dateModified":"2022-08-30T19:47:10+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"312142","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"blockGraphs\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-08-02 16:38:46","updated":"2022-09-14 12:11:03","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/cars\/\" title=\"Cars\">Cars<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMERCEDES S-CLASS W221 1.45X\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Cars","link":"https:\/\/ets2.lt\/en\/category\/cars\/"},{"label":"MERCEDES S-CLASS W221 1.45X","link":"https:\/\/ets2.lt\/en\/mercedes-s-class-w221-1-45x\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/312142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=312142"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/312142\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=312142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=312142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=312142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}