{"id":314130,"date":"2022-09-10T08:23:13","date_gmt":"2022-09-10T06:23:13","guid":{"rendered":"https:\/\/ets2.lt\/?p=314130"},"modified":"2022-09-10T08:23:13","modified_gmt":"2022-09-10T06:23:13","slug":"volvo-fh12-v1-45","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/","title":{"rendered":"Volvo FH12 v1.45"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Volvo-FH12-v1.45-ETS2-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-314131\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Volvo-FH12-v1.45-ETS2-2-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Volvo-FH12-v1.45-ETS2-2-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Volvo-FH12-v1.45-ETS2-2.jpg 1024w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a> <a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Volvo-FH12-v1.45-ETS2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-314132\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Volvo-FH12-v1.45-ETS2-1-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Volvo-FH12-v1.45-ETS2-1-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Volvo-FH12-v1.45-ETS2-1.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><\/p><p>4&times;2 chassis<br>\nGlobetrotter cab<br>\n4 types of engine and 2 types of gearbox<br>\nThis mod use standard SCS interior from Volvo FH16 2009<br>\nFor v1.45<\/p><p>Credits:<br>\nsatan19990<br>\nUpdate: Sonor<\/p><p><strong><a href=\"https:\/\/mods.to\/ywq7ymkbi6r4\/Truck-ETS2_Volvo_FH12_v1.45.scs.html\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 45 MB<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>4&times;2 chassis Globetrotter cab 4 types of engine and 2 types of gearbox This mod use standard SCS interior from Volvo FH16 2009 For v1.45Credits: satan19990 Update: SonorDOWNLOAD 45 MB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-314130","post","type-post","status-publish","format-standard","hentry","category-trucks"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"4\u00d72 chassis Globetrotter cab 4 types of engine and 2 types of gearbox This mod use standard SCS interior from Volvo FH16 2009 For v1.45 Credits: satan19990 Update: Sonor DOWNLOAD 45 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh12-v1-45\\\/#article\",\"name\":\"Volvo FH12 v1.45 | ETS 2 mods\",\"headline\":\"Volvo FH12 v1.45\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Volvo-FH12-v1.45-ETS2-2.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh12-v1-45\\\/#articleImage\",\"width\":1024,\"height\":576},\"datePublished\":\"2022-09-10T08:23:13+02:00\",\"dateModified\":\"2022-09-10T08:23:13+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh12-v1-45\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh12-v1-45\\\/#webpage\"},\"articleSection\":\"Trucks\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh12-v1-45\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"name\":\"Trucks\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"position\":2,\"name\":\"Trucks\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh12-v1-45\\\/#listItem\",\"name\":\"Volvo FH12 v1.45\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh12-v1-45\\\/#listItem\",\"position\":3,\"name\":\"Volvo FH12 v1.45\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"name\":\"Trucks\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh12-v1-45\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh12-v1-45\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh12-v1-45\\\/\",\"name\":\"Volvo FH12 v1.45 | ETS 2 mods\",\"description\":\"4\\u00d72 chassis Globetrotter cab 4 types of engine and 2 types of gearbox This mod use standard SCS interior from Volvo FH16 2009 For v1.45 Credits: satan19990 Update: Sonor DOWNLOAD 45 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volvo-fh12-v1-45\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2022-09-10T08:23:13+02:00\",\"dateModified\":\"2022-09-10T08:23:13+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Volvo FH12 v1.45 | ETS 2 mods","description":"4\u00d72 chassis Globetrotter cab 4 types of engine and 2 types of gearbox This mod use standard SCS interior from Volvo FH16 2009 For v1.45 Credits: satan19990 Update: Sonor DOWNLOAD 45 MB","canonical_url":"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/#article","name":"Volvo FH12 v1.45 | ETS 2 mods","headline":"Volvo FH12 v1.45","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Volvo-FH12-v1.45-ETS2-2.jpg","@id":"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/#articleImage","width":1024,"height":576},"datePublished":"2022-09-10T08:23:13+02:00","dateModified":"2022-09-10T08:23:13+02:00","inLanguage":"en-US","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/#webpage"},"articleSection":"Trucks"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","name":"Trucks"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","position":2,"name":"Trucks","item":"https:\/\/ets2.lt\/en\/category\/trucks\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/#listItem","name":"Volvo FH12 v1.45"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/#listItem","position":3,"name":"Volvo FH12 v1.45","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","name":"Trucks"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/#webpage","url":"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/","name":"Volvo FH12 v1.45 | ETS 2 mods","description":"4\u00d72 chassis Globetrotter cab 4 types of engine and 2 types of gearbox This mod use standard SCS interior from Volvo FH16 2009 For v1.45 Credits: satan19990 Update: Sonor DOWNLOAD 45 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2022-09-10T08:23:13+02:00","dateModified":"2022-09-10T08:23:13+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"314130","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"blockGraphs\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-09-10 06:21:35","updated":"2022-09-14 11:57:56","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/trucks\/\" title=\"Trucks\">Trucks<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVolvo FH12 v1.45\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Trucks","link":"https:\/\/ets2.lt\/en\/category\/trucks\/"},{"label":"Volvo FH12 v1.45","link":"https:\/\/ets2.lt\/en\/volvo-fh12-v1-45\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/314130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=314130"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/314130\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=314130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=314130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=314130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}