{"id":314180,"date":"2022-09-11T08:32:28","date_gmt":"2022-09-11T06:32:28","guid":{"rendered":"https:\/\/ets2.lt\/?p=314180"},"modified":"2022-09-11T08:32:28","modified_gmt":"2022-09-11T06:32:28","slug":"mercedes-conecto-autokraft-skin-pack","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/","title":{"rendered":"Mercedes Conecto Autokraft Skin Pack"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Mercedes-Conecto-Autokraft-Skin-Pack-2.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Mercedes-Conecto-Autokraft-Skin-Pack-2-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" class=\"alignnone size-medium wp-image-314181\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Mercedes-Conecto-Autokraft-Skin-Pack-2-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Mercedes-Conecto-Autokraft-Skin-Pack-2.jpg 768w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><br>\n<a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Mercedes-Conecto-Autokraft-Skin-Pack-1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Mercedes-Conecto-Autokraft-Skin-Pack-1-555x312.jpg\" alt=\"\" width=\"555\" height=\"312\" class=\"alignnone size-medium wp-image-314182\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Mercedes-Conecto-Autokraft-Skin-Pack-1-555x312.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Mercedes-Conecto-Autokraft-Skin-Pack-1.jpg 768w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><\/p><p>Skins for Mercedes Conecto by trzpro, harun aras<\/p><p>Numberplates included<\/p><p>enjoy follow for more stuff!<br>\n&ndash; Instagram: hedmark_transport_ets2 , ets2.realvsvirtual , scaniaandvolvoswedenpower<br>\n&ndash; Twitch: oikakka<br>\n&ndash; YouTube: Norwegian Trucker<br>\n&ndash; Gumroad: https:\/\/htcustom.gumroad.com\/<\/p><p>Credits:<br>\nHedmark Transport<\/p><p><strong><a href=\"https:\/\/sharemods.com\/k2u7uh0cteh9\/MB_Conecto_Autokraft_Pack.scs.html\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 930 KB<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Skins for Mercedes Conecto by trzpro, harun arasNumberplates includedenjoy follow for more stuff! &ndash; Instagram: hedmark_transport_ets2 , ets2.realvsvirtual , scaniaandvolvoswedenpower &ndash; Twitch: oikakka &ndash; YouTube: Norwegian Trucker &ndash; Gumroad: https:\/\/htcustom.gumroad.com\/Credits: Hedmark TransportDOWNLOAD 930 KB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1211],"tags":[],"class_list":["post-314180","post","type-post","status-publish","format-standard","hentry","category-bus-mods"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Skins for Mercedes Conecto by trzpro, harun aras Numberplates included enjoy follow for more stuff! - Instagram: hedmark_transport_ets2 , ets2.realvsvirtual , scaniaandvolvoswedenpower - Twitch: oikakka - YouTube: Norwegian Trucker - Gumroad: https:\/\/htcustom.gumroad.com\/ Credits: Hedmark Transport DOWNLOAD 930 KB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-conecto-autokraft-skin-pack\\\/#article\",\"name\":\"Mercedes Conecto Autokraft Skin Pack | ETS 2 mods\",\"headline\":\"Mercedes Conecto Autokraft Skin Pack\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Mercedes-Conecto-Autokraft-Skin-Pack-2.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-conecto-autokraft-skin-pack\\\/#articleImage\",\"width\":768,\"height\":432},\"datePublished\":\"2022-09-11T08:32:28+02:00\",\"dateModified\":\"2022-09-11T08:32:28+02:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-conecto-autokraft-skin-pack\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-conecto-autokraft-skin-pack\\\/#webpage\"},\"articleSection\":\"Bus mods\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-conecto-autokraft-skin-pack\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/bus-mods\\\/#listItem\",\"name\":\"Bus mods\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/bus-mods\\\/#listItem\",\"position\":2,\"name\":\"Bus mods\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/bus-mods\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-conecto-autokraft-skin-pack\\\/#listItem\",\"name\":\"Mercedes Conecto Autokraft Skin Pack\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-conecto-autokraft-skin-pack\\\/#listItem\",\"position\":3,\"name\":\"Mercedes Conecto Autokraft Skin Pack\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/bus-mods\\\/#listItem\",\"name\":\"Bus mods\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-conecto-autokraft-skin-pack\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-conecto-autokraft-skin-pack\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-conecto-autokraft-skin-pack\\\/\",\"name\":\"Mercedes Conecto Autokraft Skin Pack | ETS 2 mods\",\"description\":\"Skins for Mercedes Conecto by trzpro, harun aras Numberplates included enjoy follow for more stuff! - Instagram: hedmark_transport_ets2 , ets2.realvsvirtual , scaniaandvolvoswedenpower - Twitch: oikakka - YouTube: Norwegian Trucker - Gumroad: https:\\\/\\\/htcustom.gumroad.com\\\/ Credits: Hedmark Transport DOWNLOAD 930 KB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-conecto-autokraft-skin-pack\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2022-09-11T08:32:28+02:00\",\"dateModified\":\"2022-09-11T08:32:28+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mercedes Conecto Autokraft Skin Pack | ETS 2 mods","description":"Skins for Mercedes Conecto by trzpro, harun aras Numberplates included enjoy follow for more stuff! - Instagram: hedmark_transport_ets2 , ets2.realvsvirtual , scaniaandvolvoswedenpower - Twitch: oikakka - YouTube: Norwegian Trucker - Gumroad: https:\/\/htcustom.gumroad.com\/ Credits: Hedmark Transport DOWNLOAD 930 KB","canonical_url":"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/#article","name":"Mercedes Conecto Autokraft Skin Pack | ETS 2 mods","headline":"Mercedes Conecto Autokraft Skin Pack","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/09\/Mercedes-Conecto-Autokraft-Skin-Pack-2.jpg","@id":"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/#articleImage","width":768,"height":432},"datePublished":"2022-09-11T08:32:28+02:00","dateModified":"2022-09-11T08:32:28+02:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/#webpage"},"articleSection":"Bus mods"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/bus-mods\/#listItem","name":"Bus mods"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/bus-mods\/#listItem","position":2,"name":"Bus mods","item":"https:\/\/ets2.lt\/en\/category\/bus-mods\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/#listItem","name":"Mercedes Conecto Autokraft Skin Pack"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/#listItem","position":3,"name":"Mercedes Conecto Autokraft Skin Pack","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/bus-mods\/#listItem","name":"Bus mods"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/#webpage","url":"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/","name":"Mercedes Conecto Autokraft Skin Pack | ETS 2 mods","description":"Skins for Mercedes Conecto by trzpro, harun aras Numberplates included enjoy follow for more stuff! - Instagram: hedmark_transport_ets2 , ets2.realvsvirtual , scaniaandvolvoswedenpower - Twitch: oikakka - YouTube: Norwegian Trucker - Gumroad: https:\/\/htcustom.gumroad.com\/ Credits: Hedmark Transport DOWNLOAD 930 KB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2022-09-11T08:32:28+02:00","dateModified":"2022-09-11T08:32:28+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"314180","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"blockGraphs\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-09-11 06:31:45","updated":"2022-09-14 12:34:07","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/bus-mods\/\" title=\"Bus mods\">Bus mods<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMercedes Conecto Autokraft Skin Pack\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Bus mods","link":"https:\/\/ets2.lt\/en\/category\/bus-mods\/"},{"label":"Mercedes Conecto Autokraft Skin Pack","link":"https:\/\/ets2.lt\/en\/mercedes-conecto-autokraft-skin-pack\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/314180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=314180"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/314180\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=314180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=314180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=314180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}