{"id":316597,"date":"2022-10-30T18:49:44","date_gmt":"2022-10-30T16:49:44","guid":{"rendered":"https:\/\/ets2.lt\/?p=316597"},"modified":"2022-11-23T19:10:52","modified_gmt":"2022-11-23T17:10:52","slug":"porsche-718-boxster-s","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/","title":{"rendered":"Porsche 718 Boxster S"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/10\/Porsche-718-Boxster-S-1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/10\/Porsche-718-Boxster-S-1-555x624.jpg\" alt=\"\" width=\"555\" height=\"624\" class=\"alignnone size-medium wp-image-316600\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/10\/Porsche-718-Boxster-S-1-555x624.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/10\/Porsche-718-Boxster-S-1.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><br>\n<a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/10\/Porsche-718-Boxster-S-2.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/10\/Porsche-718-Boxster-S-2-555x624.jpg\" alt=\"\" width=\"555\" height=\"624\" class=\"alignnone size-medium wp-image-316599\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/10\/Porsche-718-Boxster-S-2-555x624.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/10\/Porsche-718-Boxster-S-2.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><br>\n<a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/10\/Porsche-718-Boxster-S-3.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/10\/Porsche-718-Boxster-S-3-555x624.jpg\" alt=\"\" width=\"555\" height=\"624\" class=\"alignnone size-medium wp-image-316598\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/10\/Porsche-718-Boxster-S-3-555x624.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2022\/10\/Porsche-718-Boxster-S-3.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><\/p><p>&ndash; Independent<\/p><p>&ndash; Done Editing 1.46x<\/p><p>&ndash; Steering was the option<\/p><p>&ndash; Multi-Sp adapted from<\/p><p>&ndash; HQ Model<\/p><p>&ndash; Ao(Ambiyans Coating)<\/p><p>Credits:<br>\nHalil YAVUZ,Mert &#304;R&#350;&#304;<\/p><p><strong><a href=\"https:\/\/modsfire.com\/3i3L9Z2Sh6cUa1m\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 37 MB<\/strong><\/p><p><!--more--><\/p><p><a href=\"https:\/\/youtu.be\/dNHMlWLiHM8\" rel=\"ugc nofollow noopener\" target=\"_blank\">https:\/\/youtu.be\/dNHMlWLiHM8<\/a><\/p><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"ETS 2 | Porsche 718 Boxster S | Euro Truck Simulator 2 Car Mod #ets2 #eurotrucksimulator2 #ets2mod\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/wvy0x6SBIgI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"&#9989;&#9654; Porsche 718 Boxster S &#9664; | ETS 2 1.46 | 2K\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/lyJtDKBvv6o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><p><\/p>","protected":false},"excerpt":{"rendered":"<p>&ndash; Independent&ndash; Done Editing 1.46x&ndash; Steering was the option&ndash; Multi-Sp adapted from&ndash; HQ Model&ndash; Ao(Ambiyans Coating)Credits: Halil YAVUZ,Mert &#304;R&#350;&#304;DOWNLOAD 37 MB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[172],"tags":[],"class_list":["post-316597","post","type-post","status-publish","format-standard","hentry","category-cars"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u2013 Independent \u2013 Done Editing 1.46x \u2013 Steering was the option \u2013 Multi-Sp adapted from \u2013 HQ Model \u2013 Ao(Ambiyans Coating) Credits: Halil YAVUZ,Mert \u0130R\u015e\u0130 DOWNLOAD 37 MB https:\/\/www.youtube.com\/watch?v=wvy0x6SBIgI\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/porsche-718-boxster-s\\\/#article\",\"name\":\"Porsche 718 Boxster S | ETS 2 mods\",\"headline\":\"Porsche 718 Boxster S\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Porsche-718-Boxster-S-1.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/porsche-718-boxster-s\\\/#articleImage\",\"width\":1000,\"height\":1125},\"datePublished\":\"2022-10-30T18:49:44+02:00\",\"dateModified\":\"2022-11-23T19:10:52+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/porsche-718-boxster-s\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/porsche-718-boxster-s\\\/#webpage\"},\"articleSection\":\"Cars\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/porsche-718-boxster-s\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"name\":\"Cars\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"position\":2,\"name\":\"Cars\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/porsche-718-boxster-s\\\/#listItem\",\"name\":\"Porsche 718 Boxster S\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/porsche-718-boxster-s\\\/#listItem\",\"position\":3,\"name\":\"Porsche 718 Boxster S\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"name\":\"Cars\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/porsche-718-boxster-s\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/porsche-718-boxster-s\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/porsche-718-boxster-s\\\/\",\"name\":\"Porsche 718 Boxster S | ETS 2 mods\",\"description\":\"\\u2013 Independent \\u2013 Done Editing 1.46x \\u2013 Steering was the option \\u2013 Multi-Sp adapted from \\u2013 HQ Model \\u2013 Ao(Ambiyans Coating) Credits: Halil YAVUZ,Mert \\u0130R\\u015e\\u0130 DOWNLOAD 37 MB https:\\\/\\\/www.youtube.com\\\/watch?v=wvy0x6SBIgI\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/porsche-718-boxster-s\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2022-10-30T18:49:44+02:00\",\"dateModified\":\"2022-11-23T19:10:52+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Porsche 718 Boxster S | ETS 2 mods","description":"\u2013 Independent \u2013 Done Editing 1.46x \u2013 Steering was the option \u2013 Multi-Sp adapted from \u2013 HQ Model \u2013 Ao(Ambiyans Coating) Credits: Halil YAVUZ,Mert \u0130R\u015e\u0130 DOWNLOAD 37 MB https:\/\/www.youtube.com\/watch?v=wvy0x6SBIgI","canonical_url":"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/#article","name":"Porsche 718 Boxster S | ETS 2 mods","headline":"Porsche 718 Boxster S","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2022\/10\/Porsche-718-Boxster-S-1.jpg","@id":"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/#articleImage","width":1000,"height":1125},"datePublished":"2022-10-30T18:49:44+02:00","dateModified":"2022-11-23T19:10:52+02:00","inLanguage":"en-US","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/#webpage"},"articleSection":"Cars"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","name":"Cars"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","position":2,"name":"Cars","item":"https:\/\/ets2.lt\/en\/category\/cars\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/#listItem","name":"Porsche 718 Boxster S"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/#listItem","position":3,"name":"Porsche 718 Boxster S","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","name":"Cars"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/#webpage","url":"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/","name":"Porsche 718 Boxster S | ETS 2 mods","description":"\u2013 Independent \u2013 Done Editing 1.46x \u2013 Steering was the option \u2013 Multi-Sp adapted from \u2013 HQ Model \u2013 Ao(Ambiyans Coating) Credits: Halil YAVUZ,Mert \u0130R\u015e\u0130 DOWNLOAD 37 MB https:\/\/www.youtube.com\/watch?v=wvy0x6SBIgI","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2022-10-30T18:49:44+02:00","dateModified":"2022-11-23T19:10:52+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"316597","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-10-30 16:48:04","updated":"2022-11-23 17:10:52","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/cars\/\" title=\"Cars\">Cars<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPorsche 718 Boxster S\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Cars","link":"https:\/\/ets2.lt\/en\/category\/cars\/"},{"label":"Porsche 718 Boxster S","link":"https:\/\/ets2.lt\/en\/porsche-718-boxster-s\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/316597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=316597"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/316597\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=316597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=316597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=316597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}