{"id":322478,"date":"2023-03-09T09:26:25","date_gmt":"2023-03-09T07:26:25","guid":{"rendered":"https:\/\/ets2.lt\/?p=322478"},"modified":"2023-03-09T09:26:25","modified_gmt":"2023-03-09T07:26:25","slug":"volkswagen-passat-b8-fixed","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/","title":{"rendered":"Volkswagen Passat B8 (Fixed)"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/03\/Volkswagen-Passat-B8-Fixed-1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/03\/Volkswagen-Passat-B8-Fixed-1-555x694.jpg\" alt=\"\" width=\"555\" height=\"694\" class=\"alignnone size-medium wp-image-322480\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/03\/Volkswagen-Passat-B8-Fixed-1-555x694.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2023\/03\/Volkswagen-Passat-B8-Fixed-1.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><br>\n<a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/03\/Volkswagen-Passat-B8-Fixed-2.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/03\/Volkswagen-Passat-B8-Fixed-2-555x694.jpg\" alt=\"\" width=\"555\" height=\"694\" class=\"alignnone size-medium wp-image-322479\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/03\/Volkswagen-Passat-B8-Fixed-2-555x694.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2023\/03\/Volkswagen-Passat-B8-Fixed-2.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><\/p><p>All requested errors have been fixed<\/p><p>Features<br>\n&ndash; HQ Model &amp; textures<br>\n&ndash; Active glass animation and more animations<br>\n&ndash; 3 different wheels<br>\n&ndash; Realistic lightmasks<br>\n&ndash; Realistic engine settings<\/p><p>Credits:<br>\nBerkay Pekesen<\/p><p><strong><a href=\"https:\/\/sharemods.com\/pskqlt3w00e9\/Volkswagen_Passat_B8.scs.html\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 56 MB<\/strong><\/p><p><!--more--><\/p><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"VOLKSWAGEN PASSAT \/\/ &#350;U ANA KADAR K&#304; EN KAL&#304;TEL&#304; PASSAT | GRAND UTOPIA 1.13 ETS2 1.43 !!\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/WF7xKPjELD4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><p><\/p>","protected":false},"excerpt":{"rendered":"<p>All requested errors have been fixedFeatures &ndash; HQ Model &amp; textures &ndash; Active glass animation and more animations &ndash; 3 different wheels &ndash; Realistic lightmasks &ndash; Realistic engine settingsCredits: Berkay PekesenDOWNLOAD 56 MB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[172],"tags":[],"class_list":["post-322478","post","type-post","status-publish","format-standard","hentry","category-cars"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"All requested errors have been fixed Features \u2013 HQ Model &amp; textures \u2013 Active glass animation and more animations \u2013 3 different wheels \u2013 Realistic lightmasks \u2013 Realistic engine settings Credits: Berkay Pekesen DOWNLOAD 56 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volkswagen-passat-b8-fixed\\\/#article\",\"name\":\"Volkswagen Passat B8 (Fixed) | ETS 2 mods\",\"headline\":\"Volkswagen Passat B8 (Fixed)\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Volkswagen-Passat-B8-Fixed-1.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volkswagen-passat-b8-fixed\\\/#articleImage\",\"width\":1000,\"height\":1250},\"datePublished\":\"2023-03-09T09:26:25+02:00\",\"dateModified\":\"2023-03-09T09:26:25+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":6,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volkswagen-passat-b8-fixed\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volkswagen-passat-b8-fixed\\\/#webpage\"},\"articleSection\":\"Cars\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volkswagen-passat-b8-fixed\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"name\":\"Cars\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"position\":2,\"name\":\"Cars\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volkswagen-passat-b8-fixed\\\/#listItem\",\"name\":\"Volkswagen Passat B8 (Fixed)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volkswagen-passat-b8-fixed\\\/#listItem\",\"position\":3,\"name\":\"Volkswagen Passat B8 (Fixed)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"name\":\"Cars\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volkswagen-passat-b8-fixed\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volkswagen-passat-b8-fixed\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volkswagen-passat-b8-fixed\\\/\",\"name\":\"Volkswagen Passat B8 (Fixed) | ETS 2 mods\",\"description\":\"All requested errors have been fixed Features \\u2013 HQ Model & textures \\u2013 Active glass animation and more animations \\u2013 3 different wheels \\u2013 Realistic lightmasks \\u2013 Realistic engine settings Credits: Berkay Pekesen DOWNLOAD 56 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/volkswagen-passat-b8-fixed\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2023-03-09T09:26:25+02:00\",\"dateModified\":\"2023-03-09T09:26:25+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Volkswagen Passat B8 (Fixed) | ETS 2 mods","description":"All requested errors have been fixed Features \u2013 HQ Model & textures \u2013 Active glass animation and more animations \u2013 3 different wheels \u2013 Realistic lightmasks \u2013 Realistic engine settings Credits: Berkay Pekesen DOWNLOAD 56 MB","canonical_url":"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/#article","name":"Volkswagen Passat B8 (Fixed) | ETS 2 mods","headline":"Volkswagen Passat B8 (Fixed)","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/03\/Volkswagen-Passat-B8-Fixed-1.jpg","@id":"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/#articleImage","width":1000,"height":1250},"datePublished":"2023-03-09T09:26:25+02:00","dateModified":"2023-03-09T09:26:25+02:00","inLanguage":"en-US","commentCount":6,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/#webpage"},"articleSection":"Cars"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","name":"Cars"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","position":2,"name":"Cars","item":"https:\/\/ets2.lt\/en\/category\/cars\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/#listItem","name":"Volkswagen Passat B8 (Fixed)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/#listItem","position":3,"name":"Volkswagen Passat B8 (Fixed)","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","name":"Cars"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/#webpage","url":"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/","name":"Volkswagen Passat B8 (Fixed) | ETS 2 mods","description":"All requested errors have been fixed Features \u2013 HQ Model & textures \u2013 Active glass animation and more animations \u2013 3 different wheels \u2013 Realistic lightmasks \u2013 Realistic engine settings Credits: Berkay Pekesen DOWNLOAD 56 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2023-03-09T09:26:25+02:00","dateModified":"2023-03-09T09:26:25+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"322478","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-03-09 07:25:40","updated":"2023-03-09 07:26:26","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/cars\/\" title=\"Cars\">Cars<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVolkswagen Passat B8 (Fixed)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Cars","link":"https:\/\/ets2.lt\/en\/category\/cars\/"},{"label":"Volkswagen Passat B8 (Fixed)","link":"https:\/\/ets2.lt\/en\/volkswagen-passat-b8-fixed\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/322478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=322478"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/322478\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=322478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=322478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=322478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}