{"id":326365,"date":"2023-05-22T04:41:53","date_gmt":"2023-05-22T02:41:53","guid":{"rendered":"https:\/\/ets2.lt\/?p=326365"},"modified":"2023-05-22T21:24:24","modified_gmt":"2023-05-22T19:24:24","slug":"mercedes-benz-w223-s-class-v1-1-1-47","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/","title":{"rendered":"Mercedes-Benz W223 S-Class V1.1 1.47"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-1.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-1-555x1041.jpg\" alt=\"\" width=\"555\" height=\"1041\" class=\"alignnone size-medium wp-image-326368\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-1-555x1041.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-1-819x1536.jpg 819w, https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-1.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><br>\n<a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-2.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-2-555x1041.jpg\" alt=\"\" width=\"555\" height=\"1041\" class=\"alignnone size-medium wp-image-326367\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-2-555x1041.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-2-819x1536.jpg 819w, https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-2.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><br>\n<a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-3.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-3-555x1041.jpg\" alt=\"\" width=\"555\" height=\"1041\" class=\"alignnone size-medium wp-image-326366\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-3-555x1041.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-3-819x1536.jpg 819w, https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-3.jpg 1000w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\"><\/a><\/p><p>CHANGELOG:-<\/p><p>&ndash; Updated to game version 1.47<br>\n&ndash; Added interior rear-view mirror<br>\n&ndash; Added dashboard symbols (light beam, handbrake &amp; indicators)<br>\n&ndash; Added new rims<br>\n&ndash; Minor edits and fixes<\/p><p>Specifications:-<\/p><p>&ndash; Very high-quality exterior &amp; interior<br>\n&ndash; Custom UI with digital speedo (in km\/h) &amp; functional misc information<br>\n&ndash; Excellent driveability<br>\n&ndash; Openable Front Windows<br>\n&ndash; Wipers work accurately<br>\n&ndash; Indicator stalk animation<br>\n&ndash; 5 types of rims<br>\n&ndash; Can be attached with a compatible trailer<br>\n&ndash; Realistic engine &amp; transmission configuration (even the 0-100, 0-200 &amp; 0-250 kmph timings are very close compared to the real-life counterpart)<br>\n&ndash; Partially realistic sound (to turn on comfort sound, hold your assigned lighthorn hotkey for one complete second)<\/p><p>*To achieve the top speed, slot the car into the 6th gear*<\/p><p>FAQ:<br>\nQ: Where to purchase it?:<br>\nA: Truck Dealers &gt; Access Mod Dealer &gt; Mercedes-Benz<\/p><p>DO NOT EDIT<br>\nDO NOT CHANGE LINK<br>\nDO NOT REUPLOAD<\/p><p>Credits:<br>\nDN Modding, Nimit, &#304;smail Kaan, Slav Jerry<\/p><p><strong><a href=\"https:\/\/modsfire.com\/UnXr5K3GCj4562L\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 162 MB<\/strong><\/p><p><!--more--><\/p><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"[ATS\/ETS2] Mercedes-Benz W223 S-Class V1\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/0LNG9AvvDro?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"Mercedes-Benz W223 S500L-Euro Truck Simulator 2\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/xaJjbccnK-s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><p><\/p>","protected":false},"excerpt":{"rendered":"<p>CHANGELOG:-&ndash; Updated to game version 1.47 &ndash; Added interior rear-view mirror &ndash; Added dashboard symbols (light beam, handbrake &amp; indicators) &ndash; Added new rims &ndash; Minor edits and fixesSpecifications:-&ndash; Very high-quality exterior &amp; interior &ndash; Custom UI with digital speedo (in km\/h) &amp; functional misc information &ndash; Excellent driveability &ndash; Openable Front Windows &ndash; Wipers [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[172],"tags":[8860],"class_list":["post-326365","post","type-post","status-publish","format-standard","hentry","category-cars","tag-1-47"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"CHANGELOG:- - Updated to game version 1.47 - Added interior rear-view mirror - Added dashboard symbols (light beam, handbrake &amp; indicators) - Added new rims - Minor edits and fixes Specifications:- - Very high-quality exterior &amp; interior - Custom UI with digital speedo (in km\/h) &amp; functional misc information \u2013 Excellent driveability - Openable Front\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-w223-s-class-v1-1-1-47\\\/#article\",\"name\":\"Mercedes-Benz W223 S-Class V1.1 1.47 | ETS 2 mods\",\"headline\":\"Mercedes-Benz W223 S-Class V1.1 1.47\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Mercedes-Benz-W223-S-Class-V1.1-1.47-1.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-w223-s-class-v1-1-1-47\\\/#articleImage\",\"width\":1000,\"height\":1875},\"datePublished\":\"2023-05-22T04:41:53+02:00\",\"dateModified\":\"2023-05-22T21:24:24+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":22,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-w223-s-class-v1-1-1-47\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-w223-s-class-v1-1-1-47\\\/#webpage\"},\"articleSection\":\"Cars, 1.47\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-w223-s-class-v1-1-1-47\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"name\":\"Cars\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"position\":2,\"name\":\"Cars\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-w223-s-class-v1-1-1-47\\\/#listItem\",\"name\":\"Mercedes-Benz W223 S-Class V1.1 1.47\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-w223-s-class-v1-1-1-47\\\/#listItem\",\"position\":3,\"name\":\"Mercedes-Benz W223 S-Class V1.1 1.47\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/cars\\\/#listItem\",\"name\":\"Cars\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-w223-s-class-v1-1-1-47\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-w223-s-class-v1-1-1-47\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-w223-s-class-v1-1-1-47\\\/\",\"name\":\"Mercedes-Benz W223 S-Class V1.1 1.47 | ETS 2 mods\",\"description\":\"CHANGELOG:- - Updated to game version 1.47 - Added interior rear-view mirror - Added dashboard symbols (light beam, handbrake & indicators) - Added new rims - Minor edits and fixes Specifications:- - Very high-quality exterior & interior - Custom UI with digital speedo (in km\\\/h) & functional misc information \\u2013 Excellent driveability - Openable Front\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mercedes-benz-w223-s-class-v1-1-1-47\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2023-05-22T04:41:53+02:00\",\"dateModified\":\"2023-05-22T21:24:24+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mercedes-Benz W223 S-Class V1.1 1.47 | ETS 2 mods","description":"CHANGELOG:- - Updated to game version 1.47 - Added interior rear-view mirror - Added dashboard symbols (light beam, handbrake & indicators) - Added new rims - Minor edits and fixes Specifications:- - Very high-quality exterior & interior - Custom UI with digital speedo (in km\/h) & functional misc information \u2013 Excellent driveability - Openable Front","canonical_url":"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/#article","name":"Mercedes-Benz W223 S-Class V1.1 1.47 | ETS 2 mods","headline":"Mercedes-Benz W223 S-Class V1.1 1.47","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2023\/05\/Mercedes-Benz-W223-S-Class-V1.1-1.47-1.jpg","@id":"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/#articleImage","width":1000,"height":1875},"datePublished":"2023-05-22T04:41:53+02:00","dateModified":"2023-05-22T21:24:24+02:00","inLanguage":"en-US","commentCount":22,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/#webpage"},"articleSection":"Cars, 1.47"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","name":"Cars"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","position":2,"name":"Cars","item":"https:\/\/ets2.lt\/en\/category\/cars\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/#listItem","name":"Mercedes-Benz W223 S-Class V1.1 1.47"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/#listItem","position":3,"name":"Mercedes-Benz W223 S-Class V1.1 1.47","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/cars\/#listItem","name":"Cars"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/#webpage","url":"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/","name":"Mercedes-Benz W223 S-Class V1.1 1.47 | ETS 2 mods","description":"CHANGELOG:- - Updated to game version 1.47 - Added interior rear-view mirror - Added dashboard symbols (light beam, handbrake & indicators) - Added new rims - Minor edits and fixes Specifications:- - Very high-quality exterior & interior - Custom UI with digital speedo (in km\/h) & functional misc information \u2013 Excellent driveability - Openable Front","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2023-05-22T04:41:53+02:00","dateModified":"2023-05-22T21:24:24+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"326365","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-22 02:40:56","updated":"2023-05-22 19:24:24","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/cars\/\" title=\"Cars\">Cars<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMercedes-Benz W223 S-Class V1.1 1.47\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Cars","link":"https:\/\/ets2.lt\/en\/category\/cars\/"},{"label":"Mercedes-Benz W223 S-Class V1.1 1.47","link":"https:\/\/ets2.lt\/en\/mercedes-benz-w223-s-class-v1-1-1-47\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/326365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=326365"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/326365\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=326365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=326365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=326365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}