{"id":374251,"date":"2026-02-21T18:53:16","date_gmt":"2026-02-21T16:53:16","guid":{"rendered":"https:\/\/ets2.lt\/en\/?p=374251"},"modified":"2026-02-21T18:53:16","modified_gmt":"2026-02-21T16:53:16","slug":"scania-megamod-v7-0-ets2-1-58-x","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/","title":{"rendered":"SCANIA MEGAMOD v7.0 ETS2 1.58.x"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/02\/sm00.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-374248\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/02\/sm00-750x844.jpg\" alt=\"SCANIA MEGAMOD v7.0 ETS2 1.58.x\" width=\"750\" height=\"844\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/02\/sm00-750x844.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/02\/sm00.jpg 1000w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/02\/sm01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-374249\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/02\/sm01-750x844.jpg\" alt=\"SCANIA MEGAMOD v7.0 ETS2 1.58.x\" width=\"750\" height=\"844\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/02\/sm01-750x844.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/02\/sm01.jpg 1000w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/02\/sm02.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-374250\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/02\/sm02-750x844.jpg\" alt=\"SCANIA MEGAMOD v7.0 ETS2 1.58.x\" width=\"750\" height=\"844\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/02\/sm02-750x844.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/02\/sm02.jpg 1000w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p>THIS IS A LITE VERSION. ASK FOR FULL VERSION BY EMAIL.<br>\ncyrusthevirus2016@gmail.com<\/p><p>FULL version includes:<br>\nRigid chassis.<br>\nCar transport chassis.<br>\n8&times;4 chassis.<br>\nLohr car transport trailer.<br>\nBdf trailers (6 models).<br>\nLongline cabins.<br>\nTruck in trucks browser.<br>\nTrailers in freight market.<br>\nTrailers in trailers browser.<br>\nMetallic paint collection.<br>\nGet instructions. Send me an email.<br>\ncyrusthevirus2016@gmail.com<\/p><p>MOD PROTECTED BY CREATIVE COMMONS LICENSE V4.0.<br>\nhttps:\/\/creativecommons.org\/licenses\/by-nc-nd\/4.0\/<br>\nYOU CAN SHARE FREELY BUT ONLY USING THE ORIGINAL LINKS.<br>\nUPLOAD THE FILES TO OTHER SERVERS IS NOT PERMITTED.<\/p><p>YOUTUBE: https:\/\/www.youtube.com\/cyrusthevirus_mods SUBSCRIBE!<\/p><p>SUPPORT ME WITH A SMALL DONATION: www.paypal.me\/cyrusth3virus<\/p><p>SCANIA MEGAMOD v7.0 LITE.<\/p><p>Changes v7.0:<br>\nUpdated to 1.58.x.<br>\nCargos adapted to new SCS cargo system (again) (ONLY IN FULL VERSION).<br>\nNew cargo iron pipes for log trailer (ONLY IN FULL VERSION).<br>\nNew cargo icon for log cargo (ONLY IN FULL VERSION).<br>\nCargos adapted to latest DLC (ONLY IN FULL VERSION).<br>\nImproved locale files.<br>\nOther minor changes.<\/p><p>Changes v6.0:<br>\nUpdated to 1.55.x.<br>\nCargos adapted to new SCS cargo system (ONLY IN FULL VERSION).<br>\nImproved cargo icons (ONLY IN FULL VERSION).<br>\nFixed V8 seats logo.<br>\nFixed roof glass.<br>\nTrailers in freight market (ONLY IN FULL VERSION).<br>\nTrailers in trailers browser (ONLY IN FULL VERSION).<br>\nAdded new John Deere Gators cargo (ONLY IN FULL VERSION).<br>\nAdded new Lamborghini supercars cargo (ONLY IN FULL VERSION).<br>\nAdded new Ford Mustang cargo (ONLY IN FULL VERSION).<br>\nOther improves &amp; corrections.<br>\nCargos adapted to latest DLC (ONLY IN FULL VERSION).<br>\nOther lite changes.<br>\nA lot of chassis (few only with certain cabins\/engines).<br>\nA lot of cabins (few only with certains chassis).<br>\nSOME VARIANTS LIKE AUTO TRANSPORTER OR 8X4 CHASSIS ONLY AVAILABLE WITH CERTAIN ENGINES\/CABIN.<br>\nImproved compatibility with other mods.<br>\nDeleted innecesary files.<br>\nYou need SiS&rsquo;L megapack to have all the cabin accessories available.<\/p><p>Clean gamelog.<br>\nPlease inform about bugs\/errors. Thank you.<br>\ncyrusthevirus2016@gmail.com<\/p><p>Enjoy it. &#128578;<\/p><p>MOD PROTECTED BY CREATIVE COMMONS LICENSE V4.0.<br>\nhttps:\/\/creativecommons.org\/licenses\/by-nc-nd\/4.0\/<br>\nYOU CAN SHARE FREELY BUT ONLY USING THE ORIGINAL LINKS.<br>\nUPLOAD THE FILES TO OTHER SERVERS IS NOT PERMITTED.<\/p><p>Credits:<br>\nCyrusTheVirus, SCS Software, Playtruckcool, TheGreatJoe, Matgamer Chudy, Ahaneim, Fenix, Kosolap, VINZEL, RusPowErs, DankeHuj.<\/p><p><!--more--><\/p><p><strong><a href=\"https:\/\/modsfire.com\/s9i8Su2do9TGy0c\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 490.12 MB<\/strong><\/p><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"SCANIA MEGAMOD v6.0 ETS2 1.55.x (ETS2MOD)\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/mUweZ9OTcBk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>THIS IS A LITE VERSION. ASK FOR FULL VERSION BY EMAIL. cyrusthevirus2016@gmail.comFULL version includes: Rigid chassis. Car transport chassis. 8&times;4 chassis. Lohr car transport trailer. Bdf trailers (6 models). Longline cabins. Truck in trucks browser. Trailers in freight market. Trailers in trailers browser. Metallic paint collection. Get instructions. Send me an email. cyrusthevirus2016@gmail.comMOD PROTECTED BY [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3],"tags":[8858,8907],"class_list":["post-374251","post","type-post","status-publish","format-standard","hentry","category-trucks","tag-1-55","tag-1-58"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"THIS IS A LITE VERSION. ASK FOR FULL VERSION BY EMAIL. cyrusthevirus2016@gmail.com FULL version includes: Rigid chassis. Car transport chassis. 8\u00d74 chassis. Lohr car transport trailer. Bdf trailers (6 models). Longline cabins. Truck in trucks browser. Trailers in freight market. Trailers in trailers browser. Metallic paint collection. Get instructions. Send me an email. cyrusthevirus2016@gmail.com MOD\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/scania-megamod-v7-0-ets2-1-58-x\\\/#article\",\"name\":\"SCANIA MEGAMOD v7.0 ETS2 1.58.x | ETS 2 mods\",\"headline\":\"SCANIA MEGAMOD v7.0 ETS2 1.58.x\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/sm00.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/scania-megamod-v7-0-ets2-1-58-x\\\/#articleImage\",\"width\":1000,\"height\":1125},\"datePublished\":\"2026-02-21T18:53:16+02:00\",\"dateModified\":\"2026-02-21T18:53:16+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/scania-megamod-v7-0-ets2-1-58-x\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/scania-megamod-v7-0-ets2-1-58-x\\\/#webpage\"},\"articleSection\":\"Trucks, 1.55, 1.58\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/scania-megamod-v7-0-ets2-1-58-x\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"name\":\"Trucks\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"position\":2,\"name\":\"Trucks\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/scania-megamod-v7-0-ets2-1-58-x\\\/#listItem\",\"name\":\"SCANIA MEGAMOD v7.0 ETS2 1.58.x\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/scania-megamod-v7-0-ets2-1-58-x\\\/#listItem\",\"position\":3,\"name\":\"SCANIA MEGAMOD v7.0 ETS2 1.58.x\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"name\":\"Trucks\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/scania-megamod-v7-0-ets2-1-58-x\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/scania-megamod-v7-0-ets2-1-58-x\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/scania-megamod-v7-0-ets2-1-58-x\\\/\",\"name\":\"SCANIA MEGAMOD v7.0 ETS2 1.58.x | ETS 2 mods\",\"description\":\"THIS IS A LITE VERSION. ASK FOR FULL VERSION BY EMAIL. cyrusthevirus2016@gmail.com FULL version includes: Rigid chassis. Car transport chassis. 8\\u00d74 chassis. Lohr car transport trailer. Bdf trailers (6 models). Longline cabins. Truck in trucks browser. Trailers in freight market. Trailers in trailers browser. Metallic paint collection. Get instructions. Send me an email. cyrusthevirus2016@gmail.com MOD\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/scania-megamod-v7-0-ets2-1-58-x\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2026-02-21T18:53:16+02:00\",\"dateModified\":\"2026-02-21T18:53:16+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"SCANIA MEGAMOD v7.0 ETS2 1.58.x | ETS 2 mods","description":"THIS IS A LITE VERSION. ASK FOR FULL VERSION BY EMAIL. cyrusthevirus2016@gmail.com FULL version includes: Rigid chassis. Car transport chassis. 8\u00d74 chassis. Lohr car transport trailer. Bdf trailers (6 models). Longline cabins. Truck in trucks browser. Trailers in freight market. Trailers in trailers browser. Metallic paint collection. Get instructions. Send me an email. cyrusthevirus2016@gmail.com MOD","canonical_url":"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/#article","name":"SCANIA MEGAMOD v7.0 ETS2 1.58.x | ETS 2 mods","headline":"SCANIA MEGAMOD v7.0 ETS2 1.58.x","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/02\/sm00.jpg","@id":"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/#articleImage","width":1000,"height":1125},"datePublished":"2026-02-21T18:53:16+02:00","dateModified":"2026-02-21T18:53:16+02:00","inLanguage":"en-US","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/#webpage"},"articleSection":"Trucks, 1.55, 1.58"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","name":"Trucks"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","position":2,"name":"Trucks","item":"https:\/\/ets2.lt\/en\/category\/trucks\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/#listItem","name":"SCANIA MEGAMOD v7.0 ETS2 1.58.x"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/#listItem","position":3,"name":"SCANIA MEGAMOD v7.0 ETS2 1.58.x","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","name":"Trucks"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/#webpage","url":"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/","name":"SCANIA MEGAMOD v7.0 ETS2 1.58.x | ETS 2 mods","description":"THIS IS A LITE VERSION. ASK FOR FULL VERSION BY EMAIL. cyrusthevirus2016@gmail.com FULL version includes: Rigid chassis. Car transport chassis. 8\u00d74 chassis. Lohr car transport trailer. Bdf trailers (6 models). Longline cabins. Truck in trucks browser. Trailers in freight market. Trailers in trailers browser. Metallic paint collection. Get instructions. Send me an email. cyrusthevirus2016@gmail.com MOD","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2026-02-21T18:53:16+02:00","dateModified":"2026-02-21T18:53:16+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"374251","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-02-21 16:54:42","updated":"2026-02-21 16:54:42","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/trucks\/\" title=\"Trucks\">Trucks<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSCANIA MEGAMOD v7.0 ETS2 1.58.x\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Trucks","link":"https:\/\/ets2.lt\/en\/category\/trucks\/"},{"label":"SCANIA MEGAMOD v7.0 ETS2 1.58.x","link":"https:\/\/ets2.lt\/en\/scania-megamod-v7-0-ets2-1-58-x\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/374251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=374251"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/374251\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=374251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=374251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=374251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}