{"id":375425,"date":"2026-03-07T14:49:53","date_gmt":"2026-03-07T12:49:53","guid":{"rendered":"https:\/\/ets2.lt\/en\/?p=375425"},"modified":"2026-03-07T14:49:53","modified_gmt":"2026-03-07T12:49:53","slug":"noma-low-board-trailer-v1-4","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/","title":{"rendered":"Noma Low Board Trailer v1.4"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/noma-low-board-trailer-v1.4-ets2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-375424\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/noma-low-board-trailer-v1.4-ets2-1.jpg\" alt=\"Noma Low Board Trailer v1.4\" width=\"650\" height=\"365\"><\/a><\/p><p><!--fsp:slot:after-images--><\/p><p>&ndash; Standalone<br>\n&ndash; Sold at a mod dealer<br>\n&ndash; 6 different loads<br>\n&ndash; Cable support<\/p><p>Updated models\/materials for parts and wheels<\/p><p><!--fsp:slot:after-description--><\/p><p>Credits:<br>\nFACTOR<\/p><p><!--fsp:slot:after-credits--><\/p><p><!--more--><\/p><p><!--fsp:slot:before-download-links--><\/p><p><strong><a href=\"https:\/\/modsfire.com\/2I750h2Uoqm7h12\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 101 MB<\/strong><br>\n<!--fsp:slot:after-download-links--><\/p><p><!--fsp:slot:post-end--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&ndash; Standalone &ndash; Sold at a mod dealer &ndash; 6 different loads &ndash; Cable supportUpdated models\/materials for parts and wheelsCredits: FACTOR<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-375425","post","type-post","status-publish","format-standard","hentry","category-trailers"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"- Standalone \u2013 Sold at a mod dealer \u2013 6 different loads \u2013 Cable support Updated models\/materials for parts and wheels Credits: FACTOR DOWNLOAD 101 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/noma-low-board-trailer-v1-4\\\/#article\",\"name\":\"Noma Low Board Trailer v1.4 | ETS 2 mods\",\"headline\":\"Noma Low Board Trailer v1.4\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/noma-low-board-trailer-v1.4-ets2-1.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/noma-low-board-trailer-v1-4\\\/#articleImage\",\"width\":650,\"height\":365},\"datePublished\":\"2026-03-07T14:49:53+02:00\",\"dateModified\":\"2026-03-07T14:49:53+02:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/noma-low-board-trailer-v1-4\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/noma-low-board-trailer-v1-4\\\/#webpage\"},\"articleSection\":\"Trailers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/noma-low-board-trailer-v1-4\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trailers\\\/#listItem\",\"name\":\"Trailers\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trailers\\\/#listItem\",\"position\":2,\"name\":\"Trailers\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trailers\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/noma-low-board-trailer-v1-4\\\/#listItem\",\"name\":\"Noma Low Board Trailer v1.4\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/noma-low-board-trailer-v1-4\\\/#listItem\",\"position\":3,\"name\":\"Noma Low Board Trailer v1.4\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trailers\\\/#listItem\",\"name\":\"Trailers\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/noma-low-board-trailer-v1-4\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/noma-low-board-trailer-v1-4\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/noma-low-board-trailer-v1-4\\\/\",\"name\":\"Noma Low Board Trailer v1.4 | ETS 2 mods\",\"description\":\"- Standalone \\u2013 Sold at a mod dealer \\u2013 6 different loads \\u2013 Cable support Updated models\\\/materials for parts and wheels Credits: FACTOR DOWNLOAD 101 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/noma-low-board-trailer-v1-4\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2026-03-07T14:49:53+02:00\",\"dateModified\":\"2026-03-07T14:49:53+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Noma Low Board Trailer v1.4 | ETS 2 mods","description":"- Standalone \u2013 Sold at a mod dealer \u2013 6 different loads \u2013 Cable support Updated models\/materials for parts and wheels Credits: FACTOR DOWNLOAD 101 MB","canonical_url":"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/#article","name":"Noma Low Board Trailer v1.4 | ETS 2 mods","headline":"Noma Low Board Trailer v1.4","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/noma-low-board-trailer-v1.4-ets2-1.jpg","@id":"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/#articleImage","width":650,"height":365},"datePublished":"2026-03-07T14:49:53+02:00","dateModified":"2026-03-07T14:49:53+02:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/#webpage"},"articleSection":"Trailers"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trailers\/#listItem","name":"Trailers"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trailers\/#listItem","position":2,"name":"Trailers","item":"https:\/\/ets2.lt\/en\/category\/trailers\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/#listItem","name":"Noma Low Board Trailer v1.4"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/#listItem","position":3,"name":"Noma Low Board Trailer v1.4","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trailers\/#listItem","name":"Trailers"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/#webpage","url":"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/","name":"Noma Low Board Trailer v1.4 | ETS 2 mods","description":"- Standalone \u2013 Sold at a mod dealer \u2013 6 different loads \u2013 Cable support Updated models\/materials for parts and wheels Credits: FACTOR DOWNLOAD 101 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2026-03-07T14:49:53+02:00","dateModified":"2026-03-07T14:49:53+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"375425","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-03-07 12:50:34","updated":"2026-03-07 12:50:34","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/trailers\/\" title=\"Trailers\">Trailers<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNoma Low Board Trailer v1.4\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Trailers","link":"https:\/\/ets2.lt\/en\/category\/trailers\/"},{"label":"Noma Low Board Trailer v1.4","link":"https:\/\/ets2.lt\/en\/noma-low-board-trailer-v1-4\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/375425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=375425"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/375425\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=375425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=375425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=375425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}