{"id":375565,"date":"2026-03-09T07:49:19","date_gmt":"2026-03-09T05:49:19","guid":{"rendered":"https:\/\/ets2.lt\/en\/?p=375565"},"modified":"2026-03-09T07:49:19","modified_gmt":"2026-03-09T05:49:19","slug":"jm-group-logistic-project","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/","title":{"rendered":"JM GROUP LOGISTIC PROJECT"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/IMG_2393.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-375564\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/IMG_2393-750x758.jpeg\" alt=\"JM GROUP LOGISTIC PROJECT\" width=\"750\" height=\"758\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/IMG_2393-750x758.jpeg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/IMG_2393.jpeg 764w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><!--fsp:slot:after-images--><\/p><p>This project is a map that rework France, compatible with Sud de France map and Peyrat-le-Ch&acirc;teau map<\/p><p> &#9888;&#65039;PROMOD is required for the map to function correctly&#9888;&#65039;<\/p><p><!--fsp:slot:after-description--><\/p><p>Credits:<br>\nJM GROUP<\/p><p><!--fsp:slot:after-credits--><\/p><p><!--more--><\/p><p><!--fsp:slot:before-download-links--><\/p><p><strong><a href=\"https:\/\/sharemods.com\/tnp5jyf8tqul\/JM_Group_Logistique_1.scs.html\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 329.5 MB<\/strong><br>\n<strong><a href=\"https:\/\/sharemods.com\/hkh4vz4nwtbg\/JM_Group_Logistique_2.scs.html\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 764.8 MB [Part 2]<\/strong><br>\n<!--fsp:slot:after-download-links--><\/p><p><!--fsp:slot:post-end--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>This project is a map that rework France, compatible with Sud de France map and Peyrat-le-Ch&acirc;teau map &#9888;&#65039;PROMOD is required for the map to function correctly&#9888;&#65039;Credits: JM GROUP<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-375565","post","type-post","status-publish","format-standard","hentry","category-maps"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"This project is a map that rework France, compatible with Sud de France map and Peyrat-le-Ch\u00e2teau map \u26a0\ufe0fPROMOD is required for the map to function correctly\u26a0\ufe0f Credits: JM GROUP DOWNLOAD 329.5 MB DOWNLOAD 764.8 MB [Part 2]\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jm-group-logistic-project\\\/#article\",\"name\":\"JM GROUP LOGISTIC PROJECT | ETS 2 mods\",\"headline\":\"JM GROUP LOGISTIC PROJECT\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG_2393.jpeg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jm-group-logistic-project\\\/#articleImage\",\"width\":764,\"height\":772},\"datePublished\":\"2026-03-09T07:49:19+02:00\",\"dateModified\":\"2026-03-09T07:49:19+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jm-group-logistic-project\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jm-group-logistic-project\\\/#webpage\"},\"articleSection\":\"Maps\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jm-group-logistic-project\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/maps\\\/#listItem\",\"name\":\"Maps\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/maps\\\/#listItem\",\"position\":2,\"name\":\"Maps\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/maps\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jm-group-logistic-project\\\/#listItem\",\"name\":\"JM GROUP LOGISTIC PROJECT\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jm-group-logistic-project\\\/#listItem\",\"position\":3,\"name\":\"JM GROUP LOGISTIC PROJECT\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/maps\\\/#listItem\",\"name\":\"Maps\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jm-group-logistic-project\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jm-group-logistic-project\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jm-group-logistic-project\\\/\",\"name\":\"JM GROUP LOGISTIC PROJECT | ETS 2 mods\",\"description\":\"This project is a map that rework France, compatible with Sud de France map and Peyrat-le-Ch\\u00e2teau map \\u26a0\\ufe0fPROMOD is required for the map to function correctly\\u26a0\\ufe0f Credits: JM GROUP DOWNLOAD 329.5 MB DOWNLOAD 764.8 MB [Part 2]\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/jm-group-logistic-project\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2026-03-09T07:49:19+02:00\",\"dateModified\":\"2026-03-09T07:49:19+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"JM GROUP LOGISTIC PROJECT | ETS 2 mods","description":"This project is a map that rework France, compatible with Sud de France map and Peyrat-le-Ch\u00e2teau map \u26a0\ufe0fPROMOD is required for the map to function correctly\u26a0\ufe0f Credits: JM GROUP DOWNLOAD 329.5 MB DOWNLOAD 764.8 MB [Part 2]","canonical_url":"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/#article","name":"JM GROUP LOGISTIC PROJECT | ETS 2 mods","headline":"JM GROUP LOGISTIC PROJECT","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/IMG_2393.jpeg","@id":"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/#articleImage","width":764,"height":772},"datePublished":"2026-03-09T07:49:19+02:00","dateModified":"2026-03-09T07:49:19+02:00","inLanguage":"en-US","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/#webpage"},"articleSection":"Maps"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/maps\/#listItem","name":"Maps"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/maps\/#listItem","position":2,"name":"Maps","item":"https:\/\/ets2.lt\/en\/category\/maps\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/#listItem","name":"JM GROUP LOGISTIC PROJECT"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/#listItem","position":3,"name":"JM GROUP LOGISTIC PROJECT","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/maps\/#listItem","name":"Maps"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/#webpage","url":"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/","name":"JM GROUP LOGISTIC PROJECT | ETS 2 mods","description":"This project is a map that rework France, compatible with Sud de France map and Peyrat-le-Ch\u00e2teau map \u26a0\ufe0fPROMOD is required for the map to function correctly\u26a0\ufe0f Credits: JM GROUP DOWNLOAD 329.5 MB DOWNLOAD 764.8 MB [Part 2]","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2026-03-09T07:49:19+02:00","dateModified":"2026-03-09T07:49:19+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"375565","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-03-09 05:50:16","updated":"2026-03-09 05:50:16","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/maps\/\" title=\"Maps\">Maps<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tJM GROUP LOGISTIC PROJECT\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Maps","link":"https:\/\/ets2.lt\/en\/category\/maps\/"},{"label":"JM GROUP LOGISTIC PROJECT","link":"https:\/\/ets2.lt\/en\/jm-group-logistic-project\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/375565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=375565"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/375565\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=375565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=375565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=375565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}