{"id":375655,"date":"2026-03-10T07:49:44","date_gmt":"2026-03-10T05:49:44","guid":{"rendered":"https:\/\/ets2.lt\/en\/?p=375655"},"modified":"2026-03-10T07:49:44","modified_gmt":"2026-03-10T05:49:44","slug":"custom-gsrs-transport-yards","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/","title":{"rendered":"CUSTOM GSRS TRANSPORT YARDS"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_085229_00.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-375652\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_085229_00-750x422.webp\" alt=\"CUSTOM GSRS TRANSPORT YARDS\" width=\"750\" height=\"422\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_085229_00-750x422.webp 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_085229_00-1536x864.webp 1536w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_085229_00.webp 1920w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_084751_00.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-375653\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_084751_00-750x422.webp\" alt=\"CUSTOM GSRS TRANSPORT YARDS\" width=\"750\" height=\"422\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_084751_00-750x422.webp 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_084751_00-1536x864.webp 1536w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_084751_00.webp 1920w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_085251_00.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-375654\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_085251_00-750x422.jpg\" alt=\"CUSTOM GSRS TRANSPORT YARDS\" width=\"750\" height=\"422\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_085251_00-750x422.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_085251_00-1536x864.jpg 1536w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_085251_00.jpg 1920w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><!--fsp:slot:after-images--><\/p><p>GSRS TRANSPORT<br>\nWorkshop Yards v1.0 ETS2<\/p><p><!--fsp:slot:after-description--><\/p><p>Credits:<br>\nGSRS<\/p><p><!--fsp:slot:after-credits--><\/p><p><!--more--><\/p><p><!--fsp:slot:before-download-links--><\/p><p><strong><a href=\"https:\/\/modsfire.com\/eG2Fb3m2W50kw9V\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 109.68 MB<\/strong><br>\n<!--fsp:slot:after-download-links--><\/p><p><!--fsp:slot:post-end--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GSRS TRANSPORT Workshop Yards v1.0 ETS2Credits: GSRS<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-375655","post","type-post","status-publish","format-standard","hentry","category-maps"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"GSRS TRANSPORT Workshop Yards v1.0 ETS2 Credits: GSRS DOWNLOAD 109.68 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/custom-gsrs-transport-yards\\\/#article\",\"name\":\"CUSTOM GSRS TRANSPORT YARDS | ETS 2 mods\",\"headline\":\"CUSTOM GSRS TRANSPORT YARDS\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/ets2_20260310_085229_00.webp\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/custom-gsrs-transport-yards\\\/#articleImage\",\"width\":1920,\"height\":1080},\"datePublished\":\"2026-03-10T07:49:44+02:00\",\"dateModified\":\"2026-03-10T07:49:44+02:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/custom-gsrs-transport-yards\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/custom-gsrs-transport-yards\\\/#webpage\"},\"articleSection\":\"Maps\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/custom-gsrs-transport-yards\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/maps\\\/#listItem\",\"name\":\"Maps\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/maps\\\/#listItem\",\"position\":2,\"name\":\"Maps\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/maps\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/custom-gsrs-transport-yards\\\/#listItem\",\"name\":\"CUSTOM GSRS TRANSPORT YARDS\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/custom-gsrs-transport-yards\\\/#listItem\",\"position\":3,\"name\":\"CUSTOM GSRS TRANSPORT YARDS\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/maps\\\/#listItem\",\"name\":\"Maps\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/custom-gsrs-transport-yards\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/custom-gsrs-transport-yards\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/custom-gsrs-transport-yards\\\/\",\"name\":\"CUSTOM GSRS TRANSPORT YARDS | ETS 2 mods\",\"description\":\"GSRS TRANSPORT Workshop Yards v1.0 ETS2 Credits: GSRS DOWNLOAD 109.68 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/custom-gsrs-transport-yards\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2026-03-10T07:49:44+02:00\",\"dateModified\":\"2026-03-10T07:49:44+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"CUSTOM GSRS TRANSPORT YARDS | ETS 2 mods","description":"GSRS TRANSPORT Workshop Yards v1.0 ETS2 Credits: GSRS DOWNLOAD 109.68 MB","canonical_url":"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/#article","name":"CUSTOM GSRS TRANSPORT YARDS | ETS 2 mods","headline":"CUSTOM GSRS TRANSPORT YARDS","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/ets2_20260310_085229_00.webp","@id":"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/#articleImage","width":1920,"height":1080},"datePublished":"2026-03-10T07:49:44+02:00","dateModified":"2026-03-10T07:49:44+02:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/#webpage"},"articleSection":"Maps"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/maps\/#listItem","name":"Maps"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/maps\/#listItem","position":2,"name":"Maps","item":"https:\/\/ets2.lt\/en\/category\/maps\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/#listItem","name":"CUSTOM GSRS TRANSPORT YARDS"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/#listItem","position":3,"name":"CUSTOM GSRS TRANSPORT YARDS","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/maps\/#listItem","name":"Maps"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/#webpage","url":"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/","name":"CUSTOM GSRS TRANSPORT YARDS | ETS 2 mods","description":"GSRS TRANSPORT Workshop Yards v1.0 ETS2 Credits: GSRS DOWNLOAD 109.68 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2026-03-10T07:49:44+02:00","dateModified":"2026-03-10T07:49:44+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"375655","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-03-10 05:50:11","updated":"2026-03-10 05:50:11","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/maps\/\" title=\"Maps\">Maps<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCUSTOM GSRS TRANSPORT YARDS\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Maps","link":"https:\/\/ets2.lt\/en\/category\/maps\/"},{"label":"CUSTOM GSRS TRANSPORT YARDS","link":"https:\/\/ets2.lt\/en\/custom-gsrs-transport-yards\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/375655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=375655"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/375655\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=375655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=375655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=375655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}