{"id":375831,"date":"2026-03-13T17:28:41","date_gmt":"2026-03-13T15:28:41","guid":{"rendered":"https:\/\/ets2.lt\/en\/?p=375831"},"modified":"2026-03-13T17:28:41","modified_gmt":"2026-03-13T15:28:41","slug":"renault-d-wide","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/renault-d-wide\/","title":{"rendered":"Renault d-wide"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/20260313162527_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-375829\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/20260313162527_1-750x422.jpg\" alt=\"Renault d-wide\" width=\"750\" height=\"422\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/20260313162527_1-750x422.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/20260313162527_1-1536x864.jpg 1536w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/20260313162527_1.jpg 1920w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/20260313162551_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-375830\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/20260313162551_1-750x422.jpg\" alt=\"Renault d-wide\" width=\"750\" height=\"422\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/20260313162551_1-750x422.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/20260313162551_1-1536x864.jpg 1536w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/20260313162551_1.jpg 1920w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><!--fsp:slot:after-images--><\/p><p>Features:<br>\n&ndash; No FPS Drop<br>\n&ndash; AO Texture<br>\n&ndash; HQ Interior<br>\n&ndash; 1 Type Of interior<br>\n&ndash; Nightday, Sleeper cabins<br>\n&ndash; DTI8, DTI11 engines<br>\n&ndash; Compatible with Cabin Accessories<br>\n&ndash; Template for Paint Job<br>\n&ndash; 4&times;2, 4&times;2 Low deck, 4&times;2 Brazil Edition chassis<br>\n&ndash; And More<\/p><p><!--fsp:slot:after-description--><\/p><p>Credits:<br>\nZahed Truck<\/p><p><!--fsp:slot:after-credits--><\/p><p><!--more--><\/p><p><!--fsp:slot:before-download-links--><\/p><p><strong><a href=\"https:\/\/modsfire.com\/L7IlI8QL9IzA9s9\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 27 MB<\/strong><br>\n<!--fsp:slot:after-download-links--><\/p><p><!--fsp:slot:post-end--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Features: &ndash; No FPS Drop &ndash; AO Texture &ndash; HQ Interior &ndash; 1 Type Of interior &ndash; Nightday, Sleeper cabins &ndash; DTI8, DTI11 engines &ndash; Compatible with Cabin Accessories &ndash; Template for Paint Job &ndash; 4&times;2, 4&times;2 Low deck, 4&times;2 Brazil Edition chassis &ndash; And MoreCredits: Zahed Truck<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-375831","post","type-post","status-publish","format-standard","hentry","category-trucks"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Features: \u2013 No FPS Drop \u2013 AO Texture \u2013 HQ Interior \u2013 1 Type Of interior \u2013 Nightday, Sleeper cabins \u2013 DTI8, DTI11 engines - Compatible with Cabin Accessories - Template for Paint Job \u2013 4x2, 4x2 Low deck, 4x2 Brazil Edition chassis \u2013 And More Credits: Zahed Truck DOWNLOAD 27 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/renault-d-wide\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-d-wide\\\/#article\",\"name\":\"Renault d-wide | ETS 2 mods\",\"headline\":\"Renault d-wide\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260313162527_1.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-d-wide\\\/#articleImage\",\"width\":1920,\"height\":1080},\"datePublished\":\"2026-03-13T17:28:41+02:00\",\"dateModified\":\"2026-03-13T17:28:41+02:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-d-wide\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-d-wide\\\/#webpage\"},\"articleSection\":\"Trucks\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-d-wide\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"name\":\"Trucks\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"position\":2,\"name\":\"Trucks\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-d-wide\\\/#listItem\",\"name\":\"Renault d-wide\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-d-wide\\\/#listItem\",\"position\":3,\"name\":\"Renault d-wide\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"name\":\"Trucks\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-d-wide\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-d-wide\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-d-wide\\\/\",\"name\":\"Renault d-wide | ETS 2 mods\",\"description\":\"Features: \\u2013 No FPS Drop \\u2013 AO Texture \\u2013 HQ Interior \\u2013 1 Type Of interior \\u2013 Nightday, Sleeper cabins \\u2013 DTI8, DTI11 engines - Compatible with Cabin Accessories - Template for Paint Job \\u2013 4x2, 4x2 Low deck, 4x2 Brazil Edition chassis \\u2013 And More Credits: Zahed Truck DOWNLOAD 27 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-d-wide\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2026-03-13T17:28:41+02:00\",\"dateModified\":\"2026-03-13T17:28:41+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Renault d-wide | ETS 2 mods","description":"Features: \u2013 No FPS Drop \u2013 AO Texture \u2013 HQ Interior \u2013 1 Type Of interior \u2013 Nightday, Sleeper cabins \u2013 DTI8, DTI11 engines - Compatible with Cabin Accessories - Template for Paint Job \u2013 4x2, 4x2 Low deck, 4x2 Brazil Edition chassis \u2013 And More Credits: Zahed Truck DOWNLOAD 27 MB","canonical_url":"https:\/\/ets2.lt\/en\/renault-d-wide\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/renault-d-wide\/#article","name":"Renault d-wide | ETS 2 mods","headline":"Renault d-wide","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/20260313162527_1.jpg","@id":"https:\/\/ets2.lt\/en\/renault-d-wide\/#articleImage","width":1920,"height":1080},"datePublished":"2026-03-13T17:28:41+02:00","dateModified":"2026-03-13T17:28:41+02:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/renault-d-wide\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/renault-d-wide\/#webpage"},"articleSection":"Trucks"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/renault-d-wide\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","name":"Trucks"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","position":2,"name":"Trucks","item":"https:\/\/ets2.lt\/en\/category\/trucks\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/renault-d-wide\/#listItem","name":"Renault d-wide"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/renault-d-wide\/#listItem","position":3,"name":"Renault d-wide","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","name":"Trucks"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/renault-d-wide\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/renault-d-wide\/#webpage","url":"https:\/\/ets2.lt\/en\/renault-d-wide\/","name":"Renault d-wide | ETS 2 mods","description":"Features: \u2013 No FPS Drop \u2013 AO Texture \u2013 HQ Interior \u2013 1 Type Of interior \u2013 Nightday, Sleeper cabins \u2013 DTI8, DTI11 engines - Compatible with Cabin Accessories - Template for Paint Job \u2013 4x2, 4x2 Low deck, 4x2 Brazil Edition chassis \u2013 And More Credits: Zahed Truck DOWNLOAD 27 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/renault-d-wide\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2026-03-13T17:28:41+02:00","dateModified":"2026-03-13T17:28:41+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"375831","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-03-13 15:30:53","updated":"2026-03-13 15:30:53","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/trucks\/\" title=\"Trucks\">Trucks<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRenault d-wide\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Trucks","link":"https:\/\/ets2.lt\/en\/category\/trucks\/"},{"label":"Renault d-wide","link":"https:\/\/ets2.lt\/en\/renault-d-wide\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/375831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=375831"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/375831\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=375831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=375831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=375831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}