{"id":376416,"date":"2026-03-23T13:47:14","date_gmt":"2026-03-23T11:47:14","guid":{"rendered":"https:\/\/ets2.lt\/en\/?p=376416"},"modified":"2026-03-23T13:47:14","modified_gmt":"2026-03-23T11:47:14","slug":"bussbygg-euromax-v1-4","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/","title":{"rendered":"Bussbygg Euromax v1.4"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/bussbygg-euromax-v1.4-ets2-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-376414\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/bussbygg-euromax-v1.4-ets2-2-750x422.jpg\" alt=\"Bussbygg Euromax v1.4\" width=\"750\" height=\"422\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/bussbygg-euromax-v1.4-ets2-2-750x422.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/bussbygg-euromax-v1.4-ets2-2.jpg 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/bussbygg-euromax-v1.4-ets2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-376415\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/bussbygg-euromax-v1.4-ets2-1-750x422.jpg\" alt=\"Bussbygg Euromax v1.4\" width=\"750\" height=\"422\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/bussbygg-euromax-v1.4-ets2-1-750x422.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/bussbygg-euromax-v1.4-ets2-1.jpg 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><!--fsp:slot:after-images--><\/p><p>Ownable<br>\nChoice between single trailer and dolly version<br>\n2 chassis types (normal and spread axles)<br>\n2 sideskirt types<br>\n2 types of taillights (orange and white blinkers)<br>\n3 types of rims (chrome, half white\/half paint &amp; painted)<br>\nOwn Custom wheels, hubs, nuts, tires<br>\nSkin template and XML for Mods Studio 2<br>\n14 skins included<br>\nTemplate for Skins (XML+DDS)<\/p><p>Tested on game version 1.58<\/p><p><!--fsp:slot:after-description--><\/p><p>Credits:<br>\nBKC<\/p><p><!--fsp:slot:after-credits--><\/p><p><!--more--><\/p><p><!--fsp:slot:before-download-links--><\/p><p><strong><a href=\"https:\/\/modsfire.com\/YWP9NZgv4Sjw9T6\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 81 MB<\/strong><br>\n<!--fsp:slot:after-download-links--><\/p><p><!--fsp:slot:post-end--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ownable Choice between single trailer and dolly version 2 chassis types (normal and spread axles) 2 sideskirt types 2 types of taillights (orange and white blinkers) 3 types of rims (chrome, half white\/half paint &amp; painted) Own Custom wheels, hubs, nuts, tires Skin template and XML for Mods Studio 2 14 skins included Template for [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[4],"tags":[8907],"class_list":["post-376416","post","type-post","status-publish","format-standard","hentry","category-trailers","tag-1-58"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ownable Choice between single trailer and dolly version 2 chassis types (normal and spread axles) 2 sideskirt types 2 types of taillights (orange and white blinkers) 3 types of rims (chrome, half white\/half paint &amp; painted) Own Custom wheels, hubs, nuts, tires Skin template and XML for Mods Studio 2 14 skins included Template for\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bussbygg-euromax-v1-4\\\/#article\",\"name\":\"Bussbygg Euromax v1.4 | ETS 2 mods\",\"headline\":\"Bussbygg Euromax v1.4\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/bussbygg-euromax-v1.4-ets2-2.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bussbygg-euromax-v1-4\\\/#articleImage\",\"width\":1280,\"height\":720},\"datePublished\":\"2026-03-23T13:47:14+02:00\",\"dateModified\":\"2026-03-23T13:47:14+02:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bussbygg-euromax-v1-4\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bussbygg-euromax-v1-4\\\/#webpage\"},\"articleSection\":\"Trailers, 1.58\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bussbygg-euromax-v1-4\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trailers\\\/#listItem\",\"name\":\"Trailers\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trailers\\\/#listItem\",\"position\":2,\"name\":\"Trailers\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trailers\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bussbygg-euromax-v1-4\\\/#listItem\",\"name\":\"Bussbygg Euromax v1.4\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bussbygg-euromax-v1-4\\\/#listItem\",\"position\":3,\"name\":\"Bussbygg Euromax v1.4\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trailers\\\/#listItem\",\"name\":\"Trailers\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bussbygg-euromax-v1-4\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bussbygg-euromax-v1-4\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bussbygg-euromax-v1-4\\\/\",\"name\":\"Bussbygg Euromax v1.4 | ETS 2 mods\",\"description\":\"Ownable Choice between single trailer and dolly version 2 chassis types (normal and spread axles) 2 sideskirt types 2 types of taillights (orange and white blinkers) 3 types of rims (chrome, half white\\\/half paint & painted) Own Custom wheels, hubs, nuts, tires Skin template and XML for Mods Studio 2 14 skins included Template for\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/bussbygg-euromax-v1-4\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2026-03-23T13:47:14+02:00\",\"dateModified\":\"2026-03-23T13:47:14+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Bussbygg Euromax v1.4 | ETS 2 mods","description":"Ownable Choice between single trailer and dolly version 2 chassis types (normal and spread axles) 2 sideskirt types 2 types of taillights (orange and white blinkers) 3 types of rims (chrome, half white\/half paint & painted) Own Custom wheels, hubs, nuts, tires Skin template and XML for Mods Studio 2 14 skins included Template for","canonical_url":"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/#article","name":"Bussbygg Euromax v1.4 | ETS 2 mods","headline":"Bussbygg Euromax v1.4","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/bussbygg-euromax-v1.4-ets2-2.jpg","@id":"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/#articleImage","width":1280,"height":720},"datePublished":"2026-03-23T13:47:14+02:00","dateModified":"2026-03-23T13:47:14+02:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/#webpage"},"articleSection":"Trailers, 1.58"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trailers\/#listItem","name":"Trailers"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trailers\/#listItem","position":2,"name":"Trailers","item":"https:\/\/ets2.lt\/en\/category\/trailers\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/#listItem","name":"Bussbygg Euromax v1.4"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/#listItem","position":3,"name":"Bussbygg Euromax v1.4","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trailers\/#listItem","name":"Trailers"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/#webpage","url":"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/","name":"Bussbygg Euromax v1.4 | ETS 2 mods","description":"Ownable Choice between single trailer and dolly version 2 chassis types (normal and spread axles) 2 sideskirt types 2 types of taillights (orange and white blinkers) 3 types of rims (chrome, half white\/half paint & painted) Own Custom wheels, hubs, nuts, tires Skin template and XML for Mods Studio 2 14 skins included Template for","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2026-03-23T13:47:14+02:00","dateModified":"2026-03-23T13:47:14+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"376416","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-03-23 11:47:30","updated":"2026-03-23 11:47:30","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/trailers\/\" title=\"Trailers\">Trailers<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBussbygg Euromax v1.4\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Trailers","link":"https:\/\/ets2.lt\/en\/category\/trailers\/"},{"label":"Bussbygg Euromax v1.4","link":"https:\/\/ets2.lt\/en\/bussbygg-euromax-v1-4\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/376416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=376416"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/376416\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=376416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=376416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=376416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}