{"id":376612,"date":"2026-03-26T19:02:46","date_gmt":"2026-03-26T17:02:46","guid":{"rendered":"https:\/\/ets2.lt\/en\/?p=376612"},"modified":"2026-03-26T19:02:46","modified_gmt":"2026-03-26T17:02:46","slug":"daf-xf95-euro-3-v1-58","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/","title":{"rendered":"DAF XF95 Euro 3 v1.58"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/daf-xf95-euro-3-v4.0-ets2-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-376610\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/daf-xf95-euro-3-v4.0-ets2-3-750x422.jpg\" alt=\"DAF XF95 Euro 3 v1.58\" width=\"750\" height=\"422\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/daf-xf95-euro-3-v4.0-ets2-3-750x422.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/daf-xf95-euro-3-v4.0-ets2-3.jpg 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/daf-xf95-euro-3-v4.0-ets2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-376611\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/daf-xf95-euro-3-v4.0-ets2-1-750x422.jpg\" alt=\"DAF XF95 Euro 3 v1.58\" width=\"750\" height=\"422\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/daf-xf95-euro-3-v4.0-ets2-1-750x422.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/daf-xf95-euro-3-v4.0-ets2-1.jpg 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><!--fsp:slot:after-images--><\/p><p>&ndash; 2 cabins<br>\n&ndash; 4 chassis<br>\n&ndash; Paccar MX 265\/375<br>\n&ndash; 12-speed gearbox + retarder<br>\n&ndash; Original interior with Sony GPS slide-out display<br>\n&ndash; Mudguards<br>\n&ndash; 2 side body kits<br>\n&ndash; 2 bumpers<br>\n&ndash; 3 grils<\/p><p>Game version 1.58<\/p><p><!--fsp:slot:after-description--><\/p><p>Credits:<br>\nAndrii<\/p><p><!--fsp:slot:after-credits--><\/p><p><!--more--><\/p><p><!--fsp:slot:before-download-links--><\/p><p><strong><a href=\"https:\/\/mods.to\/394p69c5662870f0d\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 471 MB<\/strong><br>\n<!--fsp:slot:after-download-links--><\/p><p><!--fsp:slot:post-end--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&ndash; 2 cabins &ndash; 4 chassis &ndash; Paccar MX 265\/375 &ndash; 12-speed gearbox + retarder &ndash; Original interior with Sony GPS slide-out display &ndash; Mudguards &ndash; 2 side body kits &ndash; 2 bumpers &ndash; 3 grilsGame version 1.58Credits: Andrii<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3],"tags":[8907],"class_list":["post-376612","post","type-post","status-publish","format-standard","hentry","category-trucks","tag-1-58"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u2013 2 cabins \u2013 4 chassis \u2013 Paccar MX 265\/375 \u2013 12-speed gearbox + retarder \u2013 Original interior with Sony GPS slide-out display \u2013 Mudguards \u2013 2 side body kits \u2013 2 bumpers \u2013 3 grils Game version 1.58 Credits: Andrii DOWNLOAD 471 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/daf-xf95-euro-3-v1-58\\\/#article\",\"name\":\"DAF XF95 Euro 3 v1.58 | ETS 2 mods\",\"headline\":\"DAF XF95 Euro 3 v1.58\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/daff95-euro-3-v4.0-ets2-3.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/daf-xf95-euro-3-v1-58\\\/#articleImage\"},\"datePublished\":\"2026-03-26T19:02:46+02:00\",\"dateModified\":\"2026-03-26T19:02:46+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/daf-xf95-euro-3-v1-58\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/daf-xf95-euro-3-v1-58\\\/#webpage\"},\"articleSection\":\"Trucks, 1.58\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/daf-xf95-euro-3-v1-58\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"name\":\"Trucks\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"position\":2,\"name\":\"Trucks\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/daf-xf95-euro-3-v1-58\\\/#listItem\",\"name\":\"DAF XF95 Euro 3 v1.58\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/daf-xf95-euro-3-v1-58\\\/#listItem\",\"position\":3,\"name\":\"DAF XF95 Euro 3 v1.58\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"name\":\"Trucks\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/daf-xf95-euro-3-v1-58\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/daf-xf95-euro-3-v1-58\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/daf-xf95-euro-3-v1-58\\\/\",\"name\":\"DAF XF95 Euro 3 v1.58 | ETS 2 mods\",\"description\":\"\\u2013 2 cabins \\u2013 4 chassis \\u2013 Paccar MX 265\\\/375 \\u2013 12-speed gearbox + retarder \\u2013 Original interior with Sony GPS slide-out display \\u2013 Mudguards \\u2013 2 side body kits \\u2013 2 bumpers \\u2013 3 grils Game version 1.58 Credits: Andrii DOWNLOAD 471 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/daf-xf95-euro-3-v1-58\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2026-03-26T19:02:46+02:00\",\"dateModified\":\"2026-03-26T19:02:46+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"DAF XF95 Euro 3 v1.58 | ETS 2 mods","description":"\u2013 2 cabins \u2013 4 chassis \u2013 Paccar MX 265\/375 \u2013 12-speed gearbox + retarder \u2013 Original interior with Sony GPS slide-out display \u2013 Mudguards \u2013 2 side body kits \u2013 2 bumpers \u2013 3 grils Game version 1.58 Credits: Andrii DOWNLOAD 471 MB","canonical_url":"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/#article","name":"DAF XF95 Euro 3 v1.58 | ETS 2 mods","headline":"DAF XF95 Euro 3 v1.58","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/daff95-euro-3-v4.0-ets2-3.jpg","@id":"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/#articleImage"},"datePublished":"2026-03-26T19:02:46+02:00","dateModified":"2026-03-26T19:02:46+02:00","inLanguage":"en-US","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/#webpage"},"articleSection":"Trucks, 1.58"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","name":"Trucks"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","position":2,"name":"Trucks","item":"https:\/\/ets2.lt\/en\/category\/trucks\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/#listItem","name":"DAF XF95 Euro 3 v1.58"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/#listItem","position":3,"name":"DAF XF95 Euro 3 v1.58","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","name":"Trucks"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/#webpage","url":"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/","name":"DAF XF95 Euro 3 v1.58 | ETS 2 mods","description":"\u2013 2 cabins \u2013 4 chassis \u2013 Paccar MX 265\/375 \u2013 12-speed gearbox + retarder \u2013 Original interior with Sony GPS slide-out display \u2013 Mudguards \u2013 2 side body kits \u2013 2 bumpers \u2013 3 grils Game version 1.58 Credits: Andrii DOWNLOAD 471 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2026-03-26T19:02:46+02:00","dateModified":"2026-03-26T19:02:46+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"376612","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-03-26 17:03:10","updated":"2026-03-26 17:03:10","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/trucks\/\" title=\"Trucks\">Trucks<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDAF XF95 Euro 3 v1.58\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Trucks","link":"https:\/\/ets2.lt\/en\/category\/trucks\/"},{"label":"DAF XF95 Euro 3 v1.58","link":"https:\/\/ets2.lt\/en\/daf-xf95-euro-3-v1-58\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/376612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=376612"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/376612\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=376612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=376612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=376612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}