{"id":376792,"date":"2026-03-29T08:03:11","date_gmt":"2026-03-29T06:03:11","guid":{"rendered":"https:\/\/ets2.lt\/en\/?p=376792"},"modified":"2026-03-29T08:03:11","modified_gmt":"2026-03-29T06:03:11","slug":"map-narogong-raya-v3-save-game-profile-ets2-1-58","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/","title":{"rendered":"Map Narogong Raya v3 Save Game Profile ETS2 1.58"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/1750175313_narogong-raya-map-ets2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-376791\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/1750175313_narogong-raya-map-ets2-750x422.jpg\" alt=\"Map Narogong Raya v3 Save Game Profile ETS2 1.58\" width=\"750\" height=\"422\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/1750175313_narogong-raya-map-ets2-750x422.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/1750175313_narogong-raya-map-ets2.jpg 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><!--fsp:slot:after-images--><\/p><p>Here you have a Save Profile for Map Narogong Raya v3<\/p><p>&ndash; Money<br>\n&ndash; All skills<br>\n&ndash; Garages<br>\n&ndash; All Truck dealers<br>\n&ndash; Level 75<br>\n&ndash; All cities discovered<\/p><p><!--fsp:slot:after-description--><\/p><p>Credits:<br>\npixell<\/p><p><!--fsp:slot:after-credits--><\/p><p><!--more--><\/p><p><!--fsp:slot:before-download-links--><\/p><p><strong><a href=\"https:\/\/sharemods.com\/0sfitnvbxtb7\/Map_Narogong_Raya_Map_Save_Profile_Download.rar.html\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 656 KB<\/strong><br>\n<!--fsp:slot:after-download-links--><\/p><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"ETS2 1.58 New Map - Challenging Narrow Roads Driving\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/vuC_uuL7qZc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><p><!--fsp:slot:post-end--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Here you have a Save Profile for Map Narogong Raya v3&ndash; Money &ndash; All skills &ndash; Garages &ndash; All Truck dealers &ndash; Level 75 &ndash; All cities discoveredCredits: pixell<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[6],"tags":[8907],"class_list":["post-376792","post","type-post","status-publish","format-standard","hentry","category-other-mods","tag-1-58"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Here you have a Save Profile for Map Narogong Raya v3 \u2013 Money \u2013 All skills \u2013 Garages \u2013 All Truck dealers \u2013 Level 75 \u2013 All cities discovered Credits: pixell DOWNLOAD 656 KB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/map-narogong-raya-v3-save-game-profile-ets2-1-58\\\/#article\",\"name\":\"Map Narogong Raya v3 Save Game Profile ETS2 1.58 | ETS 2 mods\",\"headline\":\"Map Narogong Raya v3 Save Game Profile ETS2 1.58\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/1750175313_narogong-raya-map-ets2.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/map-narogong-raya-v3-save-game-profile-ets2-1-58\\\/#articleImage\",\"width\":1280,\"height\":720},\"datePublished\":\"2026-03-29T08:03:11+02:00\",\"dateModified\":\"2026-03-29T08:03:11+02:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/map-narogong-raya-v3-save-game-profile-ets2-1-58\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/map-narogong-raya-v3-save-game-profile-ets2-1-58\\\/#webpage\"},\"articleSection\":\"Others, 1.58\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/map-narogong-raya-v3-save-game-profile-ets2-1-58\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"position\":2,\"name\":\"Others\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/map-narogong-raya-v3-save-game-profile-ets2-1-58\\\/#listItem\",\"name\":\"Map Narogong Raya v3 Save Game Profile ETS2 1.58\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/map-narogong-raya-v3-save-game-profile-ets2-1-58\\\/#listItem\",\"position\":3,\"name\":\"Map Narogong Raya v3 Save Game Profile ETS2 1.58\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/map-narogong-raya-v3-save-game-profile-ets2-1-58\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/map-narogong-raya-v3-save-game-profile-ets2-1-58\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/map-narogong-raya-v3-save-game-profile-ets2-1-58\\\/\",\"name\":\"Map Narogong Raya v3 Save Game Profile ETS2 1.58 | ETS 2 mods\",\"description\":\"Here you have a Save Profile for Map Narogong Raya v3 \\u2013 Money \\u2013 All skills \\u2013 Garages \\u2013 All Truck dealers \\u2013 Level 75 \\u2013 All cities discovered Credits: pixell DOWNLOAD 656 KB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/map-narogong-raya-v3-save-game-profile-ets2-1-58\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2026-03-29T08:03:11+02:00\",\"dateModified\":\"2026-03-29T08:03:11+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Map Narogong Raya v3 Save Game Profile ETS2 1.58 | ETS 2 mods","description":"Here you have a Save Profile for Map Narogong Raya v3 \u2013 Money \u2013 All skills \u2013 Garages \u2013 All Truck dealers \u2013 Level 75 \u2013 All cities discovered Credits: pixell DOWNLOAD 656 KB","canonical_url":"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/#article","name":"Map Narogong Raya v3 Save Game Profile ETS2 1.58 | ETS 2 mods","headline":"Map Narogong Raya v3 Save Game Profile ETS2 1.58","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/03\/1750175313_narogong-raya-map-ets2.jpg","@id":"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/#articleImage","width":1280,"height":720},"datePublished":"2026-03-29T08:03:11+02:00","dateModified":"2026-03-29T08:03:11+02:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/#webpage"},"articleSection":"Others, 1.58"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","position":2,"name":"Others","item":"https:\/\/ets2.lt\/en\/category\/other-mods\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/#listItem","name":"Map Narogong Raya v3 Save Game Profile ETS2 1.58"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/#listItem","position":3,"name":"Map Narogong Raya v3 Save Game Profile ETS2 1.58","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/#webpage","url":"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/","name":"Map Narogong Raya v3 Save Game Profile ETS2 1.58 | ETS 2 mods","description":"Here you have a Save Profile for Map Narogong Raya v3 \u2013 Money \u2013 All skills \u2013 Garages \u2013 All Truck dealers \u2013 Level 75 \u2013 All cities discovered Credits: pixell DOWNLOAD 656 KB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2026-03-29T08:03:11+02:00","dateModified":"2026-03-29T08:03:11+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"376792","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-03-29 06:05:31","updated":"2026-03-29 06:05:31","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/other-mods\/\" title=\"Others\">Others<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMap Narogong Raya v3 Save Game Profile ETS2 1.58\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Others","link":"https:\/\/ets2.lt\/en\/category\/other-mods\/"},{"label":"Map Narogong Raya v3 Save Game Profile ETS2 1.58","link":"https:\/\/ets2.lt\/en\/map-narogong-raya-v3-save-game-profile-ets2-1-58\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/376792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=376792"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/376792\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=376792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=376792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=376792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}