{"id":377072,"date":"2026-04-01T11:59:49","date_gmt":"2026-04-01T09:59:49","guid":{"rendered":"https:\/\/ets2.lt\/en\/?p=377072"},"modified":"2026-04-01T11:59:49","modified_gmt":"2026-04-01T09:59:49","slug":"mod-led-eyes-v2-0","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/","title":{"rendered":"Mod LED Eyes V2.0"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/Untitled-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-377069\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/Untitled-1.jpg\" alt=\"Mod LED Eyes V2.0\" width=\"640\" height=\"360\"><\/a><\/p><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/ets2_20250124_045459_00.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-377070\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/ets2_20250124_045459_00-750x600.webp\" alt=\"Mod LED Eyes V2.0\" width=\"750\" height=\"600\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/ets2_20250124_045459_00-750x600.webp 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/ets2_20250124_045459_00.webp 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/ets2_20250124_045924_00.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-377071\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/ets2_20250124_045924_00-750x600.webp\" alt=\"Mod LED Eyes V2.0\" width=\"750\" height=\"600\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/ets2_20250124_045924_00-750x600.webp 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/ets2_20250124_045924_00.webp 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><!--fsp:slot:after-images--><\/p><p>Mod LED Eyes v2.0<\/p><p>Mod Parts:<br>\nBrown Eyes<br>\nDevil Eyes<br>\nDragon Eyes<br>\nSnake Eyes<br>\nRed Eyes<\/p><p>Hello guys,<\/p><p>HOW TO USE :<\/p><p>1) Start the singleplayer game, open the MOD manager and enable the mod<br>\n2) Chose your truck<br>\n3) Press E &amp; Enjoy<\/p><p>I Hope You Like My Works<\/p><p>Thank You *_-<\/p><p><!--fsp:slot:after-description--><\/p><p>Credits:<br>\nCredit By OkShiNo<\/p><p><!--fsp:slot:after-credits--><\/p><p><!--more--><\/p><p><!--fsp:slot:before-download-links--><\/p><p><strong><a href=\"https:\/\/cloudfirepro.com\/8qw1zedZ3Xyn\/file\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 544.31 KB<\/strong><br>\n<!--fsp:slot:after-download-links--><\/p><p class=\"fsp-discord-link\"><a href=\"https:\/\/discord.com\/invite\/Tbw2UhY3uA\" target=\"_blank\" rel=\"noopener ugc nofollow\" class=\"btn-info btn-info--discord\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-discord\" viewbox=\"0 0 16 16\">\r\n  <path d=\"M13.545 2.907a13.2 13.2 0 0 0-3.257-1.011.05.05 0 0 0-.052.025c-.141.25-.297.577-.406.833a12.2 12.2 0 0 0-3.658 0 8 8 0 0 0-.412-.833.05.05 0 0 0-.052-.025c-1.125.194-2.22.534-3.257 1.011a.04.04 0 0 0-.021.018C.356 6.024-.213 9.047.066 12.032q.003.022.021.037a13.3 13.3 0 0 0 3.995 2.02.05.05 0 0 0 .056-.019q.463-.63.818-1.329a.05.05 0 0 0-.01-.059l-.018-.011a9 9 0 0 1-1.248-.595.05.05 0 0 1-.02-.066l.015-.019q.127-.095.248-.195a.05.05 0 0 1 .051-.007c2.619 1.196 5.454 1.196 8.041 0a.05.05 0 0 1 .053.007q.121.1.248.195a.05.05 0 0 1-.004.085 8 8 0 0 1-1.249.594.05.05 0 0 0-.03.03.05.05 0 0 0 .003.041c.24.465.515.909.817 1.329a.05.05 0 0 0 .056.019 13.2 13.2 0 0 0 4.001-2.02.05.05 0 0 0 .021-.037c.334-3.451-.559-6.449-2.366-9.106a.03.03 0 0 0-.02-.019m-8.198 7.307c-.789 0-1.438-.724-1.438-1.612s.637-1.613 1.438-1.613c.807 0 1.45.73 1.438 1.613 0 .888-.637 1.612-1.438 1.612m5.316 0c-.788 0-1.438-.724-1.438-1.612s.637-1.613 1.438-1.613c.807 0 1.451.73 1.438 1.613 0 .888-.631 1.612-1.438 1.612\"><\/path>\r\n<\/svg><span>Join Discord Server<\/span><\/a>\n<\/p><div class=\"fsp-donation-buttons\"><a href=\"https:\/\/www.paypal.com\/paypalme\/OkShiNo\" target=\"_blank\" rel=\"noopener ugc nofollow\" class=\"btn-info btn-info--paypal\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"16\" fill=\"currentColor\" class=\"bi bi-paypal\" viewbox=\"0 0 16 16\">\r\n  <path d=\"M14.06 3.713c.12-1.071-.093-1.832-.702-2.526C12.628.356 11.312 0 9.626 0H4.734a.7.7 0 0 0-.691.59L2.005 13.509a.42.42 0 0 0 .415.486h2.756l-.202 1.28a.628.628 0 0 0 .62.726H8.14c.429 0 .793-.31.862-.731l.025-.13.48-3.043.03-.164.001-.007a.35.35 0 0 1 .348-.297h.38c1.266 0 2.425-.256 3.345-.91q.57-.403.993-1.005a4.94 4.94 0 0 0 .88-2.195c.242-1.246.13-2.356-.57-3.154a2.7 2.7 0 0 0-.76-.59l-.094-.061ZM6.543 8.82a.7.7 0 0 1 .321-.079H8.3c2.82 0 5.027-1.144 5.672-4.456l.003-.016q.326.186.548.438c.546.623.679 1.535.45 2.71-.272 1.397-.866 2.307-1.663 2.874-.802.57-1.842.815-3.043.815h-.38a.87.87 0 0 0-.863.734l-.03.164-.48 3.043-.024.13-.001.004a.35.35 0 0 1-.348.296H5.595a.106.106 0 0 1-.105-.123l.208-1.32z\"><\/path>\r\n<\/svg><span>Donate via PayPal<\/span><\/a><\/div><div class=\"video-wrapper\"><iframe loading=\"lazy\" title=\"&#1588;&#1585;&#1581; &#1605;&#1608;&#1583; &#1575;&#1604;&#1593;&#1610;&#1608;&#1606; &#1604;&#1580;&#1605;&#1610;&#1593; &#1575;&#1604;&#1588;&#1575;&#1581;&#1606;&#1575;&#1578; &#1575;&#1608;&#1606;&#1604;&#1575;&#1610;&#1606; &#1608;&#1591;&#1585;&#1610;&#1602;&#1577; &#1578;&#1581;&#1605;&#1610;&#1604;&#1607; &#1608;&#1578;&#1585;&#1603;&#1610;&#1576;&#1607; &#1576;&#1575;&#1604;&#1603;&#1575;&#1605;&#1604; &#128076;&#127995;&#128293; | &#1605;&#1581;&#1575;&#1603;&#1609; &#1575;&#1604;&#1588;&#1575;&#1581;&#1606;&#1575;&#1578; &#1575;&#1604;&#1575;&#1608;&#1585;&#1608;&#1576;&#1610;&#1607; 2\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/qRLwlbzq6xM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><p><!--fsp:slot:post-end--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mod LED Eyes v2.0Mod Parts: Brown Eyes Devil Eyes Dragon Eyes Snake Eyes Red EyesHello guys,HOW TO USE :1) Start the singleplayer game, open the MOD manager and enable the mod 2) Chose your truck 3) Press E &amp; EnjoyI Hope You Like My WorksThank You *_-Credits: Credit By OkShiNo<\/p>\n","protected":false},"author":199755,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-377072","post","type-post","status-publish","format-standard","hentry","category-detalestiuningas"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Mod LED Eyes v2.0 Mod Parts: Brown Eyes Devil Eyes Dragon Eyes Snake Eyes Red Eyes Hello guys, HOW TO USE : 1) Start the singleplayer game, open the MOD manager and enable the mod 2) Chose your truck 3) Press E &amp; Enjoy I Hope You Like My Works Thank You *_- Credits: Credit\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"OkShiNoTV\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mod-led-eyes-v2-0\\\/#article\",\"name\":\"Mod LED Eyes V2.0 | ETS 2 mods\",\"headline\":\"Mod LED Eyes V2.0\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/okshinotv\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Untitled-1.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mod-led-eyes-v2-0\\\/#articleImage\",\"width\":640,\"height\":360},\"datePublished\":\"2026-04-01T11:59:49+02:00\",\"dateModified\":\"2026-04-01T11:59:49+02:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mod-led-eyes-v2-0\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mod-led-eyes-v2-0\\\/#webpage\"},\"articleSection\":\"Parts\\\/Tuning\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mod-led-eyes-v2-0\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"name\":\"Parts\\\/Tuning\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"position\":2,\"name\":\"Parts\\\/Tuning\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mod-led-eyes-v2-0\\\/#listItem\",\"name\":\"Mod LED Eyes V2.0\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mod-led-eyes-v2-0\\\/#listItem\",\"position\":3,\"name\":\"Mod LED Eyes V2.0\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"name\":\"Parts\\\/Tuning\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/okshinotv\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/okshinotv\\\/\",\"name\":\"OkShiNoTV\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mod-led-eyes-v2-0\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/21058b11e2610a52b9748c0c8723816d844cc0a7436220da9cd8e5f0382614ba?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"OkShiNoTV\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mod-led-eyes-v2-0\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mod-led-eyes-v2-0\\\/\",\"name\":\"Mod LED Eyes V2.0 | ETS 2 mods\",\"description\":\"Mod LED Eyes v2.0 Mod Parts: Brown Eyes Devil Eyes Dragon Eyes Snake Eyes Red Eyes Hello guys, HOW TO USE : 1) Start the singleplayer game, open the MOD manager and enable the mod 2) Chose your truck 3) Press E & Enjoy I Hope You Like My Works Thank You *_- Credits: Credit\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/mod-led-eyes-v2-0\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/okshinotv\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/okshinotv\\\/#author\"},\"datePublished\":\"2026-04-01T11:59:49+02:00\",\"dateModified\":\"2026-04-01T11:59:49+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mod LED Eyes V2.0 | ETS 2 mods","description":"Mod LED Eyes v2.0 Mod Parts: Brown Eyes Devil Eyes Dragon Eyes Snake Eyes Red Eyes Hello guys, HOW TO USE : 1) Start the singleplayer game, open the MOD manager and enable the mod 2) Chose your truck 3) Press E & Enjoy I Hope You Like My Works Thank You *_- Credits: Credit","canonical_url":"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/#article","name":"Mod LED Eyes V2.0 | ETS 2 mods","headline":"Mod LED Eyes V2.0","author":{"@id":"https:\/\/ets2.lt\/en\/author\/okshinotv\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/Untitled-1.jpg","@id":"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/#articleImage","width":640,"height":360},"datePublished":"2026-04-01T11:59:49+02:00","dateModified":"2026-04-01T11:59:49+02:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/#webpage"},"articleSection":"Parts\/Tuning"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","name":"Parts\/Tuning"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","position":2,"name":"Parts\/Tuning","item":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/#listItem","name":"Mod LED Eyes V2.0"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/#listItem","position":3,"name":"Mod LED Eyes V2.0","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","name":"Parts\/Tuning"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/okshinotv\/#author","url":"https:\/\/ets2.lt\/en\/author\/okshinotv\/","name":"OkShiNoTV","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/21058b11e2610a52b9748c0c8723816d844cc0a7436220da9cd8e5f0382614ba?s=96&d=mm&r=g","width":96,"height":96,"caption":"OkShiNoTV"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/#webpage","url":"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/","name":"Mod LED Eyes V2.0 | ETS 2 mods","description":"Mod LED Eyes v2.0 Mod Parts: Brown Eyes Devil Eyes Dragon Eyes Snake Eyes Red Eyes Hello guys, HOW TO USE : 1) Start the singleplayer game, open the MOD manager and enable the mod 2) Chose your truck 3) Press E & Enjoy I Hope You Like My Works Thank You *_- Credits: Credit","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/okshinotv\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/okshinotv\/#author"},"datePublished":"2026-04-01T11:59:49+02:00","dateModified":"2026-04-01T11:59:49+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"377072","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-04-01 10:00:04","updated":"2026-04-01 10:00:04","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/\" title=\"Parts\/Tuning\">Parts\/Tuning<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMod LED Eyes V2.0\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Parts\/Tuning","link":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/"},{"label":"Mod LED Eyes V2.0","link":"https:\/\/ets2.lt\/en\/mod-led-eyes-v2-0\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/377072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/199755"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=377072"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/377072\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=377072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=377072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=377072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}