{"id":377547,"date":"2026-04-08T09:11:45","date_gmt":"2026-04-08T07:11:45","guid":{"rendered":"https:\/\/ets2.lt\/en\/?p=377547"},"modified":"2026-04-08T09:11:45","modified_gmt":"2026-04-08T07:11:45","slug":"better-flares-fix-v4-6-6","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/","title":{"rendered":"Better Flares Fix v4.6.6"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/Better-Flares-Fix-v4.6.6-ETS2.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-377546\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/Better-Flares-Fix-v4.6.6-ETS2-750x422.jpeg\" alt=\"Better Flares Fix v4.6.6\" width=\"750\" height=\"422\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/Better-Flares-Fix-v4.6.6-ETS2-750x422.jpeg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/Better-Flares-Fix-v4.6.6-ETS2.jpeg 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><!--fsp:slot:after-images--><\/p><p>Changes:<br>\nSmall fix to City Lights Addon:<br>\nRemoved duplicated street lamp flares<\/p><p>Please re-downlaod archive. Sorry for inconvenience!<br>\nMod is updated to version 4.6.6.<\/p><p>Changes:<br>\nStreet lights now have flares like they did before ETS2 1.50 update<br>\nBrought back lamp flares texture with fog effect from City Lights Addon 4.4 (it just look much better than simple round flares, but please note that upside-down mirror reflection issue is still present)<br>\nIncreased size for red and orange blinking lights (on some stop and roadwork signs)<br>\nImproved DOT headlight pattern<\/p><p>Key features:<br>\nCompletely reworked flares<br>\nRealistic headlights patterns with 6 different colors (up to 50 modded trucks supported)<br>\nModified SCS AI traffic with 9 headlights color variants and 2 red\/brake signals in Traffic Addon<br>\nDimmed street lamps in City Lights Addon<\/p><p>IMPORTANT!<br>\nTraffic Addon now require Sound Fixes Pack, otherwise traffic won&rsquo;t spawn!<br>\nCompatibility: 1.58<\/p><p><!--fsp:slot:after-description--><\/p><p>Credits:<br>\nAvelium<\/p><p><!--fsp:slot:after-credits--><\/p><p><!--more--><\/p><p><!--fsp:slot:before-download-links--><\/p><p><strong><a href=\"https:\/\/mods.to\/Dw3L69d5f3a722d24\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 159 MB<\/strong><br>\n<!--fsp:slot:after-download-links--><\/p><p><!--fsp:slot:post-end--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Changes: Small fix to City Lights Addon: Removed duplicated street lamp flaresPlease re-downlaod archive. Sorry for inconvenience! Mod is updated to version 4.6.6.Changes: Street lights now have flares like they did before ETS2 1.50 update Brought back lamp flares texture with fog effect from City Lights Addon 4.4 (it just look much better than simple [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[6],"tags":[8854,8907],"class_list":["post-377547","post","type-post","status-publish","format-standard","hentry","category-other-mods","tag-1-50","tag-1-58"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Changes: Small fix to City Lights Addon: Removed duplicated street lamp flares Please re-downlaod archive. Sorry for inconvenience! Mod is updated to version 4.6.6. Changes: Street lights now have flares like they did before ETS2 1.50 update Brought back lamp flares texture with fog effect from City Lights Addon 4.4 (it just look much better\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/better-flares-fix-v4-6-6\\\/#article\",\"name\":\"Better Flares Fix v4.6.6 | ETS 2 mods\",\"headline\":\"Better Flares Fix v4.6.6\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Better-Flares-Fix-v4.6.6-ETS2.jpeg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/better-flares-fix-v4-6-6\\\/#articleImage\",\"width\":1280,\"height\":720},\"datePublished\":\"2026-04-08T09:11:45+02:00\",\"dateModified\":\"2026-04-08T09:11:45+02:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/better-flares-fix-v4-6-6\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/better-flares-fix-v4-6-6\\\/#webpage\"},\"articleSection\":\"Others, 1.50, 1.58\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/better-flares-fix-v4-6-6\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"position\":2,\"name\":\"Others\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/better-flares-fix-v4-6-6\\\/#listItem\",\"name\":\"Better Flares Fix v4.6.6\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/better-flares-fix-v4-6-6\\\/#listItem\",\"position\":3,\"name\":\"Better Flares Fix v4.6.6\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/better-flares-fix-v4-6-6\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/better-flares-fix-v4-6-6\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/better-flares-fix-v4-6-6\\\/\",\"name\":\"Better Flares Fix v4.6.6 | ETS 2 mods\",\"description\":\"Changes: Small fix to City Lights Addon: Removed duplicated street lamp flares Please re-downlaod archive. Sorry for inconvenience! Mod is updated to version 4.6.6. Changes: Street lights now have flares like they did before ETS2 1.50 update Brought back lamp flares texture with fog effect from City Lights Addon 4.4 (it just look much better\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/better-flares-fix-v4-6-6\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2026-04-08T09:11:45+02:00\",\"dateModified\":\"2026-04-08T09:11:45+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Better Flares Fix v4.6.6 | ETS 2 mods","description":"Changes: Small fix to City Lights Addon: Removed duplicated street lamp flares Please re-downlaod archive. Sorry for inconvenience! Mod is updated to version 4.6.6. Changes: Street lights now have flares like they did before ETS2 1.50 update Brought back lamp flares texture with fog effect from City Lights Addon 4.4 (it just look much better","canonical_url":"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/#article","name":"Better Flares Fix v4.6.6 | ETS 2 mods","headline":"Better Flares Fix v4.6.6","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/Better-Flares-Fix-v4.6.6-ETS2.jpeg","@id":"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/#articleImage","width":1280,"height":720},"datePublished":"2026-04-08T09:11:45+02:00","dateModified":"2026-04-08T09:11:45+02:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/#webpage"},"articleSection":"Others, 1.50, 1.58"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","position":2,"name":"Others","item":"https:\/\/ets2.lt\/en\/category\/other-mods\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/#listItem","name":"Better Flares Fix v4.6.6"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/#listItem","position":3,"name":"Better Flares Fix v4.6.6","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/#webpage","url":"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/","name":"Better Flares Fix v4.6.6 | ETS 2 mods","description":"Changes: Small fix to City Lights Addon: Removed duplicated street lamp flares Please re-downlaod archive. Sorry for inconvenience! Mod is updated to version 4.6.6. Changes: Street lights now have flares like they did before ETS2 1.50 update Brought back lamp flares texture with fog effect from City Lights Addon 4.4 (it just look much better","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2026-04-08T09:11:45+02:00","dateModified":"2026-04-08T09:11:45+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"377547","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-04-08 07:12:50","updated":"2026-04-08 07:12:50","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/other-mods\/\" title=\"Others\">Others<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBetter Flares Fix v4.6.6\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Others","link":"https:\/\/ets2.lt\/en\/category\/other-mods\/"},{"label":"Better Flares Fix v4.6.6","link":"https:\/\/ets2.lt\/en\/better-flares-fix-v4-6-6\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/377547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=377547"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/377547\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=377547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=377547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=377547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}