{"id":378412,"date":"2026-04-19T14:47:05","date_gmt":"2026-04-19T12:47:05","guid":{"rendered":"https:\/\/ets2.lt\/?p=378412"},"modified":"2026-04-19T14:54:05","modified_gmt":"2026-04-19T12:54:05","slug":"renault-magnum-dxi-eev-v9-0","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/","title":{"rendered":"Renault Magnum DXi EEV v9.0"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/renault-magnum-dxi-eev-v9.0-ets2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-378415\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/renault-magnum-dxi-eev-v9.0-ets2-1.jpg\" alt=\"Renault Magnum DXi EEV v9.0\" width=\"1280\" height=\"720\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/renault-magnum-dxi-eev-v9.0-ets2-1.jpg 1280w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/renault-magnum-dxi-eev-v9.0-ets2-1-750x422.jpg 750w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"><\/a><br>\n<a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/renault-magnum-dxi-eev-v9.0-ets2-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-378414\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/renault-magnum-dxi-eev-v9.0-ets2-3.jpg\" alt=\"Renault Magnum DXi EEV v9.0\" width=\"1280\" height=\"720\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/renault-magnum-dxi-eev-v9.0-ets2-3.jpg 1280w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/renault-magnum-dxi-eev-v9.0-ets2-3-750x422.jpg 750w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"><\/a><br>\n<a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/renault-magnum-dxi-eev-v9.0-ets2-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-378413\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/renault-magnum-dxi-eev-v9.0-ets2-4.jpg\" alt=\"Renault Magnum DXi EEV v9.0\" width=\"1280\" height=\"720\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/renault-magnum-dxi-eev-v9.0-ets2-4.jpg 1280w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/renault-magnum-dxi-eev-v9.0-ets2-4-750x422.jpg 750w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"><\/a><\/p><p>&ndash; Template 4k (Cab\/License Plate\/Country Sticker\/ADR-TIR)<br>\n&ndash; 1 cabin (Excellence)<br>\n&ndash; 2 chassis (4&times;2 (Standard) \/ 4&times;2 (low deck)<br>\n&ndash; Engine (440, 480, 500, 520 &ndash; EEV version)<br>\n&ndash; ZF transmissions<br>\n&ndash; Original interior<br>\n&ndash; Skins<br>\n&ndash; Personal sounds<br>\n&ndash; Personal tuning parts and slots<br>\n&ndash; Compatibility of SISl and Wolli&rsquo;s accessories<br>\n&ndash; Custom animation<br>\n&ndash; Full Standalone<br>\n&ndash; Full Lightmask<br>\n&ndash; Own Flarepack<br>\n&ndash; Cabin accessories (SISL support etc)<br>\n&ndash; Truck Cables<\/p><p>P.S. Wheels from 50Keda are used in the screenshots<br>\nVersion game &ndash; 1.58<\/p><p>Credits:<br>\nMT<\/p><p><strong><a href=\"https:\/\/mods.to\/KRL969e4cfe515986\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 764 MB<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>&ndash; Template 4k (Cab\/License Plate\/Country Sticker\/ADR-TIR) &ndash; 1 cabin (Excellence) &ndash; 2 chassis (4&times;2 (Standard) \/ 4&times;2 (low deck) &ndash; Engine (440, 480, 500, 520 &ndash; EEV version) &ndash; ZF transmissions &ndash; Original interior &ndash; Skins &ndash; Personal sounds &ndash; Personal tuning parts and slots &ndash; Compatibility of SISl and Wolli&rsquo;s accessories &ndash; Custom animation [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-378412","post","type-post","status-publish","format-standard","hentry","category-trucks"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u2013 Template 4k (Cab\/License Plate\/Country Sticker\/ADR-TIR) \u2013 1 cabin (Excellence) \u2013 2 chassis (4\u00d72 (Standard) \/ 4\u00d72 (low deck) \u2013 Engine (440, 480, 500, 520 \u2013 EEV version) \u2013 ZF transmissions \u2013 Original interior \u2013 Skins \u2013 Personal sounds \u2013 Personal tuning parts and slots \u2013 Compatibility of SISl and Wolli\u2019s accessories \u2013 Custom animation\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-magnum-dxi-eev-v9-0\\\/#article\",\"name\":\"Renault Magnum DXi EEV v9.0 | ETS 2 mods\",\"headline\":\"Renault Magnum DXi EEV v9.0\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/renault-magnum-dxi-eev-v9.0-ets2-1.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-magnum-dxi-eev-v9-0\\\/#articleImage\",\"width\":1280,\"height\":720},\"datePublished\":\"2026-04-19T14:47:05+02:00\",\"dateModified\":\"2026-04-19T14:54:05+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-magnum-dxi-eev-v9-0\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-magnum-dxi-eev-v9-0\\\/#webpage\"},\"articleSection\":\"Trucks\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-magnum-dxi-eev-v9-0\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"name\":\"Trucks\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"position\":2,\"name\":\"Trucks\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-magnum-dxi-eev-v9-0\\\/#listItem\",\"name\":\"Renault Magnum DXi EEV v9.0\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-magnum-dxi-eev-v9-0\\\/#listItem\",\"position\":3,\"name\":\"Renault Magnum DXi EEV v9.0\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/trucks\\\/#listItem\",\"name\":\"Trucks\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-magnum-dxi-eev-v9-0\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-magnum-dxi-eev-v9-0\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-magnum-dxi-eev-v9-0\\\/\",\"name\":\"Renault Magnum DXi EEV v9.0 | ETS 2 mods\",\"description\":\"\\u2013 Template 4k (Cab\\\/License Plate\\\/Country Sticker\\\/ADR-TIR) \\u2013 1 cabin (Excellence) \\u2013 2 chassis (4\\u00d72 (Standard) \\\/ 4\\u00d72 (low deck) \\u2013 Engine (440, 480, 500, 520 \\u2013 EEV version) \\u2013 ZF transmissions \\u2013 Original interior \\u2013 Skins \\u2013 Personal sounds \\u2013 Personal tuning parts and slots \\u2013 Compatibility of SISl and Wolli\\u2019s accessories \\u2013 Custom animation\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/renault-magnum-dxi-eev-v9-0\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2026-04-19T14:47:05+02:00\",\"dateModified\":\"2026-04-19T14:54:05+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Renault Magnum DXi EEV v9.0 | ETS 2 mods","description":"\u2013 Template 4k (Cab\/License Plate\/Country Sticker\/ADR-TIR) \u2013 1 cabin (Excellence) \u2013 2 chassis (4\u00d72 (Standard) \/ 4\u00d72 (low deck) \u2013 Engine (440, 480, 500, 520 \u2013 EEV version) \u2013 ZF transmissions \u2013 Original interior \u2013 Skins \u2013 Personal sounds \u2013 Personal tuning parts and slots \u2013 Compatibility of SISl and Wolli\u2019s accessories \u2013 Custom animation","canonical_url":"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/#article","name":"Renault Magnum DXi EEV v9.0 | ETS 2 mods","headline":"Renault Magnum DXi EEV v9.0","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/04\/renault-magnum-dxi-eev-v9.0-ets2-1.jpg","@id":"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/#articleImage","width":1280,"height":720},"datePublished":"2026-04-19T14:47:05+02:00","dateModified":"2026-04-19T14:54:05+02:00","inLanguage":"en-US","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/#webpage"},"articleSection":"Trucks"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","name":"Trucks"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","position":2,"name":"Trucks","item":"https:\/\/ets2.lt\/en\/category\/trucks\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/#listItem","name":"Renault Magnum DXi EEV v9.0"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/#listItem","position":3,"name":"Renault Magnum DXi EEV v9.0","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/trucks\/#listItem","name":"Trucks"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/#webpage","url":"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/","name":"Renault Magnum DXi EEV v9.0 | ETS 2 mods","description":"\u2013 Template 4k (Cab\/License Plate\/Country Sticker\/ADR-TIR) \u2013 1 cabin (Excellence) \u2013 2 chassis (4\u00d72 (Standard) \/ 4\u00d72 (low deck) \u2013 Engine (440, 480, 500, 520 \u2013 EEV version) \u2013 ZF transmissions \u2013 Original interior \u2013 Skins \u2013 Personal sounds \u2013 Personal tuning parts and slots \u2013 Compatibility of SISl and Wolli\u2019s accessories \u2013 Custom animation","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2026-04-19T14:47:05+02:00","dateModified":"2026-04-19T14:54:05+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"378412","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-04-19 12:52:05","updated":"2026-04-19 12:54:05","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/trucks\/\" title=\"Trucks\">Trucks<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRenault Magnum DXi EEV v9.0\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Trucks","link":"https:\/\/ets2.lt\/en\/category\/trucks\/"},{"label":"Renault Magnum DXi EEV v9.0","link":"https:\/\/ets2.lt\/en\/renault-magnum-dxi-eev-v9-0\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/378412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=378412"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/378412\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=378412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=378412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=378412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}