{"id":379770,"date":"2026-05-06T16:07:56","date_gmt":"2026-05-06T14:07:56","guid":{"rendered":"https:\/\/ets2.lt\/en\/?p=379770"},"modified":"2026-05-06T16:07:56","modified_gmt":"2026-05-06T14:07:56","slug":"profile-jumpstart-hoca33-for-ets-2-v1-59","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/","title":{"rendered":"Profile Jumpstart hoca33 For ETS 2 &#8211; v1.59"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/Profile_v1.59_ETS2.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-379769\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/Profile_v1.59_ETS2-750x422.webp\" alt=\"Profile Jumpstart hoca33 For ETS 2 - v1.59\" width=\"750\" height=\"422\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/Profile_v1.59_ETS2-750x422.webp 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/Profile_v1.59_ETS2-1536x864.webp 1536w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/Profile_v1.59_ETS2.webp 1920w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><!--fsp:slot:after-images--><\/p><p>Profile Jumpstart hoca33 For ETS 2 &ndash; v1.59<\/p><p>&#10004; This is for ETS 2 version 1.59.<br>\n&#10004; It is only used when creating a new profile.<br>\n&#10004; Money: &euro;100.000.000 (&euro;100M)<br>\n&#10004; Level 100 Divine Champion.<br>\n&#10004; Max Skills<br>\n&#10004; All Truck Dealers Unlocked.<br>\n&#10004; All Recruitment Agency Discovered.<br>\n&#10004; All Map and Cities 100% Discovered.<\/p><p>How to use:<\/p><p>1- Activate this mod in the mod manager during new profile creation.<br>\n2- Deactivate this mod after profile creation is complete.<\/p><p><!--fsp:slot:after-description--><\/p><p>Credits:<br>\nhoca33<\/p><p><!--fsp:slot:after-credits--><\/p><p><!--more--><\/p><p><!--fsp:slot:before-download-links--><\/p><p><strong><a href=\"https:\/\/www.mediafire.com\/file\/1schufxj57x2snu\/profile_jumpstart_hoca33_ETS2_v1.59.scs\/file\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 1.66 MB<\/strong><br>\n<!--fsp:slot:after-download-links--><\/p><p><!--fsp:slot:post-end--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Profile Jumpstart hoca33 For ETS 2 &ndash; v1.59&#10004; This is for ETS 2 version 1.59. &#10004; It is only used when creating a new profile. &#10004; Money: &euro;100.000.000 (&euro;100M) &#10004; Level 100 Divine Champion. &#10004; Max Skills &#10004; All Truck Dealers Unlocked. &#10004; All Recruitment Agency Discovered. &#10004; All Map and Cities 100% Discovered.How to [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[6],"tags":[8910],"class_list":["post-379770","post","type-post","status-publish","format-standard","hentry","category-other-mods","tag-1-59"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Profile Jumpstart hoca33 For ETS 2 - v1.59 \u2714 This is for ETS 2 version 1.59. \u2714 It is only used when creating a new profile. \u2714 Money: \u20ac100.000.000 (\u20ac100M) \u2714 Level 100 Divine Champion. \u2714 Max Skills \u2714 All Truck Dealers Unlocked. \u2714 All Recruitment Agency Discovered. \u2714 All Map and Cities 100% Discovered.\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/profile-jumpstart-hoca33-for-ets-2-v1-59\\\/#article\",\"name\":\"Profile Jumpstart hoca33 For ETS 2 \\u2013 v1.59 | ETS 2 mods\",\"headline\":\"Profile Jumpstart hoca33 For ETS 2 &#8211; v1.59\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Profile_v1.59_ETS2.webp\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/profile-jumpstart-hoca33-for-ets-2-v1-59\\\/#articleImage\",\"width\":1920,\"height\":1080},\"datePublished\":\"2026-05-06T16:07:56+02:00\",\"dateModified\":\"2026-05-06T16:07:56+02:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/profile-jumpstart-hoca33-for-ets-2-v1-59\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/profile-jumpstart-hoca33-for-ets-2-v1-59\\\/#webpage\"},\"articleSection\":\"Others, 1.59\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/profile-jumpstart-hoca33-for-ets-2-v1-59\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"position\":2,\"name\":\"Others\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/profile-jumpstart-hoca33-for-ets-2-v1-59\\\/#listItem\",\"name\":\"Profile Jumpstart hoca33 For ETS 2 &#8211; v1.59\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/profile-jumpstart-hoca33-for-ets-2-v1-59\\\/#listItem\",\"position\":3,\"name\":\"Profile Jumpstart hoca33 For ETS 2 &#8211; v1.59\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/profile-jumpstart-hoca33-for-ets-2-v1-59\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/profile-jumpstart-hoca33-for-ets-2-v1-59\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/profile-jumpstart-hoca33-for-ets-2-v1-59\\\/\",\"name\":\"Profile Jumpstart hoca33 For ETS 2 \\u2013 v1.59 | ETS 2 mods\",\"description\":\"Profile Jumpstart hoca33 For ETS 2 - v1.59 \\u2714 This is for ETS 2 version 1.59. \\u2714 It is only used when creating a new profile. \\u2714 Money: \\u20ac100.000.000 (\\u20ac100M) \\u2714 Level 100 Divine Champion. \\u2714 Max Skills \\u2714 All Truck Dealers Unlocked. \\u2714 All Recruitment Agency Discovered. \\u2714 All Map and Cities 100% Discovered.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/profile-jumpstart-hoca33-for-ets-2-v1-59\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2026-05-06T16:07:56+02:00\",\"dateModified\":\"2026-05-06T16:07:56+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Profile Jumpstart hoca33 For ETS 2 \u2013 v1.59 | ETS 2 mods","description":"Profile Jumpstart hoca33 For ETS 2 - v1.59 \u2714 This is for ETS 2 version 1.59. \u2714 It is only used when creating a new profile. \u2714 Money: \u20ac100.000.000 (\u20ac100M) \u2714 Level 100 Divine Champion. \u2714 Max Skills \u2714 All Truck Dealers Unlocked. \u2714 All Recruitment Agency Discovered. \u2714 All Map and Cities 100% Discovered.","canonical_url":"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/#article","name":"Profile Jumpstart hoca33 For ETS 2 \u2013 v1.59 | ETS 2 mods","headline":"Profile Jumpstart hoca33 For ETS 2 &#8211; v1.59","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/Profile_v1.59_ETS2.webp","@id":"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/#articleImage","width":1920,"height":1080},"datePublished":"2026-05-06T16:07:56+02:00","dateModified":"2026-05-06T16:07:56+02:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/#webpage"},"articleSection":"Others, 1.59"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","position":2,"name":"Others","item":"https:\/\/ets2.lt\/en\/category\/other-mods\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/#listItem","name":"Profile Jumpstart hoca33 For ETS 2 &#8211; v1.59"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/#listItem","position":3,"name":"Profile Jumpstart hoca33 For ETS 2 &#8211; v1.59","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/#webpage","url":"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/","name":"Profile Jumpstart hoca33 For ETS 2 \u2013 v1.59 | ETS 2 mods","description":"Profile Jumpstart hoca33 For ETS 2 - v1.59 \u2714 This is for ETS 2 version 1.59. \u2714 It is only used when creating a new profile. \u2714 Money: \u20ac100.000.000 (\u20ac100M) \u2714 Level 100 Divine Champion. \u2714 Max Skills \u2714 All Truck Dealers Unlocked. \u2714 All Recruitment Agency Discovered. \u2714 All Map and Cities 100% Discovered.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2026-05-06T16:07:56+02:00","dateModified":"2026-05-06T16:07:56+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"379770","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-05-06 14:08:46","updated":"2026-05-06 14:08:46","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/other-mods\/\" title=\"Others\">Others<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tProfile Jumpstart hoca33 For ETS 2 \u2013 v1.59\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Others","link":"https:\/\/ets2.lt\/en\/category\/other-mods\/"},{"label":"Profile Jumpstart hoca33 For ETS 2 &#8211; v1.59","link":"https:\/\/ets2.lt\/en\/profile-jumpstart-hoca33-for-ets-2-v1-59\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/379770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=379770"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/379770\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=379770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=379770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=379770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}