{"id":379949,"date":"2026-05-07T14:25:45","date_gmt":"2026-05-07T12:25:45","guid":{"rendered":"https:\/\/ets2.lt\/en\/?p=379949"},"modified":"2026-05-07T14:25:45","modified_gmt":"2026-05-07T12:25:45","slug":"road-into-wilderness-v2-3","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/","title":{"rendered":"Road into Wilderness v2.3"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/Road-into-Wilderness-v2.3-ETS2.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-379948\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/Road-into-Wilderness-v2.3-ETS2-750x422.jpeg\" alt=\"Road into Wilderness v2.3\" width=\"750\" height=\"422\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/Road-into-Wilderness-v2.3-ETS2-750x422.jpeg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/Road-into-Wilderness-v2.3-ETS2.jpeg 1400w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><!--fsp:slot:after-images--><\/p><p>This is a map of Africa.<br>\nIncludes cities and roads<\/p><p>Requires all map DLC to work properly.<\/p><p>Adds more cities and roads<br>\nFixed some bugs.<br>\nAdjusted Garies rock to make it more avoidable.<\/p><p><!--fsp:slot:after-description--><\/p><p>Credits:<br>\nTony_Viborg<\/p><p><!--fsp:slot:after-credits--><\/p><p><!--more--><\/p><p><!--fsp:slot:before-download-links--><\/p><p><strong><a href=\"https:\/\/modsfire.com\/I0hyl0q5ans539u\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 342 MB<\/strong><br>\n<!--fsp:slot:after-download-links--><\/p><p><!--fsp:slot:post-end--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>This is a map of Africa. Includes cities and roadsRequires all map DLC to work properly.Adds more cities and roads Fixed some bugs. Adjusted Garies rock to make it more avoidable.Credits: Tony_Viborg<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-379949","post","type-post","status-publish","format-standard","hentry","category-maps"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"This is a map of Africa. Includes cities and roads Requires all map DLC to work properly. Adds more cities and roads Fixed some bugs. Adjusted Garies rock to make it more avoidable. Credits: Tony_Viborg DOWNLOAD 342 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/road-into-wilderness-v2-3\\\/#article\",\"name\":\"Road into Wilderness v2.3 | ETS 2 mods\",\"headline\":\"Road into Wilderness v2.3\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Road-into-Wilderness-v2.3-ETS2.jpeg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/road-into-wilderness-v2-3\\\/#articleImage\",\"width\":1400,\"height\":788},\"datePublished\":\"2026-05-07T14:25:45+02:00\",\"dateModified\":\"2026-05-07T14:25:45+02:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/road-into-wilderness-v2-3\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/road-into-wilderness-v2-3\\\/#webpage\"},\"articleSection\":\"Maps\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/road-into-wilderness-v2-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/maps\\\/#listItem\",\"name\":\"Maps\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/maps\\\/#listItem\",\"position\":2,\"name\":\"Maps\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/maps\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/road-into-wilderness-v2-3\\\/#listItem\",\"name\":\"Road into Wilderness v2.3\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/road-into-wilderness-v2-3\\\/#listItem\",\"position\":3,\"name\":\"Road into Wilderness v2.3\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/maps\\\/#listItem\",\"name\":\"Maps\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/road-into-wilderness-v2-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/road-into-wilderness-v2-3\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/road-into-wilderness-v2-3\\\/\",\"name\":\"Road into Wilderness v2.3 | ETS 2 mods\",\"description\":\"This is a map of Africa. Includes cities and roads Requires all map DLC to work properly. Adds more cities and roads Fixed some bugs. Adjusted Garies rock to make it more avoidable. Credits: Tony_Viborg DOWNLOAD 342 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/road-into-wilderness-v2-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2026-05-07T14:25:45+02:00\",\"dateModified\":\"2026-05-07T14:25:45+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Road into Wilderness v2.3 | ETS 2 mods","description":"This is a map of Africa. Includes cities and roads Requires all map DLC to work properly. Adds more cities and roads Fixed some bugs. Adjusted Garies rock to make it more avoidable. Credits: Tony_Viborg DOWNLOAD 342 MB","canonical_url":"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/#article","name":"Road into Wilderness v2.3 | ETS 2 mods","headline":"Road into Wilderness v2.3","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/Road-into-Wilderness-v2.3-ETS2.jpeg","@id":"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/#articleImage","width":1400,"height":788},"datePublished":"2026-05-07T14:25:45+02:00","dateModified":"2026-05-07T14:25:45+02:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/#webpage"},"articleSection":"Maps"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/maps\/#listItem","name":"Maps"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/maps\/#listItem","position":2,"name":"Maps","item":"https:\/\/ets2.lt\/en\/category\/maps\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/#listItem","name":"Road into Wilderness v2.3"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/#listItem","position":3,"name":"Road into Wilderness v2.3","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/maps\/#listItem","name":"Maps"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/#webpage","url":"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/","name":"Road into Wilderness v2.3 | ETS 2 mods","description":"This is a map of Africa. Includes cities and roads Requires all map DLC to work properly. Adds more cities and roads Fixed some bugs. Adjusted Garies rock to make it more avoidable. Credits: Tony_Viborg DOWNLOAD 342 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2026-05-07T14:25:45+02:00","dateModified":"2026-05-07T14:25:45+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"379949","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-05-07 12:26:35","updated":"2026-05-07 12:26:35","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/maps\/\" title=\"Maps\">Maps<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRoad into Wilderness v2.3\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Maps","link":"https:\/\/ets2.lt\/en\/category\/maps\/"},{"label":"Road into Wilderness v2.3","link":"https:\/\/ets2.lt\/en\/road-into-wilderness-v2-3\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/379949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=379949"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/379949\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=379949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=379949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=379949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}