{"id":380371,"date":"2026-05-12T16:53:32","date_gmt":"2026-05-12T14:53:32","guid":{"rendered":"https:\/\/ets2.lt\/en\/?p=380371"},"modified":"2026-05-12T16:53:32","modified_gmt":"2026-05-12T14:53:32","slug":"abasstreppas-wheel-pack-for-ownership-trailers-v1-59","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/","title":{"rendered":"Abasstreppas Wheel pack for Ownership Trailers v1.59"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/abasstreppas-wheel-pack-for-ownership-trailers-v1.58-ets2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-380370\" src=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/abasstreppas-wheel-pack-for-ownership-trailers-v1.58-ets2-1-750x422.jpg\" alt=\"Abasstreppas Wheel pack for Ownership Trailers v1.59\" width=\"750\" height=\"422\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/abasstreppas-wheel-pack-for-ownership-trailers-v1.58-ets2-1-750x422.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/abasstreppas-wheel-pack-for-ownership-trailers-v1.58-ets2-1.jpg 1280w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\"><\/a><\/p><p><!--fsp:slot:after-images--><\/p><p>All discs are of high quality model<br>\nNew wheels are installed on purchased trailers<br>\n18 discs<br>\n5 tires<br>\n12 caps<br>\n14 bushings<br>\n15+ nuts<br>\nDetailed models<\/p><p>Tested for 1.59 game version<\/p><p><!--fsp:slot:after-description--><\/p><p>Credits:<br>\nAbasstreppas<\/p><p><!--fsp:slot:after-credits--><\/p><p><!--more--><\/p><p><!--fsp:slot:before-download-links--><\/p><p><strong><a href=\"https:\/\/mods.to\/nnxF6a033e1084d66\" target=\"_blank\" rel=\"noopener ugc nofollow\">DOWNLOAD<\/a> 16 MB<\/strong><br>\n<!--fsp:slot:after-download-links--><\/p><p><!--fsp:slot:post-end--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>All discs are of high quality model New wheels are installed on purchased trailers 18 discs 5 tires 12 caps 14 bushings 15+ nuts Detailed modelsTested for 1.59 game versionCredits: Abasstreppas<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[11],"tags":[8907,8910],"class_list":["post-380371","post","type-post","status-publish","format-standard","hentry","category-detalestiuningas","tag-1-58","tag-1-59"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"All discs are of high quality model New wheels are installed on purchased trailers 18 discs 5 tires 12 caps 14 bushings 15+ nuts Detailed models Tested for 1.59 game version Credits: Abasstreppas DOWNLOAD 16 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\\\/#article\",\"name\":\"Abasstreppas Wheel pack for Ownership Trailers v1.59 | ETS 2 mods\",\"headline\":\"Abasstreppas Wheel pack for Ownership Trailers v1.59\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/abasstreppas-wheel-pack-for-ownership-trailers-v1.58-ets2-1.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\\\/#articleImage\",\"width\":1280,\"height\":720},\"datePublished\":\"2026-05-12T16:53:32+02:00\",\"dateModified\":\"2026-05-12T16:53:32+02:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\\\/#webpage\"},\"articleSection\":\"Parts\\\/Tuning, 1.58, 1.59\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"name\":\"Parts\\\/Tuning\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"position\":2,\"name\":\"Parts\\\/Tuning\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\\\/#listItem\",\"name\":\"Abasstreppas Wheel pack for Ownership Trailers v1.59\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\\\/#listItem\",\"position\":3,\"name\":\"Abasstreppas Wheel pack for Ownership Trailers v1.59\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/detalestiuningas\\\/#listItem\",\"name\":\"Parts\\\/Tuning\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\\\/\",\"name\":\"Abasstreppas Wheel pack for Ownership Trailers v1.59 | ETS 2 mods\",\"description\":\"All discs are of high quality model New wheels are installed on purchased trailers 18 discs 5 tires 12 caps 14 bushings 15+ nuts Detailed models Tested for 1.59 game version Credits: Abasstreppas DOWNLOAD 16 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2026-05-12T16:53:32+02:00\",\"dateModified\":\"2026-05-12T16:53:32+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Abasstreppas Wheel pack for Ownership Trailers v1.59 | ETS 2 mods","description":"All discs are of high quality model New wheels are installed on purchased trailers 18 discs 5 tires 12 caps 14 bushings 15+ nuts Detailed models Tested for 1.59 game version Credits: Abasstreppas DOWNLOAD 16 MB","canonical_url":"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/#article","name":"Abasstreppas Wheel pack for Ownership Trailers v1.59 | ETS 2 mods","headline":"Abasstreppas Wheel pack for Ownership Trailers v1.59","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/ets2.lt\/wp-content\/uploads\/2026\/05\/abasstreppas-wheel-pack-for-ownership-trailers-v1.58-ets2-1.jpg","@id":"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/#articleImage","width":1280,"height":720},"datePublished":"2026-05-12T16:53:32+02:00","dateModified":"2026-05-12T16:53:32+02:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/#webpage"},"articleSection":"Parts\/Tuning, 1.58, 1.59"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","name":"Parts\/Tuning"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","position":2,"name":"Parts\/Tuning","item":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/#listItem","name":"Abasstreppas Wheel pack for Ownership Trailers v1.59"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/#listItem","position":3,"name":"Abasstreppas Wheel pack for Ownership Trailers v1.59","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/#listItem","name":"Parts\/Tuning"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/#webpage","url":"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/","name":"Abasstreppas Wheel pack for Ownership Trailers v1.59 | ETS 2 mods","description":"All discs are of high quality model New wheels are installed on purchased trailers 18 discs 5 tires 12 caps 14 bushings 15+ nuts Detailed models Tested for 1.59 game version Credits: Abasstreppas DOWNLOAD 16 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2026-05-12T16:53:32+02:00","dateModified":"2026-05-12T16:53:32+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"380371","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-05-12 14:54:49","updated":"2026-05-12 14:54:49","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/\" title=\"Parts\/Tuning\">Parts\/Tuning<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAbasstreppas Wheel pack for Ownership Trailers v1.59\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Parts\/Tuning","link":"https:\/\/ets2.lt\/en\/category\/detalestiuningas\/"},{"label":"Abasstreppas Wheel pack for Ownership Trailers v1.59","link":"https:\/\/ets2.lt\/en\/abasstreppas-wheel-pack-for-ownership-trailers-v1-59\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/380371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=380371"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/380371\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=380371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=380371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=380371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}