{"id":99205,"date":"2015-09-23T19:42:23","date_gmt":"2015-09-23T16:42:23","guid":{"rendered":"http:\/\/ets2.lt\/?p=99205"},"modified":"2015-09-23T19:42:23","modified_gmt":"2015-09-23T16:42:23","slug":"real-gas-station-v1-20-fixed-2","status":"publish","type":"post","link":"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/","title":{"rendered":"Real Gas Station V1.20 Fixed"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><a href=\"http:\/\/ets2.lt\/wp-content\/uploads\/2015\/09\/Real-Gas-Station-21.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-99206\" src=\"http:\/\/ets2.lt\/wp-content\/uploads\/2015\/09\/Real-Gas-Station-21-470x293.jpg\" alt=\"Real-Gas-Station-2\" width=\"470\" height=\"293\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2015\/09\/Real-Gas-Station-21-470x293.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2015\/09\/Real-Gas-Station-21.jpg 900w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\"><\/a> <a href=\"http:\/\/ets2.lt\/wp-content\/uploads\/2015\/09\/Real-Gas-Station-11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-99207\" src=\"http:\/\/ets2.lt\/wp-content\/uploads\/2015\/09\/Real-Gas-Station-11-470x293.jpg\" alt=\"Real-Gas-Station-1\" width=\"470\" height=\"293\" srcset=\"https:\/\/ets2.lt\/wp-content\/uploads\/2015\/09\/Real-Gas-Station-11-470x293.jpg 750w, https:\/\/ets2.lt\/wp-content\/uploads\/2015\/09\/Real-Gas-Station-11.jpg 900w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\"><\/a><\/p><p>Bugs Fixed<br>\nTested version 1.20.x<br>\nCompatible with DLC<br>\nCompatible with Promods, TSM, MHAPro, Pack Jazzycat<\/p><p>* Respect the dowload link *<\/p><p>Author: Fred_be<\/p><p><strong><a href=\"http:\/\/sharemods.com\/12rao697jywr\/Real_Gas_Station_V1.20.zip.html\" target=\"_blank\" rel=\"ugc nofollow noopener\">DOWNLOAD<\/a> 17 MB<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Bugs Fixed Tested version 1.20.x Compatible with DLC Compatible with Promods, TSM, MHAPro, Pack Jazzycat* Respect the dowload link *Author: Fred_beDOWNLOAD 17 MB<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-99205","post","type-post","status-publish","format-standard","hentry","category-other-mods"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Bugs Fixed Tested version 1.20.x Compatible with DLC Compatible with Promods, TSM, MHAPro, Pack Jazzycat * Respect the dowload link * Author: Fred_be DOWNLOAD 17 MB\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-gas-station-v1-20-fixed-2\\\/#article\",\"name\":\"Real Gas Station V1.20 Fixed | ETS 2 mods\",\"headline\":\"Real Gas Station V1.20 Fixed\",\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/ets2.lt\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/Real-Gas-Station-21-470x293.jpg\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-gas-station-v1-20-fixed-2\\\/#articleImage\"},\"datePublished\":\"2015-09-23T19:42:23+02:00\",\"dateModified\":\"2015-09-23T19:42:23+02:00\",\"inLanguage\":\"en-US\",\"commentCount\":24,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-gas-station-v1-20-fixed-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-gas-station-v1-20-fixed-2\\\/#webpage\"},\"articleSection\":\"Others\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-gas-station-v1-20-fixed-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"position\":2,\"name\":\"Others\",\"item\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-gas-station-v1-20-fixed-2\\\/#listItem\",\"name\":\"Real Gas Station V1.20 Fixed\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-gas-station-v1-20-fixed-2\\\/#listItem\",\"position\":3,\"name\":\"Real Gas Station V1.20 Fixed\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/category\\\/other-mods\\\/#listItem\",\"name\":\"Others\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\",\"name\":\"ETS 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-gas-station-v1-20-fixed-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-gas-station-v1-20-fixed-2\\\/#webpage\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-gas-station-v1-20-fixed-2\\\/\",\"name\":\"Real Gas Station V1.20 Fixed | ETS 2 mods\",\"description\":\"Bugs Fixed Tested version 1.20.x Compatible with DLC Compatible with Promods, TSM, MHAPro, Pack Jazzycat * Respect the dowload link * Author: Fred_be DOWNLOAD 17 MB\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/real-gas-station-v1-20-fixed-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2015-09-23T19:42:23+02:00\",\"dateModified\":\"2015-09-23T19:42:23+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ets2.lt\\\/en\\\/\",\"name\":\"ETS2 mods\",\"alternateName\":\"Euro Truck Simulator 2 mods\",\"description\":\"Euro Truck Simulator 2 mods\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/ets2.lt\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Real Gas Station V1.20 Fixed | ETS 2 mods","description":"Bugs Fixed Tested version 1.20.x Compatible with DLC Compatible with Promods, TSM, MHAPro, Pack Jazzycat * Respect the dowload link * Author: Fred_be DOWNLOAD 17 MB","canonical_url":"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/#article","name":"Real Gas Station V1.20 Fixed | ETS 2 mods","headline":"Real Gas Station V1.20 Fixed","author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/ets2.lt\/wp-content\/uploads\/2015\/09\/Real-Gas-Station-21-470x293.jpg","@id":"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/#articleImage"},"datePublished":"2015-09-23T19:42:23+02:00","dateModified":"2015-09-23T19:42:23+02:00","inLanguage":"en-US","commentCount":24,"mainEntityOfPage":{"@id":"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/#webpage"},"isPartOf":{"@id":"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/#webpage"},"articleSection":"Others"},{"@type":"BreadcrumbList","@id":"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","position":1,"name":"Home","item":"https:\/\/ets2.lt\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","position":2,"name":"Others","item":"https:\/\/ets2.lt\/en\/category\/other-mods\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/#listItem","name":"Real Gas Station V1.20 Fixed"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/#listItem","position":3,"name":"Real Gas Station V1.20 Fixed","previousItem":{"@type":"ListItem","@id":"https:\/\/ets2.lt\/en\/category\/other-mods\/#listItem","name":"Others"}}]},{"@type":"Organization","@id":"https:\/\/ets2.lt\/en\/#organization","name":"ETS 2 mods","description":"Euro Truck Simulator 2 mods","url":"https:\/\/ets2.lt\/en\/"},{"@type":"Person","@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author","url":"https:\/\/ets2.lt\/en\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/df6b0419621d40b6cf6449ebf950027d7486eebca0e08882690ac34fca80a182?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/#webpage","url":"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/","name":"Real Gas Station V1.20 Fixed | ETS 2 mods","description":"Bugs Fixed Tested version 1.20.x Compatible with DLC Compatible with Promods, TSM, MHAPro, Pack Jazzycat * Respect the dowload link * Author: Fred_be DOWNLOAD 17 MB","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/ets2.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/#breadcrumblist"},"author":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/ets2.lt\/en\/author\/admin\/#author"},"datePublished":"2015-09-23T19:42:23+02:00","dateModified":"2015-09-23T19:42:23+02:00"},{"@type":"WebSite","@id":"https:\/\/ets2.lt\/en\/#website","url":"https:\/\/ets2.lt\/en\/","name":"ETS2 mods","alternateName":"Euro Truck Simulator 2 mods","description":"Euro Truck Simulator 2 mods","inLanguage":"en-US","publisher":{"@id":"https:\/\/ets2.lt\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"99205","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-23 12:13:07","updated":"2022-09-18 12:11:23","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ets2.lt\/en\/category\/other-mods\/\" title=\"Others\">Others<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tReal Gas Station V1.20 Fixed\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/ets2.lt\/en"},{"label":"Others","link":"https:\/\/ets2.lt\/en\/category\/other-mods\/"},{"label":"Real Gas Station V1.20 Fixed","link":"https:\/\/ets2.lt\/en\/real-gas-station-v1-20-fixed-2\/"}],"_links":{"self":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/99205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/comments?post=99205"}],"version-history":[{"count":0,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/posts\/99205\/revisions"}],"wp:attachment":[{"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/media?parent=99205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/categories?post=99205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ets2.lt\/en\/wp-json\/wp\/v2\/tags?post=99205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}